﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":59017,"date":"2023-10-07T06:36:50","date_gmt":"2023-10-07T04:36:50","guid":{"rendered":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/brouillon-breves-copy-copy-copy\/"},"modified":"2023-10-09T10:19:05","modified_gmt":"2023-10-09T08:19:05","slug":"maldives-nouveau-trop-sensibles-sirenes-pekin-chine","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/","title":{"rendered":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2023-10-07T06:36:50Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 07 Octobre 2023<br \/>\n\t\tMis \u00e0 jour 09 Octobre 2023\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2023-10-09T10:19:05Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">Tribune<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/olivier-guillard\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Olivier Guillard            <\/span>\n            <img data-del=\"avatar\" alt=\"Olivier Guillard\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/09\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg\" class=\"article-image\" title=\"Mohamed Muizzu a \u00e9t\u00e9 \u00e9lu pr\u00e9sident de la R\u00e9publique des Maldives le 30 septembre 2023. (Source : France 24)\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg\" class=\"img-responsive\" alt=\"Mohamed Muizzu a \u00e9t\u00e9 \u00e9lu pr\u00e9sident de la R\u00e9publique des Maldives le 30 septembre 2023. (Source : France 24)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-250x188.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-1024x768.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-150x113.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-768x576.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-200x150.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-267x200.jpg 267w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-533x400.jpg 533w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-800x600.jpg 800w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-1137x853.jpg 1137w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle-680x510.jpg 680w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n      <meta itemprop=\"height\" content=\"1280\"\/>\n      <meta itemprop=\"width\" content=\"960\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tMohamed Muizzu a \u00e9t\u00e9 \u00e9lu pr\u00e9sident de la R\u00e9publique des Maldives le 30 septembre 2023. (Source : <a href=\"https:\/\/www.france24.com\/en\/live-news\/20230930-pro-china-candidate-wins-maldives-presidency\" rel=\"noopener\" target=\"_blank\">France 24<\/a>)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tOuvertement pro-Chine durant la campagne, le candidat de l&rsquo;opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l&rsquo;\u00e9lection pr\u00e9sidentielle aux Maldives, l&rsquo;un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu&rsquo;il s&rsquo;efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l&rsquo;archipel.\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*200 seulement sont habit\u00e9es, dont plusieurs dizaines consacr\u00e9es exclusivement au tourisme de luxe <em>(resorts) <\/em>et \u00e0 une client\u00e8le \u00e9trang\u00e8re dispendieuse. **60 ans, du Maldivian Democratic Party, en poste depuis 2018. ***45 ans, du People&rsquo;s National Congress, maire de la capitale Mal\u00e9, ancien ministre du Logement et de l\u2019Environnement. ****85 % des personnes inscrites sur les listes \u00e9lectorales &#8211; soit pr\u00e8s de 240 000 des 544 000 Maldiviens &#8211; ont pris part au vote.<\/div>Samedi 30 septembre, la lointaine et archip\u00e9lagique R\u00e9publique des Maldives (300 km\u00b2 pour un demi-million d\u2019habitants), nation insulaire de l\u2019oc\u00e9an Indien ventil\u00e9e du Nord au Sud sur 1 000 km et autant d\u2019\u00eelots*, conviait \u00e0 nouveau, trois semaines apr\u00e8s un premier tour de scrutin, son \u00e9lectorat \u00e0 une nouvelle visite des bureaux de vote pour d\u00e9signer qui du pr\u00e9sident sortant Ibrahim Mohamed Solih** ou de son rival de l\u2019opposition Mohamed Muizzu*** occuperait \u00e0 court terme le poste de chef de l\u2019\u00c9tat. Au sortir de ces 13\u00e8me \u00e9lections pr\u00e9sidentielles organis\u00e9es depuis 1952 dans ce pays en d\u00e9veloppement d\u2019Asie m\u00e9ridionale parmi les plus expos\u00e9s aux effets du changement climatique, il revient <em>in fine <\/em>\u00e0 Mohamed Muizzu d\u2019endosser les responsabilit\u00e9s de futur pr\u00e9sident &#8211; il sera investi offciellement le 17 novembre. Ce dernier a rassembl\u00e9 derri\u00e8re sa banni\u00e8re 54 % des suffrages, contre 46 % pour le sortant \u00ab\u00a0Ibu\u00a0\u00bb Solih, dans un contexte de forte mobilisation de l\u2019\u00e9lectorat****, de calme relatif &#8211; peu de violences politiques et d\u2019incidents ont \u00e9t\u00e9 d\u00e9plor\u00e9s &#8211; et de r\u00e9gularit\u00e9 de l\u2019exercice, selon les observateurs locaux et internationaux.[\/asl-article-chapo]\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t\t<\/div>\n<\/div>\n<div class=\"bulle\">\n\t*Cf. incertitudes \u00e9conomiques malgr\u00e9 une projection de croissance du PIB de + 6,5 % en 2023 selon la Banque Mondiale, un service de la dette \u00e9lev\u00e9, une crise du logement pr\u00e9occupante, des affaires de corruption en s\u00e9rie ou encore une gouvernance sujette \u00e0 caution.<\/div>Intervenant dans une configuration post-Covid, ce scrutin prioritairement centr\u00e9 sur des th\u00e9matiques domestiques concr\u00e8tes* pour la population a n\u00e9anmoins fait l\u2019objet d\u2019une certaine attention de la part du concert des nations et de l\u2019opinion publique internationale. C&rsquo;est qu&rsquo;il int\u00e9grait une inconnue g\u00e9opolitique d\u2019importance dans cette \u00e9quation \u00e9lectorale nationale, en mettant aux prises au 2\u00e8me tour deux politiques \u00e9trang\u00e8res divergentes, chacune \u00e9tant d\u00e9fendue avec conviction par son champion. Au prisme pro-Inde de l\u2019administration sortante s\u2019opposait ainsi la <a href=\"https:\/\/edition.cnn.com\/2023\/10\/01\/asia\/maldives-presidential-vote-intl\/index.html\" rel=\"noopener\" target=\"_blank\">politique ouvertement pro-Chine du candidat de l\u2019opposition<\/a>. La victoire de ce dernier dans les urnes et ses premi\u00e8res d\u00e9clarations audacieuses sinon fr\u00f4lant la provocation ont suscit\u00e9 quelques <a href=\"https:\/\/indianexpress.com\/article\/opinion\/editorials\/election-of-china-friendly-mohamed-muizzu-could-test-indo-maldives-ties-8967206\/\" rel=\"noopener\" target=\"_blank\">\u00e9motions l\u00e9gitimes du c\u00f4t\u00e9 de New Delhi<\/a>, d\u00e9sireuse de conserver dans le futur les relations bilat\u00e9rales les plus apais\u00e9es et constructives possibles, de poursuivre une politique de bon voisinage profitant mutuellement \u00e0 ces deux acteurs du sous-continent indien.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDe fait, une fois sa victoire \u00e9lectorale acquise, parmi les premi\u00e8res d\u00e9clarations ou actions sujettes \u00e0 interpr\u00e9tation du futur pr\u00e9sident maldivien, on reviendra quelques instants sur un floril\u00e8ge donnant n\u00e9cessairement mati\u00e8re \u00e0 d\u00e9bat. Lundi 2 octobre, lors de sa premi\u00e8re sortie publique \u00e8s-qualit\u00e9s, le futur chef de l&rsquo;\u00c9tat qualifia de <em><a href=\"https:\/\/en.sun.mv\/85124\" rel=\"noopener\" target=\"_blank\">\u00ab\u00a0pro-Maldives\u00a0\u00bb <\/a><\/em>la politique \u00e9trang\u00e8re de la future administration, pr\u00e9cisant que celle-ci privil\u00e9gierait l&rsquo;int\u00e9r\u00eat national et entretiendrait des relations diplomatiques avec les pays qui soutiendraient cette politique et respecteraient cette orientation strat\u00e9gique. Avant d\u2019ajouter : <em>\u00ab\u00a0Notre religion islamique est la chose la plus importante pour nous. Nous devons <a href=\"https:\/\/en.sun.mv\/85059\" rel=\"noopener\" target=\"_blank\">faire du nationalisme notre priorit\u00e9<\/a>.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe plus frontal \u00e9tait \u00e0 venir. Soulignant qu&rsquo;aucun militaire \u00e9tranger ne pouvait <em>\u00ab\u00a0\u00eatre bas\u00e9 aux Maldives contre la volont\u00e9 du peuple maldivien\u00a0\u00bb, <\/em>Mohamed Muizzu d\u00e9clara tout de go qu&rsquo;il s&rsquo;efforcerait de pousser vers la sortie tous les soldats \u00e9trangers bas\u00e9s dans l\u2019archipel le jour m\u00eame de son entr\u00e9e en fonction. Une saillie sans aucune finesse diplomatique qui ne pouvait s\u2019adresser qu\u2019\u00e0 l\u2019Inde, <em>a priori <\/em>la seule puissance ext\u00e9rieure \u00e0 compter quelques hommes de troupes chez ce voisin insulaire aux orientations diplomatiques fluctuantes. Une <a href=\"https:\/\/www.aljazeera.com\/news\/2023\/10\/2\/music-to-beijings-ears-has-china-won-the-maldives-presidency\" rel=\"noopener\" target=\"_blank\">pr\u00e9sence militaire symbolique<\/a>, de quelques dizaines d\u2019individus charg\u00e9s de l\u2019entretien des h\u00e9licopt\u00e8res et avion dont New Delhi fit plut\u00f4t cadeaux \u00e0 Mal\u00e9, ainsi que de la construction d\u2019infrastructures portuaires pour les forces maldiviennes, enfin, de la formation de ces derni\u00e8res. Rien qui ne puisse se comparer de pr\u00e8s ou de loin avec la militarisation \u00e0 marche forc\u00e9e d\u2019une foultitude d\u2019\u00eeles artificielles, de r\u00e9cifs et de hauts-fonds en mer de Chine du Sud, engag\u00e9e ces derni\u00e8res d\u00e9cennies par P\u00e9kin.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Son mentor et patron, l\u2019ancien pr\u00e9sident Abdulla Yameen, au pouvoir entre 2013 et 2018, embastill\u00e9 au moment de l\u2019\u00e9lection pour des affaires de corruption et de blanchiment d\u2019argent, ne pouvait se pr\u00e9senter devant les \u00e9lecteurs.<\/div>Le pr\u00e9avis \u00ab\u00a0d\u2019expulsion\u00a0\u00bb \u00e0 l\u2019adresse du personnel militaire indien pr\u00e9sent dans l\u2019archipel manque il est vrai plus de tact que de cran de la part de ce personnage politique jusqu\u2019alors peu charismatique parvenu \u00e0 l\u2019avant-derni\u00e8re minute et par d\u00e9faut* au pinacle du pouvoir maldivien. En recevant d\u00e8s mercredi 4 octobre dans la capitale de l\u2019archipel certains repr\u00e9sentants du corps diplomatique, le 7\u00e8me pr\u00e9sident de la R\u00e9publique des Maldives en a profit\u00e9 pour affiner, pr\u00e9ciser aux uns et aux autres sa feuille de route et une partie de son agenda politique.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>\u00ab\u00a0India out\u00a0\u00bb<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t\u00c0 l\u2019ambassadrice de Chine, Mohamed Muizzu confia notamment esp\u00e9rer que les rapports entre Mal\u00e9 et P\u00e9kin iront en se renfor\u00e7ant pour <em>\u00ab\u00a0atteindre de nouveaux sommets sous sa pr\u00e9sidence\u00a0\u00bb, <\/em>remercia la R\u00e9publique populaire pour sa contribution au d\u00e9veloppement de l\u2019archipel, enfin, demanda \u00e0 la deuxi\u00e8me \u00e9conomie mondiale de <em>\u00ab\u00a0l&rsquo;aider \u00e0 tenir les promesses faites [lors de la campagne \u00e9lectorale] au peuple maldivien\u00a0\u00bb. <\/em>Rien qui ne soit que <a href=\"https:\/\/www.lefigaro.fr\/flash-actu\/maldives-la-chine-felicite-le-vainqueur-pro-pekin-de-l-election-presidentielle-20231002\" rel=\"noopener\" target=\"_blank\">douce musique et perspectives satisfaisantes \u00e0 l\u2019oreille des autorit\u00e9s chinoises<\/a>, trop heureuses de l\u2019alternance politique se dessinant \u00e0 Mal\u00e9 pour le quinquennat \u00e0 venir.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*SunOnline (Maldives), 4 octobre 2023. **Le Pr\u00e9sident Solih a d\u00e9fendu lors de son mandat une politique \u00e9trang\u00e8re ouvertement pro-Inde et sino-sceptique. ***Al Jazeera, 2 octobre 2023<\/div>En recevant ensuite le repr\u00e9sentant de l\u2019Inde aux Maldives, l\u2019ancien ministre du Logement d\u00e9clara qu&rsquo;il esp\u00e9rait replacer la relation indo-maldivienne sur la base du <em>\u00ab\u00a0respect de la souverainet\u00e9\u00a0\u00bb, <\/em>et, propos plus rassurant et agr\u00e9able \u00e0 entendre (encore faut-il bien s\u00fbr y donner suite apr\u00e8s\u2026) pour l\u2019ambassadeur indien, <em>\u00ab\u00a0renforcer le lien sp\u00e9cial s\u00e9culaire entre les Maldives et l&rsquo;Inde pour le porter \u00e0 de nouveaux sommets\u00a0\u00bb*. <\/em>Le successeur du pr\u00e9sident Solih** a \u00e9galement exprim\u00e9 \u00e0 son interlocuteur l&rsquo;espoir de pouvoir restructurer au mieux le remboursement des pr\u00eats contract\u00e9s par l&rsquo;administration sortante, ce que l&rsquo;ambassadeur indien confirma. Relevons \u00e0 ce propos que le chef de gouvernement indien, Narendra Modi, adressa \u00e0 <em>\u00ab\u00a0l\u2019heureux \u00e9lu\u00a0\u00bb <\/em>ses f\u00e9licitations et appela, via X (anciennement Twitter), \u00e0 la poursuite de la coop\u00e9ration bilat\u00e9rale*** : <em>\u00ab\u00a0L&rsquo;Inde reste d\u00e9termin\u00e9e \u00e0 renforcer les relations bilat\u00e9rales entre l&rsquo;Inde et les Maldives, qui ont fait leurs preuves, et \u00e0 am\u00e9liorer notre coop\u00e9ration globale dans la r\u00e9gion de l&rsquo;oc\u00e9an Indien.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPar ailleurs, dans un souci compr\u00e9hensible de se pr\u00e9senter sous un jour somme toute pragmatique et ne pas froisser inutilement son voisin continental imm\u00e9diat, Mohamed Muizzu assura l\u2019\u00e9missaire de New Delhi qu\u2019il ne comptait pas remettre en cause la jurisprudence constante de Mal\u00e9 consistant, pour chaque chef de l&rsquo;\u00c9tat maldivien \u00e9lu, \u00e0 r\u00e9server \u00e0 l\u2019Inde le privil\u00e8ge de son premier d\u00e9placement officiel \u00e0 l\u2019\u00e9tranger, <em>\u00ab\u00a0compte tenu des probl\u00e8mes r\u00e9cents li\u00e9s \u00e0 la pr\u00e9sence militaire indienne\u00a0\u00bb.<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tNotons encore que le 7e chef de l\u2019\u00c9tat maldivien re\u00e7ut le lendemain, jeudi 5 octobre, en plus des ambassadeurs japonais et bangladais, le repr\u00e9sentant d\u2019Islamabad \u00e0 Mal\u00e9, en l\u2019occurrence un vice-amiral \u00e0 la retraite. L&rsquo;occasion pour le nouvel \u00e9lu d\u2019appeler au renforcement des relations bilat\u00e9rales entre l\u2019archipel &#8211; o\u00f9 l\u2019islam est depuis 1997 religion d&rsquo;\u00c9tat et s\u2019impose \u00e0 l\u2019ensemble des Maldiviens &#8211; et la R\u00e9publique islamique du Pakistan.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Dans son <em>Corruption Perceptions Index 2023, <\/em>Transparency International attribue aux Maldives la 85\u00e8me place sur les 184 \u00c9tats pris en compte dans le champ de son \u00e9tude annuelle. **Dans son \u00e9dition 2023 du classement <em>Ease of doing business, <\/em>la Banque Mondiale classe les Maldives au 147e rang sur 190 pays \u00e9valu\u00e9s. ***Purgeant jusqu\u2019alors 11 ans de prison pour blanchiment ill\u00e9gal d\u2019argent et corruption.<\/div>Sur un registre plus domestique, il n\u2019aura gu\u00e8re \u00e9chapp\u00e9 aux Maldiviens ou aux observateurs ext\u00e9rieurs que la bonne gouvernance*, la transparence et les bonnes pratiques** ne devraient pas \u00e0 court terme figurer au rang des priorit\u00e9s de la future administration Muizzu. Le fait que le vainqueur du scrutin pr\u00e9sidentiel du week-end dernier ait, parmi ses tous premiers <em>desiderata <\/em>formul\u00e9s au gouvernement sortant, sollicit\u00e9 la sortie de prison (au profit d\u2019une assignation \u00e0 r\u00e9sidence) de l\u2019ancien pr\u00e9sident Abdulla Yameen*** et qu\u2019il entendait bien \u00e0 l\u2019avenir profiter de ses conseils et de son exp\u00e9rience, est plus de nature \u00e0 interpeller qu\u2019\u00e0 rassurer.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tIl aura \u00e9t\u00e9 beaucoup question lors de la campagne \u00e9lectorale de Mohamed Muizzu d\u2019arguments hostiles \u00e0 l\u2019Inde voisine. La rh\u00e9torique <em>\u00ab\u00a0India Out\u00a0\u00bb <\/em>enflamma nombre de discours et d\u2019interventions publiques de l\u2019opposition, laquelle vantait parall\u00e8lement avec bien plus de soin le b\u00e9n\u00e9fice esp\u00e9r\u00e9 de relations plus approfondies (diplomatiques, politiques, commerciales et financi\u00e8res) \u2013 \u00e0 l\u2019image de la dynamique existante entre 2013 et 2018 sous l\u2019administration ouvertement sinophile d&rsquo;Abdulla Yameen \u2013 avec la R\u00e9publique populaire de Chine. D\u00e9sormais \u00e9lu et les promesses de campagne gratuites derri\u00e8re lui, Mohamed Muizzu, et avec lui son demi-million d\u2019administr\u00e9s, gagnerait d\u00e8s \u00e0 pr\u00e9sent \u00e0 pond\u00e9rer son discours et \u00e0 \u00e9quilibrer avec plus de jugement et de bon sens les relations de l\u2019archipel avec ses deux influents partenaires asiatiques. Pour un b\u00e9n\u00e9fice r\u00e9ciproque.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Olivier Guillard<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/asie-du-sud\/\" rel=\"tag\">Asie du Sud<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/chine\/\" rel=\"tag\">Chine<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/inde\/\" rel=\"tag\">Inde<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/maldives\/\" rel=\"tag\">Maldives<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F10%2F07%2Fmaldives-nouveau-trop-sensibles-sirenes-pekin-chine%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=Les+Maldives+%C3%A0+nouveau+trop+sensibles+aux+sir%C3%A8nes+de+P%C3%A9kin+%3F&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F10%2F07%2Fmaldives-nouveau-trop-sensibles-sirenes-pekin-chine%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F10%2F07%2Fmaldives-nouveau-trop-sensibles-sirenes-pekin-chine%2F&title=Les+Maldives+%C3%A0+nouveau+trop+sensibles+aux+sir%C3%A8nes+de+P%C3%A9kin+%3F\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F10%2F07%2Fmaldives-nouveau-trop-sensibles-sirenes-pekin-chine%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2023%2F10%2Fmuizzu-maldives-vainqueur-presidentielle-250x188.jpg&description=Les+Maldives+%C3%A0+nouveau+trop+sensibles+aux+sir%C3%A8nes+de+P%C3%A9kin+%3F\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/09\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/olivier-guillard\/\">\n\t\t\t\t\t\t\tOlivier Guillard\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tSp\u00e9cialiste de l'Asie, chercheur au CERIAS (Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al), chercheur associ\u00e9 \u00e0 l\u2019Institut d\u2019Etudes de G\u00e9opolitique Appliqu\u00e9e, le Dr Olivier Guillard est notamment l'auteur du livre \"Que faire avec la Cor\u00e9e ? Subir, honnir ou punir ?\u00a0\u00bb (NUVIS, 2019) et co-auteur de \"G\u00e9opolitique du XXIe si\u00e8cle\" (chapitre Afghanistan, Ellipses, Paris, 2024). Entre autres r\u00e9gions d\u2019Asie, il a abondamment voyag\u00e9 en Inde, en Cor\u00e9e du sud, en Afghanistan, en Birmanie, au Sri Lanka, au Pakistan, en Chine, en Tha\u00eflande, en Indon\u00e9sie, au N\u00e9pal, au Cambodge ou encore au Bangladesh. Titulaire d\u2019un Doctorat en droit international public de l\u2019Universit\u00e9 de Paris XI, il est aussi directeur de l\u2019information de la soci\u00e9t\u00e9 Crisis24 (GARDAWORLD), un cabinet de conseil et d\u2019ing\u00e9nierie sp\u00e9cialis\u00e9 dans l\u2019analyse et la gestion des risques internationaux.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2023\/09\/09\/frontieres-inde-chine-art-contrepied\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-600x400.png\" class=\"img-responsive wp-post-image\" alt=\"Un soldat chinois et un militaire indien \u00e0 la fronti\u00e8re Nathu La entre l&#039;Inde et la Chine, le 10 juillet juillet 2008. (Source : Foreign Policy)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-600x400.png 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-250x167.png 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-150x100.png 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-768x513.png 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-200x133.png 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-300x200.png 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere-680x454.png 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/09\/chine-inde-frontiere.png 806w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Fronti\u00e8res avec l'Inde : la Chine ou l\u2019art du contrepied<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2022\/04\/02\/coree-nord-lettre-missile-monstre-odeur-oubliee-printemps-intercoreen\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"281\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-600x281.jpg\" class=\"img-responsive wp-post-image\" alt=\"Le dirigeant nord-cor\u00e9en Kim Jong-Un au milieu d&#039;officiers de l&#039;arm\u00e9e au lancement, selon Pyongyang, du missile balistique intercontinental &quot;Hwasong-17&quot;, le 25 mars 2022. (Source : Infobae)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-600x281.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-250x117.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-1024x480.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-150x70.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-768x360.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-1536x720.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-2048x959.jpg 2048w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-200x94.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-300x141.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-900x422.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-1280x600.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-1600x750.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2022\/04\/lim-jong-un-missile-balistique-1-680x319.jpg 680w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>\"Missile monstre\" en Cor\u00e9e du Nord : l'odeur oubli\u00e9e du printemps intercor\u00e9en<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ouvertement pro-Chine durant la campagne, le candidat de l&rsquo;opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l&rsquo;\u00e9lection pr\u00e9sidentielle aux Maldives, l&rsquo;un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu&rsquo;il s&rsquo;efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l&rsquo;archipel.<\/p>\n","protected":false},"author":563,"featured_media":59023,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[4,22,3,477],"class_list":["post-59017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-asie-du-sud","tag-chine","tag-inde","tag-maldives"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ? - Asialyst<\/title>\n<meta name=\"description\" content=\"Ouvertement pro-Chine durant la campagne, le candidat de l&#039;opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l&#039;\u00e9lection pr\u00e9sidentielle aux Maldives, l&#039;un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu&#039;il s&#039;efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l&#039;archipel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?\" \/>\n<meta property=\"og:description\" content=\"Ouvertement pro-Chine durant la campagne, le candidat de l&#039;opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l&#039;\u00e9lection pr\u00e9sidentielle aux Maldives, l&#039;un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu&#039;il s&#039;efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l&#039;archipel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-07T04:36:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T08:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Olivier Guillard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?\" \/>\n<meta name=\"twitter:description\" content=\"Ouvertement pro-Chine durant la campagne, le candidat de l&#039;opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l&#039;\u00e9lection pr\u00e9sidentielle aux Maldives, l&#039;un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu&#039;il s&#039;efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l&#039;archipel.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Olivier Guillard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/\"},\"author\":{\"name\":\"Olivier Guillard\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/32ec25972eed47015ec7588bd9f28724\"},\"headline\":\"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?\",\"datePublished\":\"2023-10-07T04:36:50+00:00\",\"dateModified\":\"2023-10-09T08:19:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/\"},\"wordCount\":1866,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/muizzu-maldives-vainqueur-presidentielle.jpg\",\"keywords\":[\"Asie du Sud\",\"Chine\",\"Inde\",\"Maldives\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/\",\"name\":\"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ? - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/muizzu-maldives-vainqueur-presidentielle.jpg\",\"datePublished\":\"2023-10-07T04:36:50+00:00\",\"dateModified\":\"2023-10-09T08:19:05+00:00\",\"description\":\"Ouvertement pro-Chine durant la campagne, le candidat de l'opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l'\u00e9lection pr\u00e9sidentielle aux Maldives, l'un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu'il s'efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l'archipel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/muizzu-maldives-vainqueur-presidentielle.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/muizzu-maldives-vainqueur-presidentielle.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Mohamed Muizzu a \u00e9t\u00e9 \u00e9lu pr\u00e9sident de la R\u00e9publique des Maldives le 30 septembre 2023. (Source : France 24)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/10\\\/07\\\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/32ec25972eed47015ec7588bd9f28724\",\"name\":\"Olivier Guillard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg\",\"caption\":\"Olivier Guillard\"},\"description\":\"Sp\u00e9cialiste de l'Asie, chercheur au CERIAS (Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al), chercheur associ\u00e9 \u00e0 l\u2019Institut d\u2019Etudes de G\u00e9opolitique Appliqu\u00e9e, le Dr Olivier Guillard est notamment l'auteur du livre \\\"Que faire avec la Cor\u00e9e ? Subir, honnir ou punir ?\u00a0\u00bb (NUVIS, 2019) et co-auteur de \\\"G\u00e9opolitique du XXIe si\u00e8cle\\\" (chapitre Afghanistan, Ellipses, Paris, 2024). Entre autres r\u00e9gions d\u2019Asie, il a abondamment voyag\u00e9 en Inde, en Cor\u00e9e du sud, en Afghanistan, en Birmanie, au Sri Lanka, au Pakistan, en Chine, en Tha\u00eflande, en Indon\u00e9sie, au N\u00e9pal, au Cambodge ou encore au Bangladesh. Titulaire d\u2019un Doctorat en droit international public de l\u2019Universit\u00e9 de Paris XI, il est aussi directeur de l\u2019information de la soci\u00e9t\u00e9 Crisis24 (GARDAWORLD), un cabinet de conseil et d\u2019ing\u00e9nierie sp\u00e9cialis\u00e9 dans l\u2019analyse et la gestion des risques internationaux.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/olivier-guillard\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ? - Asialyst","description":"Ouvertement pro-Chine durant la campagne, le candidat de l'opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l'\u00e9lection pr\u00e9sidentielle aux Maldives, l'un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu'il s'efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l'archipel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?","og_description":"Ouvertement pro-Chine durant la campagne, le candidat de l'opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l'\u00e9lection pr\u00e9sidentielle aux Maldives, l'un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu'il s'efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l'archipel.","og_url":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2023-10-07T04:36:50+00:00","article_modified_time":"2023-10-09T08:19:05+00:00","og_image":[{"width":1280,"height":960,"url":"http:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg","type":"image\/jpeg"}],"author":"Olivier Guillard","twitter_card":"summary_large_image","twitter_title":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?","twitter_description":"Ouvertement pro-Chine durant la campagne, le candidat de l'opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l'\u00e9lection pr\u00e9sidentielle aux Maldives, l'un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu'il s'efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l'archipel.","twitter_image":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg","twitter_misc":{"\u00c9crit par":"Olivier Guillard","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/"},"author":{"name":"Olivier Guillard","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/32ec25972eed47015ec7588bd9f28724"},"headline":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?","datePublished":"2023-10-07T04:36:50+00:00","dateModified":"2023-10-09T08:19:05+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/"},"wordCount":1866,"commentCount":0,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg","keywords":["Asie du Sud","Chine","Inde","Maldives"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/","url":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/","name":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ? - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg","datePublished":"2023-10-07T04:36:50+00:00","dateModified":"2023-10-09T08:19:05+00:00","description":"Ouvertement pro-Chine durant la campagne, le candidat de l'opposition Mohamed Muizzu a remport\u00e9 le 30 septembre l'\u00e9lection pr\u00e9sidentielle aux Maldives, l'un des \u00c9tats les plus expos\u00e9s au changement climatique. Il a d\u00e9clar\u00e9 imm\u00e9diatement qu'il s'efforcerait de pousser vers la sortie tous les soldats indiens bas\u00e9s dans l'archipel.","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/10\/muizzu-maldives-vainqueur-presidentielle.jpg","width":1280,"height":960,"caption":"Mohamed Muizzu a \u00e9t\u00e9 \u00e9lu pr\u00e9sident de la R\u00e9publique des Maldives le 30 septembre 2023. (Source : France 24)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2023\/10\/07\/maldives-nouveau-trop-sensibles-sirenes-pekin-chine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Maldives \u00e0 nouveau trop sensibles aux sir\u00e8nes de P\u00e9kin ?"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/32ec25972eed47015ec7588bd9f28724","name":"Olivier Guillard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/09\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/09\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/09\/PORTRAIT-OLIVIER-GUILLARD-150x150.jpg","caption":"Olivier Guillard"},"description":"Sp\u00e9cialiste de l'Asie, chercheur au CERIAS (Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al), chercheur associ\u00e9 \u00e0 l\u2019Institut d\u2019Etudes de G\u00e9opolitique Appliqu\u00e9e, le Dr Olivier Guillard est notamment l'auteur du livre \"Que faire avec la Cor\u00e9e ? Subir, honnir ou punir ?\u00a0\u00bb (NUVIS, 2019) et co-auteur de \"G\u00e9opolitique du XXIe si\u00e8cle\" (chapitre Afghanistan, Ellipses, Paris, 2024). Entre autres r\u00e9gions d\u2019Asie, il a abondamment voyag\u00e9 en Inde, en Cor\u00e9e du sud, en Afghanistan, en Birmanie, au Sri Lanka, au Pakistan, en Chine, en Tha\u00eflande, en Indon\u00e9sie, au N\u00e9pal, au Cambodge ou encore au Bangladesh. Titulaire d\u2019un Doctorat en droit international public de l\u2019Universit\u00e9 de Paris XI, il est aussi directeur de l\u2019information de la soci\u00e9t\u00e9 Crisis24 (GARDAWORLD), un cabinet de conseil et d\u2019ing\u00e9nierie sp\u00e9cialis\u00e9 dans l\u2019analyse et la gestion des risques internationaux.","url":"https:\/\/asialyst.com\/fr\/auteur\/olivier-guillard\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/59017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/563"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=59017"}],"version-history":[{"count":10,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/59017\/revisions"}],"predecessor-version":[{"id":59031,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/59017\/revisions\/59031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/59023"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=59017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=59017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=59017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}