﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":57991,"date":"2023-03-18T06:24:46","date_gmt":"2023-03-18T05:24:46","guid":{"rendered":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/brouillon-breves-copy-copy-copy\/"},"modified":"2023-03-18T11:49:00","modified_gmt":"2023-03-18T10:49:00","slug":"afghanistan-pakistan-double-jeu-talibans","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/","title":{"rendered":"Afghanistan-Pakistan : le double jeu des Talibans"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2023-03-18T06:24:46Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 18 Mars 2023<br \/>\n\t\tMis \u00e0 jour 18 Mars 2023\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2023-03-18T11:49:00Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">Analyse<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">Afghanistan-Pakistan : le double jeu des Talibans<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/didierchaudet\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Didier Chaudet            <\/span>\n            <img data-del=\"avatar\" alt=\"Didier Chaudet\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2018\/02\/portrait-2-didier-chaudet.jpeg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png\" class=\"article-image\" title=\"Discussions entre d\u00e9l\u00e9gations minist\u00e9rielles \u00e0 Kaboul, le 22 f\u00e9vrier 2023. (Source : Al Jazeeara)\"><img loading=\"lazy\" decoding=\"async\" width=\"1538\" height=\"1024\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png\" class=\"img-responsive\" alt=\"Discussions entre d\u00e9l\u00e9gations minist\u00e9rielles \u00e0 Kaboul, le 22 f\u00e9vrier 2023. (Source : Al Jazeeara)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png 1538w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-250x166.png 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-1024x682.png 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-150x100.png 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-768x511.png 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-1536x1023.png 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-200x133.png 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-300x200.png 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-600x400.png 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-900x600.png 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-1280x853.png 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban-680x453.png 680w\" sizes=\"auto, (max-width: 1538px) 100vw, 1538px\" \/><\/a>\n      <meta itemprop=\"height\" content=\"1538\"\/>\n      <meta itemprop=\"width\" content=\"1024\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tDiscussions entre d\u00e9l\u00e9gations minist\u00e9rielles \u00e0 Kaboul, le 22 f\u00e9vrier 2023. (Source : <a href=\"https:\/\/www.aljazeera.com\/news\/2023\/2\/22\/pakistan-defence-minister-isi-head-discuss-security-with-taliban\" rel=\"noopener\" target=\"_blank\">Al Jazeeara<\/a>)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tLe niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter <em>ad nauseam <\/em>que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \u00ab\u00a0double jeu\u00a0\u00bb pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Cf. My Life with the Taliban, 2010, p.123.<\/div><em>\u00ab\u00a0Le loup et l\u2019agneau boivent peut-\u00eatre l\u2019eau du m\u00eame ruisseau mais depuis le d\u00e9but du djihad, l\u2019ISI [les services secrets pakistanais] \u00e9tendirent leurs racines au plus profond de l\u2019Afghanistan comme un cancer s\u2019ancrant dans le corps humain.\u00a0\u00bb <\/em>Ces termes particuli\u00e8rement durs se retrouvent dans les m\u00e9moires d\u2019Abdul Salaam Zaeef, l\u2019ancien ambassadeur du mollah Omar au Pakistan*. Dans cet ouvrage, on voit bien l\u2019inimiti\u00e9 entre les Talibans et l\u2019\u00c9tat pakistanais. De leur point de vue, ce dernier a toujours su garder des liens avec l\u2019Alliance du Nord, et les ennemis afghans des Talibans en g\u00e9n\u00e9ral, avant comme apr\u00e8s le 11 septembre. Mais on sait, par l\u2019ouvrage d\u2019Abdul Salaam Zaeef notamment, que les Talibans de l\u2019\u00e9poque du premier \u00c9mirat (1996-2001), ont, de leur c\u00f4t\u00e9, d\u00e9velopp\u00e9 un r\u00e9seau d\u2019informateurs au Pakistan, pour contrer l\u2019influence de l\u2019ISI et de la CIA.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tHistoriquement, les liens entre Talibans et \u00c9tat pakistanais ont \u00e9t\u00e9 tiss\u00e9s, un temps, par pragmatisme, des deux c\u00f4t\u00e9s. Mais ils n\u2019ont jamais consid\u00e9r\u00e9 avoir les m\u00eames int\u00e9r\u00eats \u00e0 long terme. Une r\u00e9alit\u00e9 qui se confirme aujourd\u2019hui encore.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Le deuxi\u00e8me \u00c9mirat et Islamabad : des relations compliqu\u00e9es<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tUn suivi r\u00e9gulier de la diplomatie pakistanaise, juste avant la fuite d\u2019Ashraf Ghani et la chute de la R\u00e9publique islamique d\u2019Afghanistan, montre qu\u2019Islamabad aurait \u00e9t\u00e9 satisfait par une paix de compromis, reconnaissant la victoire militaire des Talibans, mais amenant \u00e0 une r\u00e9conciliation entre les diff\u00e9rentes factions. Il n\u2019y a rien d\u2019\u00e9tonnant \u00e0 cela : cette possibilit\u00e9 aurait couronn\u00e9 les efforts men\u00e9s pour aboutir \u00e0 un processus de paix, qui aurait \u00e9t\u00e9 impossible sans les Pakistanais. Cela aurait signifi\u00e9 la possibilit\u00e9 pour Islamabad, mais aussi pour T\u00e9h\u00e9ran, pour Washington, et pour d\u2019autres acteurs, de s\u2019assurer avoir, au c\u0153ur des institutions afghanes, des hommes proches de leurs int\u00e9r\u00eats. Cela aurait surtout assur\u00e9 une aide internationale continuant de soutenir l\u2019\u00e9conomie afghane, \u00e9vitant de faire de l\u2019Afghanistan, \u00e0 nouveau, un \u00c9tat failli, permettant de g\u00e9rer, \u00e0 terme, la question s\u00e9curitaire afghano-pakistanaise, et le renvoi d\u2019une partie des migrants afghans pr\u00e9sents au Pakistan. La victoire des Talibans a peut-\u00eatre pu satisfaire un certain nombre de voix anti-am\u00e9ricaines, islamistes ou nationalistes, dans ce dernier pays. Mais ce moment de satisfaction n\u2019a pas forc\u00e9ment \u00e9t\u00e9 partag\u00e9 au plus haut niveau, dans l\u2019arm\u00e9e et au minist\u00e8re pakistanais des Affaires \u00e9trang\u00e8res. Les difficult\u00e9s des Talibans \u00e0 constituer un gouvernement, puis leurs choix id\u00e9ologiques d\u00e9sastreux pour les femmes, n\u2019ont pu que confirmer ce sentiment mitig\u00e9 face au nouveau r\u00e9gime.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tUn sentiment pr\u00e9monitoire, \u00e0 bien des \u00e9gards : il est permis de parler de \u00ab\u00a0double jeu\u00a0\u00bb de la part des Talibans afghans. Ou, plus pr\u00e9cis\u00e9ment, une fois arriv\u00e9s au pouvoir, les nouveaux ma\u00eetres de Kaboul ont pu ouvertement d\u00e9fendre ce qu\u2019ils consid\u00e8rent comme les int\u00e9r\u00eats nationaux de l\u2019Afghanistan, \u00e0 savoir une position qui reprend les objectifs classiques du nationalisme pachtoune. C&rsquo;est l&rsquo;ethnie qui a fond\u00e9 l\u2019\u00c9tat afghan moderne, les Talibans en sont tr\u00e8s majoritairement issus.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCela signifie, en premier lieu, faire rapidement dispara\u00eetre tout espoir d\u2019une reconnaissance de la Ligne Durand comme fronti\u00e8re entre l\u2019Afghanistan et le Pakistan. Cette Ligne, n\u00e9e du processus de colonisation britannique, divise la nation pachtoune en deux. Le refus de sa reconnaissance refl\u00e8te un sentiment solidement ancr\u00e9 chez les Talibans : ce n\u2019est que la r\u00e9prise de la position du mollah Omar quand il \u00e9tait au pouvoir, mais aussi de tous les leaders afghans depuis la Partition du Raj britannique ; et cela explique les accrochages militaires \u00e0 la fronti\u00e8re entre Talibans afghans et soldats pakistanais, <a href=\"https:\/\/www.voanews.com\/a\/fresh-border-clashes-between-pakistan-afghanistan-s-taliban-\/6878079.html\" rel=\"noopener\" target=\"_blank\">y compris tr\u00e8s r\u00e9cemment<\/a>. Une situation d\u2019autant plus frustrante pour le Pakistan que c\u2019est la <a href=\"https:\/\/www.files.ethz.ch\/isn\/134344\/durandline.pdf\" rel=\"noopener\" target=\"_blank\">position d\u2019Islamabad que soutient le droit international<\/a> : selon le principe <em>uti possidetis juris, <\/em>affirm\u00e9 par la convention de Vienne, les fronti\u00e8res officielles des \u00c9tats nouvellement ind\u00e9pendants sont celles qu\u2019ils avaient en tant que territoires colonis\u00e9s. Avec un r\u00e9gime moins hostile, et un s\u00e9rieux besoin de reconnaissance internationale et de d\u00e9veloppement \u00e9conomique, le gouvernement d&rsquo;Islamabad pouvait esp\u00e9rer cette fois une logique plus pragmatique \u00e0 Kaboul. Ce n\u2019est pourtant pas le cas. La non-reconnaissance de cette fronti\u00e8re met en danger l\u2019int\u00e9gralit\u00e9 territoriale du Pakistan, voire m\u00eame son existence pure et simple : la position afghane\/pachtoune maximale va jusqu\u2019\u00e0 r\u00e9clamer <a href=\"https:\/\/thediplomat.com\/2014\/02\/why-the-durand-line-matters\/\" rel=\"noopener\" target=\"_blank\">60% du territoire pakistanais actuel<\/a>.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPlus significatif encore d\u2019une hostilit\u00e9 de fait, au-del\u00e0 du discours de bon voisinage profess\u00e9 par le nouveau r\u00e9gime : l\u2019attitude des Talibans afghans face aux Talibans pakistanais du TTP (Tehrik-e Taliban Pakistan). Quand les nouveaux ma\u00eetres de Kaboul prenaient le contr\u00f4le des prisons, ils n\u2019ont pas h\u00e9sit\u00e9 \u00e0 liquider des commandants de l\u2019\u00c9tat Islamique au Khorasan (EI-K), la section r\u00e9gionale de Daech. Les membres du TTP, quant \u00e0 eux, ont re\u00e7u un bien meilleur traitement : plus de 2000 de ses combattants ont \u00e9t\u00e9 lib\u00e9r\u00e9s des ge\u00f4les afghanes. Le TTP a applaudi \u00e0 la victoire des Talibans afghans, et a pu circuler ouvertement en territoire afghan, proche de la fronti\u00e8re avec le Pakistan. Certes, on peut consid\u00e9rer que les Talibans afghans n\u2019ont pas forc\u00e9ment un contr\u00f4le total de leur territoire. Mais il existe un contraste important entre la libert\u00e9 d\u2019actions des Talibans pakistanais et le <a href=\"https:\/\/www.rferl.org\/a\/pakistan-baluch-separatists-afghan-sanctuary\/31687023.html\" rel=\"noopener\" target=\"_blank\">ciblage efficace des s\u00e9paratistes baloutches pakistanais<\/a>. Ces derniers semblent \u00eatre utilis\u00e9s comme un \u00ab\u00a0lot de consolation\u00a0\u00bb offert par Kaboul \u00e0 Islamabad. Lot de consolation bien insuffisant face aux d\u00e9g\u00e2ts caus\u00e9s par le TTP en 2022 : cette ann\u00e9e-l\u00e0, les <a href=\"https:\/\/thediplomat.com\/2023\/01\/the-tehreek-e-taliban-pakistan-is-back-washington-should-take-note\/\" rel=\"noopener\" target=\"_blank\">actes terroristes<\/a> associ\u00e9s \u00e0 ce groupe ont tu\u00e9 plus de 1000 Pakistanais, dont 300 membres des services de s\u00e9curit\u00e9. Les Talibans pakistanais ont clairement \u00e9t\u00e9 motiv\u00e9s par l\u2019arriv\u00e9e au pouvoir des Talibans, et ont b\u00e9n\u00e9fici\u00e9 directement de ce changement de r\u00e9gime.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL\u2019\u00c9mirat a tent\u00e9, malgr\u00e9 cette r\u00e9alit\u00e9, de se pr\u00e9senter comme une force de paix positive entre Islamabad et le TTP. Mais cela n\u2019a d\u00e9bouch\u00e9 sur rien de concret, tout d\u2019abord parce que Kaboul se garde bien de faire pression sur le groupe terroriste. Et pourquoi le r\u00e9gime des Talibans agirait-il autrement ? Le TTP agit militairement pour obtenir ce qu\u2019il exprime diplomatiquement (et parfois par la violence) : le refus de la Ligne Durand.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tBien s\u00fbr, il ne faut pas voir les Talibans afghans comme un bloc, avec les m\u00eames id\u00e9es, les m\u00eames positions. Certains leaders talibans, notamment parmi les plus pragmatiques, voudront \u00e9viter de s\u2019ali\u00e9ner un important voisin au nom d\u2019un fantasme nationaliste, alors que la situation afghane actuelle est d\u00e9j\u00e0 si difficile \u00e9conomiquement. Ils ne sont pas tous partisans d\u2019une confrontation avec le Pakistan pour d\u00e9fendre le TTP, loin de l\u00e0. Mais cette r\u00e9alit\u00e9 ne signifie pas que l\u2019option diplomatique la plus apais\u00e9e sur la question pakistanaise ait forc\u00e9ment les soutiens n\u00e9cessaires pour l\u2019emporter \u00e0 Kaboul.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCela se comprend en observant le <a href=\"https:\/\/www.thenationalnews.com\/opinion\/comment\/2022\/09\/29\/the-surprising-realpolitik-of-the-new-haqqani-network\/\" rel=\"noopener\" target=\"_blank\">positionnement actuel du r\u00e9seau Haqqani<\/a>. Ce dernier, tr\u00e8s influent militairement dans la lutte contre le pr\u00e9c\u00e9dent r\u00e9gime et les Am\u00e9ricains, a souvent \u00e9t\u00e9 r\u00e9sum\u00e9 \u00e0 ses liens avec les mouvements djihadistes \u00e9trangers. Cette vision simpliste am\u00e8ne \u00e0 oublier que le groupe a d\u2019abord eu un positionnement visant \u00e0 d\u00e9fendre ses int\u00e9r\u00eats politiques et \u00e9conomiques, qu\u2019il ne se laisse pas uniquement guid\u00e9 par des questions id\u00e9ologiques. Bien des analystes occidentaux ont fait l\u2019erreur de penser que le r\u00e9seau Haqqani \u00e9tait contr\u00f4l\u00e9 ou fortement influenc\u00e9 par l\u2019ISI, les services secrets pakistanais. Or un certain nombre de documents d\u00e9classifi\u00e9s et d\u2019analyses montrent bien que cela n\u2019a jamais \u00e9t\u00e9 vraiment le cas.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tTout en cherchant \u00e0 pr\u00e9server des liens avec ces services, le r\u00e9seau Haqqani a su pr\u00e9server d\u2019excellentes relations avec Al-Qa\u00efda et le TTP, alors que ces deux groupes livraient une guerre totale contre le Pakistan comme pays. Ces liens \u00e9taient utiles alors que les Talibans afghans \u00e9taient d\u2019abord une r\u00e9bellion anti-gouvernementale. Une fois arriv\u00e9 au pouvoir, l\u2019approche diplomatique du r\u00e9seau Haqqani a chang\u00e9\u2026 mais pas forc\u00e9ment dans un sens plus favorable au Pakistan. Ce pays \u00e9tait utile aux Talibans afghans pour permettre un processus de paix avec les Am\u00e9ricains, et pour emp\u00eacher l\u2019\u00e9crasement d\u2019une r\u00e9bellion qui avait besoin d\u2019une perp\u00e9tuelle m\u00e9sentente entre Kaboul et Islamabad pour exister. Avec la conqu\u00eate compl\u00e8te du pouvoir, il est moins dans l\u2019int\u00e9r\u00eat d\u2019un mouvement irrigu\u00e9 par l\u2019islamisme et le nationalisme pachtoune d\u2019apaiser le grand voisin de l\u2019\u00c9mirat afghan.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe r\u00e9seau Haqqani voit un plus grand int\u00e9r\u00eat \u00e0 apaiser les Am\u00e9ricains, et m\u00eame les Indiens. C\u2019est pourquoi il n\u2019a pas v\u00e9ritablement r\u00e9agi \u00e0 l\u2019assassinat cibl\u00e9 visant Al-Zawahiri le 31 juillet 2022 ; le jour o\u00f9 cet ancien alli\u00e9 se faisait tuer, Sirajuddin Haqqani, maintenant ministre de l\u2019Int\u00e9rieur de l\u2019\u00c9mirat afghan, invitait le secteur priv\u00e9 indien \u00e0 revenir dans son pays. Alors qu\u2019il aurait pu se servir d\u2019un otage am\u00e9ricain, Mark Fredrichs, en repr\u00e9sailles, ils l\u2019ont tout simplement \u00e9chang\u00e9 contre Haji Bashar Noorzai, un important trafiquant de drogues associ\u00e9 aux Talibans. Peu de temps apr\u00e8s, et surement en lien avec cet \u00e9change, une partie de l\u2019argent de l\u2019ancien gouvernement afghan (3,5 milliards de dollars sur 9 milliards) \u00e9tait rendu au nouveau r\u00e9gime\u2026 Au prix d\u2019un abandon d\u2019Al-Qa\u00efda, les Talibans afghans peuvent parler aux Am\u00e9ricains et aux Indiens. Ils n\u2019ont besoin d\u2019abandonner ni le TTP, ni leur r\u00eaves nationalistes pachtounes, dans la configuration diplomatique actuelle.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Contre la tentation du \u00ab\u00a0Pachtounistan\u00a0\u00bb, les r\u00e9ponses possibles du Pakistan<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tFace \u00e0 une attitude qui menace, en fait, son int\u00e9grit\u00e9 territoriale, que peut faire le Pakistan ?<br \/>\nBien s\u00fbr, la priorit\u00e9 ne peut \u00eatre que la stabilisation du territoire national. Cela peut passer par une n\u00e9gociation, ou par une lutte contre-terroriste sans concessions. Les deux approches ont des limites : il est dangereux de n\u00e9gocier avec un groupe terroriste qui s\u2019est impos\u00e9 dans le pass\u00e9 en utilisant une violence indiscrimin\u00e9e contre les civils, mais aussi tr\u00e8s cibl\u00e9e, en liquidant les dirigeants traditionnels en milieu pachtoune, avec des cons\u00e9quences locales d\u00e9sastreuses, jusqu&rsquo;\u00e0 aujourd\u2019hui ; et la lutte contre-terroriste, n\u00e9cessaire, est toujours d\u00e9licate, car elle peut provoquer des dommages collat\u00e9raux.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPar ailleurs, ladite lutte pourrait \u00eatre plus difficile, maintenant que les Am\u00e9ricains voient la zone comme secondaire d\u2019un point de vue de leurs int\u00e9r\u00eats nationaux. Le pouvoir pakistanais n\u2019est plus confront\u00e9 aux pressions am\u00e9ricaines, mais ne peut plus profiter non plus du m\u00eame soutien militaire et \u00e9conomique que par le pass\u00e9 dans sa lutte anti-TTP. Quoi qu\u2019il en soit, politiquement, militairement, le pouvoir central va devoir r\u00e9affirmer sa domination sur sa p\u00e9riph\u00e9rie pachtoune. C\u2019est, apr\u00e8s tout, ce que d\u00e9sire la population locale : elle <a href=\"https:\/\/www.voanews.com\/a\/rising-militant-violence-threatens-peace-in-pakistan-s-scenic-swat\/6785346.html\" rel=\"noopener\" target=\"_blank\">rejette le terrorisme<\/a>, et l\u2019a montr\u00e9 ouvertement, par exemple lors de la grande manifestation anti-TTP \u00e0 Mingora, la ville la plus importante dans la vall\u00e9e de Swat, le 11 octobre dernier. En fait, si le pouvoir central se montre trop mod\u00e9r\u00e9 ou passif face \u00e0 la menace terroriste, il n\u2019est pas exclu que la population locale <a href=\"https:\/\/gandhara.rferl.org\/a\/pakistan-malala-shot-taliban-returning-swat-valley-10-years\/32083677.html\" rel=\"noopener\" target=\"_blank\">prenne sa propre s\u00e9curit\u00e9 en main<\/a>, tellement le rejet de la terreur talibane est grand au sein des Pachtounes pakistanais. Mais une politique uniquement int\u00e9rieure serait insuffisante : Islamabad va devoir r\u00e9pondre au \u00ab\u00a0double jeu\u00a0\u00bb de Kaboul.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDans le cas o\u00f9 la tentation du \u00ab\u00a0Pachtounistan\u00a0\u00bb l\u2019emporterait au sein de la direction des Talibans, Islamabad pourrait faire comprendre \u00e0 Kaboul que le double jeu des Talibans \u00e0 l\u2019\u00e9gard du Pakistan aura un co\u00fbt insupportable. Cela peut passer par des actions militaires en territoire afghan, pour frapper directement les terroristes anti-Pakistan dans l\u2019\u00c9mirat (ce qui a d\u00e9j\u00e0 \u00e9t\u00e9 fait). Diplomatiquement, un message simple pourrait \u00eatre pass\u00e9 : sans reconnaissance pakistanaise du r\u00e9gime des Talibans, en r\u00e9ponse de l\u2019hostilit\u00e9 de ce dernier, on voit mal d\u2019autres pays, notamment la Chine, agir diff\u00e9remment. Cet \u00e9t\u00e9, Islamabad a d\u00e9j\u00e0 fait clairement comprendre que la reconnaissance de l\u2019\u00c9mirat des Talibans ne pourrait \u00eatre <a href=\"https:\/\/tribune.com.pk\/story\/2367408\/pakistan-rules-out-solo-flight-on-taliban-recognition\" rel=\"noopener\" target=\"_blank\">op\u00e9r\u00e9e qu\u2019au niveau r\u00e9gional, par consensus<\/a>. On est loin de la position pakistanaise quelques mois plus t\u00f4t : Islamabad \u00e9tait tent\u00e9 par la reconnaissance individuelle, mais a repouss\u00e9 cette id\u00e9e pour exprimer sa d\u00e9ception face aux choix de politique int\u00e9rieure du nouveau r\u00e9gime. Choix qui incluent, bien s\u00fbr, l\u2019indulgence pour le TTP. Et il est clair que si le Pakistan d\u00e9nonce une pr\u00e9sence terroriste \u00e0 l\u2019int\u00e9rieur du territoire afghan, les soup\u00e7ons d\u2019une pr\u00e9sence djihadiste plus large pouvant cibler d\u2019autres int\u00e9r\u00eats (centrasiatiques, chinois, iraniens, occidentaux) seront renforc\u00e9s, \u00e9loignant plus encore les Talibans d\u2019une reconnaissance, m\u00eame partielle, \u00e0 l\u2019international.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe Pakistan peut aussi se coordonner avec la Chine. Les Talibans ont plac\u00e9 en P\u00e9kin des espoirs quelque peu d\u00e9mesur\u00e9s, mais compr\u00e9hensibles. Apr\u00e8s tout, aucun r\u00eave de reconstruction de l\u2019Afghanistan n&rsquo;est possible sans une implication chinoise. Par le pass\u00e9, le pr\u00e9sident afghan Ashraf Ghani devait passer par Washington pour avoir la possibilit\u00e9 se faire entendre \u00e0 Islamabad. Aujourd\u2019hui, c\u2019est la R\u00e9publique populaire qui a la capacit\u00e9 de jouer ce r\u00f4le d\u2019interm\u00e9diaire. Mais voudra-t-elle s\u2019impliquer ? Elle pourrait ne pas avoir le choix : la d\u00e9fense de ses int\u00e9r\u00eats \u00e9conomiques, des \u00ab\u00a0Nouvelles Routes de la Soie\u00a0\u00bb (Belt and Road Initiative ou BRI), passe par une plus grande stabilit\u00e9, de Karachi \u00e0 Tachkent. Mais il est clair qu\u2019Islamabad devra faire l\u2019effort d\u2019expliquer l\u2019importance d\u2019une implication plus forte \u00e0 une diplomatie chinoise qui, aujourd\u2019hui, a d\u2019autres priorit\u00e9s. \t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tEnfin, si les Pakistanais se voient confront\u00e9s \u00e0 un r\u00e9gime afghan de plus en plus hostile, soutenant de plus en plus ouvertement un groupe terroriste frappant sur leur territoire, la tentation sera forte de revenir \u00e0 une m\u00e9thode qui a fonctionn\u00e9 par le pass\u00e9. \u00c0 savoir soutenir des acteurs non-\u00e9tatiques potentiellement plus amicaux, ou, <em>a minima, <\/em>moins dangereux. Cela exclut, bien entendu, l\u2019EI-K. Ce dernier groupe, comme le TTP, est de plus en plus actif dans sa lutte contre le Pakistan : il est pass\u00e9 de 8 attaques terroristes dans le pays en 2021, \u00e0 <a href=\"https:\/\/tribune.com.pk\/story\/2394869\/ttp-is-k-major-actors-of-violence-in-pakistan-during-2022-pips\" rel=\"noopener\" target=\"_blank\">23 en 2022<\/a>. L\u2019ISI pourrait donc se tourner vers le Front National de R\u00e9sistance (FNR) d\u2019Ahmad Massoud. \t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPour l&rsquo;instant, les capacit\u00e9s de ce mouvement <a href=\"https:\/\/www.areion24.news\/produit\/les-grands-dossiers-de-diplomatie-n-71\/\" rel=\"noopener\" target=\"_blank\">restent limit\u00e9es<\/a>. Mais il en est \u00e0 ses d\u00e9buts. Peu d\u2019analystes auraient mis\u00e9 sur un retour en force des Talibans en 2003. Le FNR a juste besoin de durer, de survivre sur place, et de se trouver des patrons ext\u00e9rieurs. Les Pakistanais pourraient \u00eatre ce soutien ext\u00e9rieur. M\u00eame si la possibilit\u00e9 d\u2019une reconqu\u00eate des forces ayant soutenu le pr\u00e9c\u00e9dent r\u00e9gime semble tr\u00e8s peu probable \u00e0 court terme, cet acteur non-\u00e9tatique pourrait r\u00e9ussir, dans les ann\u00e9es \u00e0 venir, \u00e0 exploiter les vuln\u00e9rabilit\u00e9s des Talibans dans les territoires domin\u00e9s par des non-Pachtounes.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDans les milieux afghans (tadjiks, ouzbeks, hazaras) expatri\u00e9s, certains sont devenus des partisans du s\u00e9paratisme, et pour la <a href=\"https:\/\/twitter.com\/birunikhorasan\/status\/1479843336101974016\" rel=\"noopener\" target=\"_blank\">cr\u00e9ation d\u2019une R\u00e9publique f\u00e9d\u00e9rale du Khorasan<\/a> lib\u00e9r\u00e9e de la domination pachtoune. Une mont\u00e9e en puissance d\u2019une r\u00e9sistance ethnique \u00e0 cette domination est une possibilit\u00e9, m\u00eame si elle n\u2019est pas imm\u00e9diate. Exemple avec les Talibans tadjiks qui <a href=\"https:\/\/www.afintl.com\/en\/202209087583\" rel=\"noopener\" target=\"_blank\">r\u00e9pugnent \u00e0 combattre les forces de Massoud<\/a> encore pr\u00e9sentes dans les provinces de Baghlan et du Pandjchir. Un chef militaire taliban mais d\u2019ethnie tadjike aurait m\u00eame abandonn\u00e9 son camp pour rejoindre le FNR en mai 2022. C\u2019est trop peu pour parler d\u2019un v\u00e9ritable danger pour les Talibans. Il faut se m\u00e9fier de <a href=\"https:\/\/www.spectator.co.uk\/article\/the-next-guerrilla-generation-in-afghanistan-an-interview-with-ahmad-massoud\/#comments-container\" rel=\"noopener\" target=\"_blank\">l\u2019enthousiasme de certains journalistes et sp\u00e9cialistes<\/a>, qui cache mal les capacit\u00e9s limit\u00e9es d\u2019une r\u00e9sistance encore embryonnaire, et l\u2019incapacit\u00e9 de v\u00e9rifier les informations mises en avant par le FNR. Mais il ne faut pas sous-estimer le rejet possible des minorit\u00e9s ethniques face au nouveau pouvoir \u00e0 Kaboul. Le soutien d\u2019une puissance r\u00e9gionale qui a r\u00e9ussi, par le pass\u00e9, \u00e0 influencer d\u2019autres acteurs afghans, pourrait donner \u00e0 cette r\u00e9sistance les moyens de se d\u00e9velopper.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tBien entendu, pour que cela soit possible, il faudrait que cette derni\u00e8re abandonne son discours anti-pakistanais, tr\u00e8s populaire au sein des personnalit\u00e9s politiques de l\u2019ancien r\u00e9gime afghan. Elle pourrait y \u00eatre forc\u00e9, si les plus radicaux, chez les Talibans afghans, consolident leur pouvoir, et continuent \u00e0 faire monter la pression autant sur les minorit\u00e9s en Afghanistan, qu\u2019\u00e0 la fronti\u00e8re afghano-pakistanaise\u2026\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tQuoi qu\u2019il en soit, il est clair que les relations entre le nouveau r\u00e9gime afghan et Islamabad vont \u00eatre difficiles en 2023. Et ce serait une erreur, \u00e0 Paris comme \u00e0 Washington, de consid\u00e9rer que ces tensions bilat\u00e9rales ne concernent pas les Occidentaux. Toute tension r\u00e9gionale pouvant b\u00e9n\u00e9ficier \u00e0 des groupes terroristes et affaiblir une puissance nucl\u00e9aire, m\u00eame localement, devrait \u00eatre une source d\u2019inqui\u00e9tude. Et si Kaboul continue de laisser le TTP agir \u00e0 sa guise, on est en droit de s\u2019inqui\u00e9ter sur ce que cela voudra dire, \u00e0 l\u2019avenir, pour la possibilit\u00e9 d\u2019autres groupes terroristes de trouver un refuge dans l\u2019\u00c9mirat afghan. Plus g\u00e9n\u00e9ralement, m\u00eame si l\u2019influence euro-am\u00e9ricaine ne peut \u00eatre que limit\u00e9e en Asie quand la priorit\u00e9, surtout pour les Europ\u00e9ens, est l\u00e9gitimement l\u2019Ukraine, un trop grand d\u00e9sint\u00e9r\u00eat pour ce qui se passe en Afghanistan et au Pakistan serait une grave erreur. Apr\u00e8s tout, L&rsquo;erreur a d\u00e9j\u00e0 \u00e9t\u00e9 faite dans les ann\u00e9es 1990. Elle a permis l\u2019\u00e9mergence d\u2019Al-Qa\u00efda.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Didier Chaudet<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/afghanistan\/\" rel=\"tag\">Afghanistan<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/al-qaida\/\" rel=\"tag\">Al-Qa\u00efda<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/asie-du-sud\/\" rel=\"tag\">Asie du Sud<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/bri\/\" rel=\"tag\">BRI<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/nouvelles-routes-de-la-soie\/\" rel=\"tag\">Nouvelles routes de la Soie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/pakistan\/\" rel=\"tag\">Pakistan<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/taliban\/\" rel=\"tag\">Taliban<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F03%2F18%2Fafghanistan-pakistan-double-jeu-talibans%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=Afghanistan-Pakistan+%3A+le+double+jeu+des+Talibans&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F03%2F18%2Fafghanistan-pakistan-double-jeu-talibans%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F03%2F18%2Fafghanistan-pakistan-double-jeu-talibans%2F&title=Afghanistan-Pakistan+%3A+le+double+jeu+des+Talibans\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2023%2F03%2F18%2Fafghanistan-pakistan-double-jeu-talibans%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2023%2F03%2Fafghanistan-pakistan-taliban-250x166.png&description=Afghanistan-Pakistan+%3A+le+double+jeu+des+Talibans\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2018\/02\/portrait-2-didier-chaudet.jpeg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/didierchaudet\/\">\n\t\t\t\t\t\t\tDidier Chaudet\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tDidier Chaudet est un consultant ind\u00e9pendant, sp\u00e9cialis\u00e9 sur les questions g\u00e9opolitiques et s\u00e9curitaires en Asie du Sud-Ouest (Iran, Pakistan, Afghanistan) et en Asie Centrale post-sovi\u00e9tique. Il est \u00e9galement le Directeur de la publication du CAPE, chercheur non r\u00e9sident \u00e0 l\u2019IPRI, l\u2019un des principaux think tanks pakistanais, et attach\u00e9 scientifique de l\u2019IFEAC (Institut fran\u00e7ais d\u2019\u00e9tudes sur l\u2019Asie centrale). Il intervient r\u00e9guli\u00e8rement dans les m\u00e9dias fran\u00e7ais (France Culture, Huffington Post, Radio Vatican, R\u00e9forme, entre autres). D\u2019octobre 2013 \u00e0 d\u00e9but 2015, il a v\u00e9cu en Iran, en Afghanistan, et au Pakistan, o\u00f9 il a \u00e9t\u00e9 chercheur invit\u00e9 par plusieurs think tanks locaux. Auparavant, il a \u00e9t\u00e9 chercheur \u00e0 l\u2019ISAS (Institute for South Asian Studies \u2013 National University of Singapore) en charge de l\u2019analyse sur le Pakistan et l\u2019Afghanistan, enseignant \u00e0 Sciences Po (Coll\u00e8gue universitaire), chercheur \u00e0 l\u2019IFRI (en charge de l\u2019Asie Centrale). Pour Asialyst, il suit principalement les \u00e9volutions s\u00e9curitaires et g\u00e9opolitiques de l\u2019Asie Centrale, de l\u2019Afghanistan, et du Pakistan.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2023\/03\/11\/afghanistan-talibans-divises\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"346\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-600x346.png\" class=\"img-responsive wp-post-image\" alt=\"Comment \u00e9valuer les divisions ethniques et politiques au sein des talibans ? (Source : MEI)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-600x346.png 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-250x144.png 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-1024x591.png 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-150x87.png 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-768x443.png 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-200x115.png 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-300x173.png 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-900x519.png 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan-680x392.png 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/roots-taliban-afgahnistan.png 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Afghanistan : les Talibans divis\u00e9s ?<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2021\/09\/17\/afghanistan-rapporchement-americains-etats-unis-taliban-possible\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-600x338.jpg\" class=\"img-responsive wp-post-image\" alt=\"Le porte-parole des Taliban Zabihullah Mujahid (au centre) lors d&#039;une conf\u00e9rence de presse \u00e0 l&#039;a\u00e9roport le 3 septembre 2021. (Source : Mid Day)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-600x338.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-250x141.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-1024x576.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-150x84.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-768x432.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-200x113.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-300x169.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-900x506.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan-680x383.jpg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/09\/taliban-porte-parole-afghanistan.jpg 1280w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Afghanistan : un rapprochement entre Am\u00e9ricains et Taliban est-il possible ?<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \u00ab\u00a0double jeu\u00a0\u00bb pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.<\/p>\n","protected":false},"author":1603,"featured_media":57999,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[183,1680,4,1668,1522,117,312],"class_list":["post-57991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-afghanistan","tag-al-qaida","tag-asie-du-sud","tag-bri","tag-nouvelles-routes-de-la-soie","tag-pakistan","tag-taliban"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afghanistan-Pakistan : le double jeu des Talibans - Asialyst<\/title>\n<meta name=\"description\" content=\"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un &quot;double jeu&quot; pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afghanistan-Pakistan : le double jeu des Talibans\" \/>\n<meta property=\"og:description\" content=\"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un &quot;double jeu&quot; pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-18T05:24:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-18T10:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1538\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Didier Chaudet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Afghanistan-Pakistan : le double jeu des Talibans\" \/>\n<meta name=\"twitter:description\" content=\"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un &quot;double jeu&quot; pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Didier Chaudet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/\"},\"author\":{\"name\":\"Didier Chaudet\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/d5d0ff99ab5dc646bed0c3335fdd8155\"},\"headline\":\"Afghanistan-Pakistan : le double jeu des Talibans\",\"datePublished\":\"2023-03-18T05:24:46+00:00\",\"dateModified\":\"2023-03-18T10:49:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/\"},\"wordCount\":3336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/afghanistan-pakistan-taliban.png\",\"keywords\":[\"Afghanistan\",\"Al-Qa\u00efda\",\"Asie du Sud\",\"BRI\",\"Nouvelles routes de la Soie\",\"Pakistan\",\"Taliban\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/\",\"name\":\"Afghanistan-Pakistan : le double jeu des Talibans - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/afghanistan-pakistan-taliban.png\",\"datePublished\":\"2023-03-18T05:24:46+00:00\",\"dateModified\":\"2023-03-18T10:49:00+00:00\",\"description\":\"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \\\"double jeu\\\" pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/afghanistan-pakistan-taliban.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/afghanistan-pakistan-taliban.png\",\"width\":1538,\"height\":1024,\"caption\":\"Discussions entre d\u00e9l\u00e9gations minist\u00e9rielles \u00e0 Kaboul, le 22 f\u00e9vrier 2023. (Source : Al Jazeeara)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2023\\\/03\\\/18\\\/afghanistan-pakistan-double-jeu-talibans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afghanistan-Pakistan : le double jeu des Talibans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/d5d0ff99ab5dc646bed0c3335fdd8155\",\"name\":\"Didier Chaudet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/portrait-2-didier-chaudet-123x150.jpeg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/portrait-2-didier-chaudet-123x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/portrait-2-didier-chaudet-123x150.jpeg\",\"caption\":\"Didier Chaudet\"},\"description\":\"Didier Chaudet est un consultant ind\u00e9pendant, sp\u00e9cialis\u00e9 sur les questions g\u00e9opolitiques et s\u00e9curitaires en Asie du Sud-Ouest (Iran, Pakistan, Afghanistan) et en Asie Centrale post-sovi\u00e9tique. Il est \u00e9galement le Directeur de la publication du CAPE, chercheur non r\u00e9sident \u00e0 l\u2019IPRI, l\u2019un des principaux think tanks pakistanais, et attach\u00e9 scientifique de l\u2019IFEAC (Institut fran\u00e7ais d\u2019\u00e9tudes sur l\u2019Asie centrale). Il intervient r\u00e9guli\u00e8rement dans les m\u00e9dias fran\u00e7ais (France Culture, Huffington Post, Radio Vatican, R\u00e9forme, entre autres). D\u2019octobre 2013 \u00e0 d\u00e9but 2015, il a v\u00e9cu en Iran, en Afghanistan, et au Pakistan, o\u00f9 il a \u00e9t\u00e9 chercheur invit\u00e9 par plusieurs think tanks locaux. Auparavant, il a \u00e9t\u00e9 chercheur \u00e0 l\u2019ISAS (Institute for South Asian Studies \u2013 National University of Singapore) en charge de l\u2019analyse sur le Pakistan et l\u2019Afghanistan, enseignant \u00e0 Sciences Po (Coll\u00e8gue universitaire), chercheur \u00e0 l\u2019IFRI (en charge de l\u2019Asie Centrale). Pour Asialyst, il suit principalement les \u00e9volutions s\u00e9curitaires et g\u00e9opolitiques de l\u2019Asie Centrale, de l\u2019Afghanistan, et du Pakistan.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/didierchaudet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afghanistan-Pakistan : le double jeu des Talibans - Asialyst","description":"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \"double jeu\" pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/","og_locale":"fr_FR","og_type":"article","og_title":"Afghanistan-Pakistan : le double jeu des Talibans","og_description":"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \"double jeu\" pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.","og_url":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2023-03-18T05:24:46+00:00","article_modified_time":"2023-03-18T10:49:00+00:00","og_image":[{"width":1538,"height":1024,"url":"http:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png","type":"image\/png"}],"author":"Didier Chaudet","twitter_card":"summary_large_image","twitter_title":"Afghanistan-Pakistan : le double jeu des Talibans","twitter_description":"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \"double jeu\" pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.","twitter_image":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png","twitter_misc":{"\u00c9crit par":"Didier Chaudet","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/"},"author":{"name":"Didier Chaudet","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/d5d0ff99ab5dc646bed0c3335fdd8155"},"headline":"Afghanistan-Pakistan : le double jeu des Talibans","datePublished":"2023-03-18T05:24:46+00:00","dateModified":"2023-03-18T10:49:00+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/"},"wordCount":3336,"commentCount":0,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png","keywords":["Afghanistan","Al-Qa\u00efda","Asie du Sud","BRI","Nouvelles routes de la Soie","Pakistan","Taliban"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/","url":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/","name":"Afghanistan-Pakistan : le double jeu des Talibans - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png","datePublished":"2023-03-18T05:24:46+00:00","dateModified":"2023-03-18T10:49:00+00:00","description":"Le niveau z\u00e9ro de l\u2019analyse sur la guerre d\u2019Afghanistan a \u00e9t\u00e9, en France comme aux \u00c9tats-Unis, de r\u00e9p\u00e9ter ad nauseam que les Pakistanais jouaient un double jeu dans ladite guerre. Une interpr\u00e9tation na\u00efve d\u2019une r\u00e9alit\u00e9 g\u00e9opolitique claire : dans l\u2019environnement r\u00e9gional afghan, tout le monde joue un \"double jeu\" pour d\u00e9fendre ses int\u00e9r\u00eats nationaux (tels qu\u2019ils sont pens\u00e9s par les \u00e9lites dirigeantes), et m\u00e9nager les int\u00e9r\u00eats des grandes puissances dont les acteurs locaux esp\u00e8rent les faveurs. L\u2019\u00c9mirat des Talibans, ici, ne fait pas exception \u00e0 cette r\u00e8gle.","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2023\/03\/afghanistan-pakistan-taliban.png","width":1538,"height":1024,"caption":"Discussions entre d\u00e9l\u00e9gations minist\u00e9rielles \u00e0 Kaboul, le 22 f\u00e9vrier 2023. (Source : Al Jazeeara)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2023\/03\/18\/afghanistan-pakistan-double-jeu-talibans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Afghanistan-Pakistan : le double jeu des Talibans"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/d5d0ff99ab5dc646bed0c3335fdd8155","name":"Didier Chaudet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2018\/02\/portrait-2-didier-chaudet-123x150.jpeg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2018\/02\/portrait-2-didier-chaudet-123x150.jpeg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2018\/02\/portrait-2-didier-chaudet-123x150.jpeg","caption":"Didier Chaudet"},"description":"Didier Chaudet est un consultant ind\u00e9pendant, sp\u00e9cialis\u00e9 sur les questions g\u00e9opolitiques et s\u00e9curitaires en Asie du Sud-Ouest (Iran, Pakistan, Afghanistan) et en Asie Centrale post-sovi\u00e9tique. Il est \u00e9galement le Directeur de la publication du CAPE, chercheur non r\u00e9sident \u00e0 l\u2019IPRI, l\u2019un des principaux think tanks pakistanais, et attach\u00e9 scientifique de l\u2019IFEAC (Institut fran\u00e7ais d\u2019\u00e9tudes sur l\u2019Asie centrale). Il intervient r\u00e9guli\u00e8rement dans les m\u00e9dias fran\u00e7ais (France Culture, Huffington Post, Radio Vatican, R\u00e9forme, entre autres). D\u2019octobre 2013 \u00e0 d\u00e9but 2015, il a v\u00e9cu en Iran, en Afghanistan, et au Pakistan, o\u00f9 il a \u00e9t\u00e9 chercheur invit\u00e9 par plusieurs think tanks locaux. Auparavant, il a \u00e9t\u00e9 chercheur \u00e0 l\u2019ISAS (Institute for South Asian Studies \u2013 National University of Singapore) en charge de l\u2019analyse sur le Pakistan et l\u2019Afghanistan, enseignant \u00e0 Sciences Po (Coll\u00e8gue universitaire), chercheur \u00e0 l\u2019IFRI (en charge de l\u2019Asie Centrale). Pour Asialyst, il suit principalement les \u00e9volutions s\u00e9curitaires et g\u00e9opolitiques de l\u2019Asie Centrale, de l\u2019Afghanistan, et du Pakistan.","url":"https:\/\/asialyst.com\/fr\/auteur\/didierchaudet\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/57991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/1603"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=57991"}],"version-history":[{"count":5,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/57991\/revisions"}],"predecessor-version":[{"id":57997,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/57991\/revisions\/57997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/57999"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=57991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=57991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=57991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}