﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":51270,"date":"2021-03-08T14:17:47","date_gmt":"2021-03-08T13:17:47","guid":{"rendered":"http:\/\/asialyst.com\/fr\/2021\/03\/08\/brouillon-regards-copy-3-copy-copy-copy-copy-2-copy-copy-copy-11-copy-copy-4\/"},"modified":"2021-03-08T15:50:23","modified_gmt":"2021-03-08T14:50:23","slug":"camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/","title":{"rendered":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2021-03-08T14:17:47Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 08 Mars 2021<br \/>\n\t\tMis \u00e0 jour 08 Mars 2021\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2021-03-08T15:50:23Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">Analyse<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/pierreantoinedonnet\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Pierre-Antoine Donnet            <\/span>\n            <img data-del=\"avatar\" alt=\"Pierre-Antoine Donnet\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2025\/02\/portrait-pierre-antoine-donnet-1.jpg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\" class=\"article-image\" title=\"Une Ou\u00efghoure dans un checkpoint \u00e0 l'entr\u00e9e du bazar de Hetan, au Xinjiang, province du nord-ouest chinois, le 31 mai 2019.(Source : RFA)\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"843\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\" class=\"img-responsive\" alt=\"Une Ou\u00efghoure dans un checkpoint \u00e0 l&#039;entr\u00e9e du bazar de Hetan, au Xinjiang, province du nord-ouest chinois, le 31 mai 2019.(Source : RFA)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg 1500w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-250x141.jpeg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-1024x575.jpeg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-150x84.jpeg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-768x432.jpeg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-200x112.jpeg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-300x169.jpeg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-600x337.jpeg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-900x506.jpeg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-1280x719.jpeg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine-680x382.jpeg 680w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/a>\n      <meta itemprop=\"height\" content=\"1500\"\/>\n      <meta itemprop=\"width\" content=\"843\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tUne Ou\u00efghoure dans un checkpoint \u00e0 l'entr\u00e9e du bazar de Hetan, au Xinjiang, province du nord-ouest chinois, le 31 mai 2019.(Source : <a href=\"https:\/\/www.rfa.org\/english\/news\/uyghur\/abuse-10302019142433.html\" rel=\"noopener\" target=\"_blank\">RFA<\/a>)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tCe sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l&rsquo;enfer des camps d&rsquo;internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d&rsquo;autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l&rsquo;existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l&rsquo;identit\u00e9 culturelle ou\u00efghoure.\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDernier t\u00e9moignage en date, celui de Gulbahar Jalilova, citoyenne kazakhe, emprisonn\u00e9e dans un camp de d\u00e9tention \u00e0 Urumqi de mai 2017 \u00e0 septembre 2018. Elle en fut lib\u00e9r\u00e9e gr\u00e2ce \u00e0 une intervention de l&rsquo;ONU. Elle r\u00e9side d\u00e9sormais en France depuis janvier dernier. Enferm\u00e9e dans une salle de 25 m\u00b2 avec une quarantaine d\u2019autres d\u00e9tenues \u00e2g\u00e9es de 14 \u00e0 80 ans, elle dit avoir \u00e9t\u00e9 tortur\u00e9e, viol\u00e9e, soumise \u00e0 une contraception forc\u00e9e.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tElle t\u00e9moigne \u00e0 visage d\u00e9couvert sur le fait que les femmes au Xinjiang sont parmi les premi\u00e8res victimes de cette implacable r\u00e9pression. <em>\u00ab\u00a0Nous \u00e9tions debout dans cette pi\u00e8ce, les pieds li\u00e9s par des cha\u00eenes de cinq kilos, <\/em>confie-t-elle dans une <a href=\"https:\/\/www.mediapart.fr\/journal\/international\/221120\/gulbahar-jalilova-rescapee-ouighoure-nous-ne-sommes-pas-des-etres-humains-pour-eux\" rel=\"noopener\" target=\"_blank\">interview diffus\u00e9e le 22 f\u00e9vrier par Mediapart<\/a>. <em>Nous pouvions nous allonger, mais \u00e0 m\u00eame le sol, pas plus de deux heures pour permettre \u00e0 d&rsquo;autres d\u00e9tenues de s&rsquo;allonger \u00e0 leur tour. Il y avait des cam\u00e9ras install\u00e9es aux quatre coins de la pi\u00e8ce. Les policiers, \u00e0 l&rsquo;ext\u00e9rieur de la pi\u00e8ce, nous dictaient leurs ordres par haut-parleur. Nous devions chanter des chants \u00e0 la gloire de Xi Jinping. Plusieurs fois par semaine, on nous administrait des drogues qui ont eu pour cons\u00e9quences que je n&rsquo;avais plus mes r\u00e8gles.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0J&rsquo;ai vu de mes yeux les tortures inflig\u00e9es \u00e0 d&rsquo;autres d\u00e9tenues, <\/em>poursuit Gulbahar Jalilova. <em>Un jour, un jeune homme de 23 ans qui me soumettait \u00e0 un interrogatoire a baiss\u00e9 son pantalon et a mis son sexe dans ma bouche. Je lui ai dit : \u00ab\u00a0Comment peux-tu faire cela, tu pourrais \u00eatre mon fils.\u00a0\u00bb J&rsquo;ai tenu face \u00e0 cet enfer car nous, les d\u00e9tenues, nous nous encouragions les unes les autres. Lorsque finalement j&rsquo;ai \u00e9t\u00e9 lib\u00e9r\u00e9e, ils m&rsquo;ont mis en garde : \u00ab\u00a0La Chine est le pays le plus puissant du monde. Nous avons le bras tr\u00e8s, tr\u00e8s long. Si tu parles, on va te retrouver et te tuer.\u00a0\u00bb Mais mes cod\u00e9tenues m&rsquo;ont suppli\u00e9e de porter leurs voix devant le monde.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0Le fond de la question est colonial\u00a0\u00bb, <\/em>souligne Dilnur Reyhan, une Ou\u00efghoure r\u00e9fugi\u00e9e en France depuis 16 ans et enseignante \u00e0 l&rsquo;Institut national des langues et civilisations orientales (INALCO). Elle est devenue lanceur d&rsquo;alerte et principale porte-parole des Ou\u00efghours en France. Pour elle, ce sont les ressources naturelles que renferme le sous-sol du Xinjiang et sa position g\u00e9ostrat\u00e9gique qui explique ce fait. De nombreux attentats meurtriers attribu\u00e9s aux Ou\u00efghours se sont produits en Chine mais, insiste-t-elle, il n&rsquo;existe aucune preuve que leurs auteurs appartiennent \u00e0 la minorit\u00e9 ou\u00efghoure. <em>\u00ab\u00a0Dans une situation coloniale, entre colonisateurs et colonis\u00e9s, il est normal qu&rsquo;il y ait des tensions.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2><\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tAutre illustration de la volont\u00e9 du r\u00e9gime de P\u00e9kin d&rsquo;\u00e9radiquer l&rsquo;identit\u00e9 culturelle des Ou\u00efghours, la destruction de leur patrimoine humain et communautaire le plus symbolique : les tombes. Je ne r\u00e9siste pas \u00e0 l&rsquo;envie imp\u00e9rieuse de retranscrire ici la quasi-int\u00e9gralit\u00e9 d&rsquo;une d\u00e9p\u00eache de l&rsquo;Agence France-Presse en octobre 2019, diffus\u00e9e apr\u00e8s un reportage tant bien que mal r\u00e9alis\u00e9 au Xinjiang par mes anciens coll\u00e8gues de l&rsquo;AFP de P\u00e9kin. Malgr\u00e9 la surveillance constante des autorit\u00e9s, ils sont parvenus \u00e0 y recueillir des informations de premi\u00e8re main sur le fait que les d\u00e9molisseurs chinois en sont arriv\u00e9s \u00e0 effacer d\u00e9finitivement des cimeti\u00e8res ou\u00efghours pour y construire \u00e0 la place des parkings.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0Des ossements \u00e0 m\u00eame le sol, entre des traces de chenilles m\u00e9talliques, <\/em>d\u00e9crivent-ils dans leur reportage, photo \u00e0 l&rsquo;appui. <em>Dans ce cimeti\u00e8re musulman du nord-ouest de la Chine, les bulldozers n&rsquo;ont pas fait dans le d\u00e9tail, effa\u00e7ant un lien entre les Ou\u00efghours et leur m\u00e9moire d&rsquo;outre-tombe. Au pied des collines du comt\u00e9 de Shayar, des tombeaux, r\u00e9duits \u00e0 des tas de briques, pars\u00e8ment le paysage. Le spectacle se r\u00e9p\u00e8te dans plus d&rsquo;une dizaine de cimeti\u00e8res visit\u00e9s le mois dernier par l&rsquo;AFP au Xinjiang, une r\u00e9gion \u00e0 majorit\u00e9 musulmane qui fait l&rsquo;objet d&rsquo;une stricte reprise en main par P\u00e9kin. Les journalistes ont constat\u00e9 la pr\u00e9sence d&rsquo;ossements \u00e0 l&rsquo;air libre dans trois anciens cimeti\u00e8res.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0Selon des images satellite analys\u00e9es par l&rsquo;AFP avec l&rsquo;association Earthrise Alliance, bas\u00e9e \u00e0 Washington, au moins une quarantaine de cimeti\u00e8res ou\u00efghours ont \u00e9t\u00e9 ras\u00e9s \u00e0 compter de l&rsquo;an dernier [2018] dans cette r\u00e9gion vaste comme trois fois la France. \u00c0 Aksu, dans l&rsquo;ouest de la r\u00e9gion, un vaste cimeti\u00e8re a \u00e9t\u00e9 transform\u00e9 en un \u00ab\u00a0Parc du bonheur\u00a0\u00bb qui comprend un lac artificiel, des jeux pour enfants et des pandas en carton-p\u00e2te. Le site \u00e9tait r\u00e9v\u00e9r\u00e9 par les Ou\u00efghours car il abritait la tombe d&rsquo;un de leurs po\u00e8tes du XXe si\u00e8cle, Lutpulla Mutellip. L&rsquo;endroit \u00e9tait comme \u00ab\u00a0un sanctuaire pour le nationalisme ou\u00efghour\u00a0\u00bb, explique \u00e0 l&rsquo;AFP Ilshat Kokbore, qui s&rsquo;est rendu sur place dans les ann\u00e9es 1990 et vit d\u00e9sormais en exil aux \u00c9tats-Unis. Le sort des restes de Mutellip n&rsquo;est pas connu. Un responsable du nouveau cimeti\u00e8re o\u00f9 les corps ont \u00e9t\u00e9 d\u00e9plac\u00e9s, dans une zone industrielle au milieu du d\u00e9sert, dit tout ignorer de ce qui est advenu des cendres du po\u00e8te. Quant aux autorit\u00e9s d&rsquo;Aksu, elles n&rsquo;\u00e9taient pas joignables pour r\u00e9pondre aux questions de l&rsquo;AFP.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0Le gouvernement chinois s&rsquo;efforce de d\u00e9truire chez les Ou\u00efghours tout sentiment d&rsquo;appartenance \u00e0 cette terre\u00a0\u00bb, accuse Aziz Isa Elkun, un militant exil\u00e9 au Royaume-Uni. La tombe de son p\u00e8re fait partie de celles qui ont \u00e9t\u00e9 d\u00e9truites dans les nombreux cimeti\u00e8res de Shayar. Les cimeti\u00e8res sont \u00ab\u00a0un lien entre l&rsquo;ancienne et la nouvelle g\u00e9n\u00e9ration. C&rsquo;est cela qu&rsquo;ils d\u00e9truisent\u00a0\u00bb, d\u00e9nonce-t-il. Lors de leur reportage en septembre, trois journalistes de l&rsquo;AFP ont visit\u00e9 une dizaine de cimeti\u00e8res d\u00e9truits dans quatre communes, ainsi que trois nouveaux sites o\u00f9 des d\u00e9pouilles ont \u00e9t\u00e9 r\u00e9inhum\u00e9es. L&rsquo;\u00e9quipe a \u00e9t\u00e9 presque constamment suivie par les autorit\u00e9s. Dans un ancien cimeti\u00e8re de Shayar, les journalistes \u00e9taient surveill\u00e9s par un groupe de 11 personnes, dont certaines expliquaient que les ruines des tombes \u00e9taient en fait celles de vieilles maisons, de fours \u00e0 pain, ou encore de simples tas de sable. M\u00eame face aux ossements trouv\u00e9s au sol, les fonctionnaires refusaient de se rendre \u00e0 l&rsquo;\u00e9vidence.\u00a0\u00bb <\/em>Aujourd\u2019hui, un tel reportage ne serait plus possible, car la surveillance et le contr\u00f4le des activit\u00e9s de la presse \u00e9trang\u00e8re au Xinjiang se sont consid\u00e9rablement renforc\u00e9es.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2><\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe 19 janvier dernier, l&rsquo;ancien secr\u00e9taire d&rsquo;\u00c9tat am\u00e9ricain Mike Pompeo avait accus\u00e9 la Chine de commettre un g\u00e9nocide au Xinjiang, accusation reprise peu apr\u00e8s \u00e0 son compte par l&rsquo;actuel secr\u00e9taire d&rsquo;\u00c9tat Anthony Blinken. Le 23 f\u00e9vrier, le parlement canadien a ent\u00e9rin\u00e9 une motion d\u00e9non\u00e7ant un g\u00e9nocide au Xinjiang. Le parlement des Pays-Bas a fait de m\u00eame le 25 f\u00e9vrier.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCe dimanche 7 mars, le ministre chinois des Affaires \u00e9trang\u00e8res et conseiller d&rsquo;\u00c9tat Wang Yi a profit\u00e9 de sa conf\u00e9rence de presse traditionnelle \u00e0 P\u00e9kin en marge de la session annuelle de l&rsquo;Assembl\u00e9e Nationale Populaire (ANP) pour d\u00e9noncer les accusations de g\u00e9nocide au Xinjiang. <em>\u00ab\u00a0Le soi-disant g\u00e9nocide au Xinjiang est ridicule et absurde. Il s&rsquo;agit d&rsquo;une rumeur aux desseins noirs et un mensonge absolu, <\/em>a affirm\u00e9 le chef de la diplomatie. <em>Quand on parle de \u00ab\u00a0g\u00e9nocide\u00a0\u00bb, la plupart des gens pensent aux Indiens en Am\u00e9rique du Nord au XI\u00e8me si\u00e8cle, aux esclaves africains au XIX\u00e8me si\u00e8cle, aux juifs au XX\u00e8me si\u00e8cle et aux aborig\u00e8nes d&rsquo;Australie qui luttent toujours aujourd&rsquo;hui.\u00a0\u00bb <\/em>L&rsquo;Histoire jugera ces propos.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0Je suis partag\u00e9e entre d&rsquo;une part une douleur humaine compatissante pour ces gens qui vivent des moments terribles, inimaginables, <\/em>a d\u00e9clar\u00e9 ce lundi 8 mars \u00e0 Asialyst la sinologue Marie Holzman. <em>Nous avons du mal \u00e0 concevoir ce qu&rsquo;ils doivent endurer. C&rsquo;est une chose. L&rsquo;autre sentiment, c&rsquo;est la stup\u00e9faction. Nous avons tous des amis chinois qui aiment la vie et ont de l&rsquo;humour, qui ont une tr\u00e8s grande intelligence des rapports sociaux et humains. Or l\u00e0 aussi, nous avons beaucoup de mal \u00e0 imaginer que ce sont des Chinois de cette m\u00eame nation qui commettent des crimes contre l&rsquo;humanit\u00e9, comme si cela pouvait faire partie d&rsquo;un programme tout \u00e0 fait acceptable. \u00c7a, c&rsquo;est quelque chose qui d\u00e9passe mon imagination et mon entendement. Cela va au-del\u00e0 de l&rsquo;indignation. L&rsquo;indignation, c&rsquo;est banal. On n&rsquo;arrive pas \u00e0 penser l&rsquo;impensable.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Pierre-Antoine Donnet<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/asie-du-nord-est\/\" rel=\"tag\">Asie du Nord-Est<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/camps-dinternement\/\" rel=\"tag\">camps d'internement<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/camps-de-reeducation\/\" rel=\"tag\">Camps de r\u00e9\u00e9ducation<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/chine\/\" rel=\"tag\">Chine<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/france\/\" rel=\"tag\">France<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/genocide\/\" rel=\"tag\">g\u00e9nocide<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/ouighours\/\" rel=\"tag\">Ou\u00efghours<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/xinjiang\/\" rel=\"tag\">Xinjiang<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F08%2Fcamps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=Camps+au+Xinjiang+%3A+malgr%C3%A9+les+t%C3%A9moignages+de+tortures+et+de+viols%2C+P%C3%A9kin+persiste+%C3%A0+nier&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F08%2Fcamps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F08%2Fcamps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier%2F&title=Camps+au+Xinjiang+%3A+malgr%C3%A9+les+t%C3%A9moignages+de+tortures+et+de+viols%2C+P%C3%A9kin+persiste+%C3%A0+nier\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F08%2Fcamps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2021%2F03%2Fxinjiang-hetan-femmes-ouighours-police-chine-250x141.jpeg&description=Camps+au+Xinjiang+%3A+malgr%C3%A9+les+t%C3%A9moignages+de+tortures+et+de+viols%2C+P%C3%A9kin+persiste+%C3%A0+nier\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2025\/02\/portrait-pierre-antoine-donnet-1.jpg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/pierreantoinedonnet\/\">\n\t\t\t\t\t\t\tPierre-Antoine Donnet\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tAncien r\u00e9dacteur en chef central de l'AFP,\u00a0Pierre-Antoine Donnet est l'auteur d'une quinzaine d'ouvrages consacr\u00e9s\u00a0\u00e0 la Chine, au Japon, au Tibet, \u00e0 l'Inde et aux grands d\u00e9fis asiatiques. En 2020, cet ancien correspondant \u00e0 P\u00e9kin a publi\u00e9 \"Le leadership mondial en question, L'affrontement entre la Chine et les \u00c9tats-Unis\" aux \u00c9ditions de l'Aube. Il est aussi l'auteur de \"Tibet mort ou vif\", paru chez Gallimard. Apr\u00e8s \"Chine, le grand pr\u00e9dateur\", paru en 2021 (l'Aube), il a dirig\u00e9 fin 2022 l'ouvrage collectif \"Le Dossier chinois\" (Cherche Midi). D\u00e9but 2023, il signe \"Confucius aujourd'hui, un h\u00e9ritage universaliste\" (l'Aube) puis en 2024 \"Chine, l'empire des illusions\" (Saint-Simon) et \"Japon, l'envol vers la modernit\u00e9\" (l'Aube). Son dernier livre,  \"Ta\u00efwan, survivre libres\" (\u00e9ditions Nevicata, collection l'\u00e2me des peuples), est paru le 14 novembre 2025.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2021\/02\/05\/chine-ouighours-camps-xinjiang-viol-pratique-courante-bbc\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-600x400.jpg\" class=\"img-responsive wp-post-image\" alt=\"Le 4 f\u00e9vrier 2021, le d\u00e9partement d&#039;\u00c9tat am\u00e9ricain s&#039;est d\u00e9clar\u00e9 &quot;profond\u00e9ment inquiet&quot; des &quot;des t\u00e9moignages de premi\u00e8re main de viols syst\u00e9matiques et d&#039;abus sexuels contre des femmes dans des camps d&#039;internement de Ou\u00efghours et d&#039;autres musulmans au Xinjiang&quot;. (Source : NYPOST)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-600x400.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-250x167.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-1024x682.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-150x100.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-768x512.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-1536x1024.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-200x133.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-300x200.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-900x600.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-1280x853.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-1600x1067.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps-680x453.jpg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/xinjiang-ouighours-camps.jpg 2000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Camps au Xinjiang : le viol est une pratique courante, selon des t\u00e9moignages \u00e0 la BBC<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2021\/01\/12\/rescapee-du-goulag-chinois-gulbuhar-haitiwaji-temoignage-livre-ouighours-france\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"309\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-600x309.jpg\" class=\"img-responsive wp-post-image\" alt=\"Gulbuhar Haitiwaji (au centre) entour\u00e9e de son mari et de l&#039;une de ses filles \u00e0 Paris apr\u00e8s sa lib\u00e9ration. (Copyright : Emmanuelle Marchadour)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-600x309.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-250x129.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-1024x527.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-150x77.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-768x395.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-1536x790.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-200x103.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-300x154.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-900x463.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-1280x659.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-1600x823.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3-680x350.jpg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/01\/OK-Famille-Haitiwaji-2\u00a9emmanuelle-marchadour-copie-3.jpg 1776w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>\"Rescap\u00e9e du Goulag chinois\" par Gulbahar Haitiwaji : le t\u00e9moignage d'une Ou\u00efghoure de France<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l&rsquo;enfer des camps d&rsquo;internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d&rsquo;autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l&rsquo;existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l&rsquo;identit\u00e9 culturelle ou\u00efghoure.<\/p>\n","protected":false},"author":1642,"featured_media":51276,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[23,1731,1520,22,294,80,321,281],"class_list":["post-51270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-asie-du-nord-est","tag-camps-dinternement","tag-camps-de-reeducation","tag-chine","tag-france","tag-genocide","tag-ouighours","tag-xinjiang"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier - Asialyst<\/title>\n<meta name=\"description\" content=\"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l&#039;enfer des camps d&#039;internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d&#039;autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l&#039;existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l&#039;identit\u00e9 culturelle ou\u00efghoure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier\" \/>\n<meta property=\"og:description\" content=\"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l&#039;enfer des camps d&#039;internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d&#039;autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l&#039;existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l&#039;identit\u00e9 culturelle ou\u00efghoure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T13:17:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-08T14:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre-Antoine Donnet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier\" \/>\n<meta name=\"twitter:description\" content=\"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l&#039;enfer des camps d&#039;internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d&#039;autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l&#039;existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l&#039;identit\u00e9 culturelle ou\u00efghoure.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Antoine Donnet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/\"},\"author\":{\"name\":\"Pierre-Antoine Donnet\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/56eaa2f288a6f8b9de83f71f6865f276\"},\"headline\":\"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier\",\"datePublished\":\"2021-03-08T13:17:47+00:00\",\"dateModified\":\"2021-03-08T14:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/\"},\"wordCount\":1686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\",\"keywords\":[\"Asie du Nord-Est\",\"camps d'internement\",\"Camps de r\u00e9\u00e9ducation\",\"Chine\",\"France\",\"g\u00e9nocide\",\"Ou\u00efghours\",\"Xinjiang\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/\",\"name\":\"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\",\"datePublished\":\"2021-03-08T13:17:47+00:00\",\"dateModified\":\"2021-03-08T14:50:23+00:00\",\"description\":\"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l'enfer des camps d'internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d'autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l'existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l'identit\u00e9 culturelle ou\u00efghoure.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg\",\"width\":1500,\"height\":843,\"caption\":\"Une Ou\u00efghoure dans un checkpoint \u00e0 l'entr\u00e9e du bazar de Hetan, au Xinjiang, province du nord-ouest chinois, le 31 mai 2019.(Source : RFA)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/08\\\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/56eaa2f288a6f8b9de83f71f6865f276\",\"name\":\"Pierre-Antoine Donnet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portrait-pierre-antoine-donnet-1-131x150.jpg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portrait-pierre-antoine-donnet-1-131x150.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/portrait-pierre-antoine-donnet-1-131x150.jpg\",\"caption\":\"Pierre-Antoine Donnet\"},\"description\":\"Ancien r\u00e9dacteur en chef central de l'AFP,\u00a0Pierre-Antoine Donnet est l'auteur d'une quinzaine d'ouvrages consacr\u00e9s\u00a0\u00e0 la Chine, au Japon, au Tibet, \u00e0 l'Inde et aux grands d\u00e9fis asiatiques. En 2020, cet ancien correspondant \u00e0 P\u00e9kin a publi\u00e9 \\\"Le leadership mondial en question, L'affrontement entre la Chine et les \u00c9tats-Unis\\\" aux \u00c9ditions de l'Aube. Il est aussi l'auteur de \\\"Tibet mort ou vif\\\", paru chez Gallimard. Apr\u00e8s \\\"Chine, le grand pr\u00e9dateur\\\", paru en 2021 (l'Aube), il a dirig\u00e9 fin 2022 l'ouvrage collectif \\\"Le Dossier chinois\\\" (Cherche Midi). D\u00e9but 2023, il signe \\\"Confucius aujourd'hui, un h\u00e9ritage universaliste\\\" (l'Aube) puis en 2024 \\\"Chine, l'empire des illusions\\\" (Saint-Simon) et \\\"Japon, l'envol vers la modernit\u00e9\\\" (l'Aube). Son dernier livre, \\\"Ta\u00efwan, survivre libres\\\" (\u00e9ditions Nevicata, collection l'\u00e2me des peuples), est paru le 14 novembre 2025.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/pierreantoinedonnet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier - Asialyst","description":"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l'enfer des camps d'internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d'autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l'existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l'identit\u00e9 culturelle ou\u00efghoure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/","og_locale":"fr_FR","og_type":"article","og_title":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier","og_description":"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l'enfer des camps d'internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d'autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l'existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l'identit\u00e9 culturelle ou\u00efghoure.","og_url":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2021-03-08T13:17:47+00:00","article_modified_time":"2021-03-08T14:50:23+00:00","og_image":[{"width":1500,"height":843,"url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg","type":"image\/jpeg"}],"author":"Pierre-Antoine Donnet","twitter_card":"summary_large_image","twitter_title":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier","twitter_description":"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l'enfer des camps d'internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d'autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l'existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l'identit\u00e9 culturelle ou\u00efghoure.","twitter_image":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg","twitter_misc":{"\u00c9crit par":"Pierre-Antoine Donnet","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/"},"author":{"name":"Pierre-Antoine Donnet","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/56eaa2f288a6f8b9de83f71f6865f276"},"headline":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier","datePublished":"2021-03-08T13:17:47+00:00","dateModified":"2021-03-08T14:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/"},"wordCount":1686,"commentCount":0,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg","keywords":["Asie du Nord-Est","camps d'internement","Camps de r\u00e9\u00e9ducation","Chine","France","g\u00e9nocide","Ou\u00efghours","Xinjiang"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/","url":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/","name":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg","datePublished":"2021-03-08T13:17:47+00:00","dateModified":"2021-03-08T14:50:23+00:00","description":"Ce sont surtout des femmes qui parlent. Les t\u00e9moignages bouleversants se multiplient sur l'enfer des camps d'internement au Xinjiang, sur les souffrances des Ou\u00efghours et des musulmans d'autres ethnies dans cette r\u00e9gion du nord-ouest chinois. Malgr\u00e9 tout, la Chine persiste \u00e0 nier la v\u00e9racit\u00e9 de leurs d\u00e9positions quant \u00e0 l'existence d\u2019une volont\u00e9 programm\u00e9e de P\u00e9kin de d\u00e9truire l'identit\u00e9 culturelle ou\u00efghoure.","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/xinjiang-hetan-femmes-ouighours-police-chine.jpeg","width":1500,"height":843,"caption":"Une Ou\u00efghoure dans un checkpoint \u00e0 l'entr\u00e9e du bazar de Hetan, au Xinjiang, province du nord-ouest chinois, le 31 mai 2019.(Source : RFA)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/08\/camps-xinjiang-ouighours-malgre-temoignages-tortures-viols-pekin-chine-persiste-nier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Camps au Xinjiang : malgr\u00e9 les t\u00e9moignages de tortures et de viols, P\u00e9kin persiste \u00e0 nier"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/56eaa2f288a6f8b9de83f71f6865f276","name":"Pierre-Antoine Donnet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2025\/02\/portrait-pierre-antoine-donnet-1-131x150.jpg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2025\/02\/portrait-pierre-antoine-donnet-1-131x150.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2025\/02\/portrait-pierre-antoine-donnet-1-131x150.jpg","caption":"Pierre-Antoine Donnet"},"description":"Ancien r\u00e9dacteur en chef central de l'AFP,\u00a0Pierre-Antoine Donnet est l'auteur d'une quinzaine d'ouvrages consacr\u00e9s\u00a0\u00e0 la Chine, au Japon, au Tibet, \u00e0 l'Inde et aux grands d\u00e9fis asiatiques. En 2020, cet ancien correspondant \u00e0 P\u00e9kin a publi\u00e9 \"Le leadership mondial en question, L'affrontement entre la Chine et les \u00c9tats-Unis\" aux \u00c9ditions de l'Aube. Il est aussi l'auteur de \"Tibet mort ou vif\", paru chez Gallimard. Apr\u00e8s \"Chine, le grand pr\u00e9dateur\", paru en 2021 (l'Aube), il a dirig\u00e9 fin 2022 l'ouvrage collectif \"Le Dossier chinois\" (Cherche Midi). D\u00e9but 2023, il signe \"Confucius aujourd'hui, un h\u00e9ritage universaliste\" (l'Aube) puis en 2024 \"Chine, l'empire des illusions\" (Saint-Simon) et \"Japon, l'envol vers la modernit\u00e9\" (l'Aube). Son dernier livre, \"Ta\u00efwan, survivre libres\" (\u00e9ditions Nevicata, collection l'\u00e2me des peuples), est paru le 14 novembre 2025.","url":"https:\/\/asialyst.com\/fr\/auteur\/pierreantoinedonnet\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/51270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/1642"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=51270"}],"version-history":[{"count":6,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/51270\/revisions"}],"predecessor-version":[{"id":51278,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/51270\/revisions\/51278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/51276"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=51270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=51270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=51270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}