﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":51217,"date":"2021-03-02T04:39:34","date_gmt":"2021-03-02T03:39:34","guid":{"rendered":"http:\/\/asialyst.com\/fr\/2021\/03\/01\/brouillon-regards-copy-3-copy-copy-copy-copy-2-copy-copy-copy-11-copy-copy-4\/"},"modified":"2021-03-02T07:32:54","modified_gmt":"2021-03-02T06:32:54","slug":"birmanie-nasse-resserre-resistants-putsch","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/","title":{"rendered":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2021-03-02T04:39:34Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 02 Mars 2021<br \/>\n\t\tMis \u00e0 jour 02 Mars 2021\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2021-03-02T07:32:54Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">Analyse<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/francischristophe\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Francis Christophe            <\/span>\n            <img data-del=\"avatar\" alt=\"Francis Christophe\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/portrait-francis-christophe-150x150.jpeg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\" class=\"article-image\" title=\"Le 2! f\u00e9vrier 2021, la police birmane avait proc\u00e9d\u00e9 \u00e0 plus de 1 100 arrestations parmi les manifestants contre le coup d'\u00c9tat militaire. (Source : APNEWS)\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\" class=\"img-responsive\" alt=\"Le 2! f\u00e9vrier 2021, la police birmane avait proc\u00e9d\u00e9 \u00e0 plus de 1 100 arrestations parmi les manifestants contre le coup d&#039;\u00c9tat militaire. (Source : APNEWS)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg 2560w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-250x167.jpeg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-1024x683.jpeg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-150x100.jpeg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-768x512.jpeg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-1536x1024.jpeg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-2048x1365.jpeg 2048w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-200x133.jpeg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-300x200.jpeg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-600x400.jpeg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-900x600.jpeg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-1280x853.jpeg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-1600x1067.jpeg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-680x453.jpeg 680w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n      <meta itemprop=\"height\" content=\"2560\"\/>\n      <meta itemprop=\"width\" content=\"1707\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tLe 2! f\u00e9vrier 2021, la police birmane avait proc\u00e9d\u00e9 \u00e0 plus de 1 100 arrestations parmi les manifestants contre le coup d'\u00c9tat militaire. (Source : <a href=\"https:\/\/apnews.com\/article\/aung-san-suu-kyi-myanmar-asia-yangon-southeast-asia-afee2d2de0bfc209bed83f2ff6827978\" rel=\"noopener\" target=\"_blank\">APNEWS<\/a>)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tPendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d&rsquo;\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d&rsquo;Administration de l&rsquo;Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu&rsquo;ait connu l&rsquo;Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d&rsquo;esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l&rsquo;\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu&rsquo;\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d&rsquo;autres villes de province.\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tSelon des sources \u00e0 Rangoun avec lesquelles Asialyst est en contact, le renseignement militaire, connu pour sa brutalit\u00e9, a inaugur\u00e9 dans la nuit du 28 f\u00e9vrier au 1er mars un nouveau mode op\u00e9ratoire : l&rsquo;\u00e9limination cibl\u00e9e <em>(hit list). <\/em>Un t\u00e9moin a confi\u00e9 \u00e0 Asialyst avoir observ\u00e9 le vol d&rsquo;un drone peu avant l&rsquo;arriv\u00e9e tous feux \u00e9teints de voitures banalis\u00e9es d&rsquo;o\u00f9 surgirent des hommes lourdement arm\u00e9s sans uniforme.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tIl n&rsquo;est pas exclu &#8211; ni d\u00e9montr\u00e9 &#8211; que l&rsquo;ing\u00e9nieur de r\u00e9seaux internet Nyi Nyi Aung Htet Naing, tu\u00e9 par balles en pleine rue (hors foule) \u00e0 Rangoun ce dimanche, fasse partie de cette campagne d&rsquo;\u00e9liminations cibl\u00e9es. La veille de sa mort, il avait post\u00e9 sur sa page Facebook : <em>\u00ab\u00a0De combien de cadavres les Nations Unies ont-elles besoin pour passer \u00e0 l&rsquo;action ?\u00a0\u00bb <\/em>Aux yeux du renseignement militaire, Nyi Nyi Aung Htet Naing n&rsquo;est pas n\u00e9c\u00e9ssairement un simple opposant exprimant son rejet du putsch. Ses comp\u00e9tences de haut niveau ont pu en faire une \u00ab\u00a0cible de haute valeur\u00a0\u00bb <em>(high value target).<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Le lourd passif de Facebook en Birmanie<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe r\u00e9seau social Facebook et sa messagerie associ\u00e9e Messenger est quasiment utilis\u00e9 pluri-quotidiennement par tous les Birmans disposant d&rsquo;un smartphone. L&rsquo;appli est pr\u00e9install\u00e9e sur les t\u00e9l\u00e9phones vendus dans le pays. Les coupures nocturnes d&rsquo;Internet ces derni\u00e8res semaines n&rsquo;ont pas v\u00e9ritablement entrav\u00e9 ce moyen de communication privil\u00e9gi\u00e9 des Birmans. Un outil que la soci\u00e9t\u00e9 civile birmane n&rsquo;est pas seule \u00e0 utiliser.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tEn pr\u00e9alable et pendant la campagne de nettoyage ethnique lanc\u00e9e en 2017 par le g\u00e9n\u00e9ral Min Aung Hlaing contre la minorit\u00e9 musulmane Rohingya, de pures campagnes de haine ont \u00e9t\u00e9 professionnellement orchestr\u00e9es sur le r\u00e9seau Facebook birman. Au point que ces pratiques, captures d&rsquo;\u00e9cran \u00e0 l&rsquo;appui, ont fini par porter pr\u00e9judice \u00e0 l&rsquo;image consensuelle que Mark Zuckerberg a toujours voulu donner de son r\u00e9seau \u00e0 haute rentabilit\u00e9.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*<em>Mindfuck, le complot Cambridge Analytica pour s&#8217;emparer de nos cerveaux, <\/em>par Christopher Wylie, Grasset, 2020.<\/div>IL faut lire ce que le lanceur d&rsquo;alerte canadien Christopher Wylie a dire sur le r\u00f4le du r\u00e9seau social am\u00e9ricain dans l&rsquo;histoire r\u00e9cente de la Birmanie. Rappelons que WYlie est l&rsquo;un des cr\u00e9ateurs des algorithmes ayant fait le succ\u00e8s de Cambridge Analytica, le bureau d&rsquo;\u00e9tudes ayant, entre autres, contribu\u00e9 \u00e0 la victoire du Brexit et \u00e0 l&rsquo;\u00e9lection de Donald Trump. Dans son livre-confession <em>Mindfuck*, <\/em>l&rsquo;auteur disserte sur l&rsquo;usage efficace des donn\u00e9es de dizaines de millions d&rsquo;utilisateurs pomp\u00e9es sur Facebook, dont il fut l&rsquo;architecte.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0En 2017, <\/em>\u00e9crit-il, <em>apparaissent [en Birmanie] sur Facebook des discours enflamm\u00e9s appelant \u00e0 l&rsquo;\u00e9limination des Rohingyas et des r\u00e9cits vantant un Myanmar lib\u00e9r\u00e9 des musulmans, qui devinrent rapidement viraux. Ils \u00e9taient, pour l&rsquo;essentiel, cr\u00e9\u00e9s et diffus\u00e9s par une unit\u00e9 sp\u00e9cialis\u00e9e de l&rsquo;arm\u00e9e birmane.\u00a0\u00bb <\/em>Wylie souligne que la direction de Facebook fut r\u00e9guli\u00e8rement inform\u00e9e de la situation birmane par des ONG et des diplomates. <em>\u00ab\u00a0Mais, <\/em>pr\u00e9cise-t-il, <em>l&rsquo;entreprise d\u00e9cida d&rsquo;exclure un groupe Rohingya tout en laissant le champ libre aux groupes militaires et pro-gouvernementaux. En mars 2018, un rapport de l&rsquo;ONU conclut que Facebook a jou\u00e9 un r\u00f4le d\u00e9terminant dans le nettoyage ethnique des Rohingyas.\u00a0\u00bb <\/em>En f\u00e9vrier 2021, la firme de Cupertino a annonc\u00e9 avoir ferm\u00e9 tous les comptes Facebook identifi\u00e9s comme li\u00e9s \u00e0 l&rsquo;arm\u00e9e birmane.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Reconnaissance faciale et drones, nouvelles armes des g\u00e9n\u00e9raux<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDepuis maintenant trois ans, l&rsquo;ensemble des cartes d&rsquo;identit\u00e9 des ressortissants birmans sont num\u00e9ris\u00e9es. Cette base de donn\u00e9es, selon des professionnels consult\u00e9s par Asialyst, peut \u00eatre configur\u00e9e avec les logiciels idoines et des serveurs disponibles dans nombre d&rsquo;\u00c9tats et de firmes priv\u00e9es sp\u00e9cialis\u00e9es. Les comp\u00e9tences dont l&rsquo;arm\u00e9e birmane a fait preuve en 2017 laissent supposer que ces quatre derni\u00e8res semaines de troubles que la junte a r\u00e9prim\u00e9es avec une relative mod\u00e9ration jusqu&rsquo;\u00e0 pr\u00e9sent, ont \u00e9t\u00e9 mises \u00e0 profit pour mettre en route les proc\u00e9dures techniques d&rsquo;identification des meneurs suppos\u00e9s, des organisateurs potentiels et observer leurs modes de communication.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tSi la coordination entre drones et interventions de voitures banalis\u00e9es se r\u00e9p\u00e8te, avec la quantit\u00e9 de documents video et photos ais\u00e9ment disponibles, notamment sur Facebook et Twitter ce mois \u00e9coul\u00e9, cela donne une id\u00e9e de la quantit\u00e9 de Birmans identifiables et potentiellement \u00ab\u00a0\u00e9liminables\u00a0\u00bb. Certains le sont d&rsquo;autant plus facilement qu&rsquo;ils affichent fi\u00e8rement sur leur page Facebook professionnelle leur attachement \u00e0 la d\u00e9mocratie et leur rejet absolu des putschistes.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLes prestataires capables de fournir aux g\u00e9n\u00e9raux birmans formation, mat\u00e9riel et sous-traitance sont nombreux et comp\u00e9tents. En Europe, en Isra\u00ebl, aux \u00c9mirats arabes unis et aux \u00c9tats-Unis, mais aussi en Chine et en Russie. Beaucoup de progr\u00e8s sont intervenus depuis 2005\u20132007, quand la <a href=\"https:\/\/www.lexpress.fr\/actualite\/societe\/justice\/france-libye-l-affaire-amesys-est-gravissime_1093607.html\" rel=\"noopener\" target=\"_blank\">firme fran\u00e7aise Amesys<\/a>, avec l&rsquo;assistance de Claude Gu\u00e9ant, directeur de cabinet de Nicolas Sarkozy alors ministre de l&rsquo;Int\u00e9rieur, <a href=\"https:\/\/www.liberation.fr\/planete\/2011\/09\/02\/kadhafi-a-espionne-les-libyens-grace-a-la-france_758690\/\" rel=\"noopener\" target=\"_blank\">vendit au r\u00e9gime Khadafi un syst\u00e8me d&rsquo;interception et d&rsquo;identification<\/a> de toutes les communications t\u00e9l\u00e9phoniques et internet, qui aboutit \u00e0 la liquidation de la plupart des opposants int\u00e9rieurs et des assassinats cibl\u00e9s hors de Libye.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLa visite non annonc\u00e9e en Birmanie du ministre russe de la D\u00e9fense, le g\u00e9n\u00e9ral Sergue\u00ef Cho\u00efgou deux jours avant le coup d&rsquo;\u00c9tat n&rsquo;a pas fait l&rsquo;objet de commentaires particuliers. Toutefois, de nombreux v\u00e9hicules blind\u00e9s l\u00e9gers flambant neufs film\u00e9s dans les rues de Rangoun et d&rsquo;autres villes importantes \u00e9taient <em>\u00ab\u00a0made in Russia\u00a0\u00bb, <\/em>et n&rsquo;avaient pas \u00e9t\u00e9 remarqu\u00e9s pr\u00e9c\u00e9demment.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Francis Christophe<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/asie-du-sud-est\/\" rel=\"tag\">Asie du Sud-Est<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/aung-san-suu-kyi\/\" rel=\"tag\">Aung san Suu Kyi<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/birmanie\/\" rel=\"tag\">Birmanie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/coup-detat\/\" rel=\"tag\">Coup d'Etat<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/democratie\/\" rel=\"tag\">d\u00e9mocratie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/junte\/\" rel=\"tag\">junte<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/militaires\/\" rel=\"tag\">militaires<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/tatmadaw\/\" rel=\"tag\">Tatmadaw<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F02%2Fbirmanie-nasse-resserre-resistants-putsch%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=Birmanie+%3A+la+nasse+se+resserre+sur+les+r%C3%A9sistants+au+putsch&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F02%2Fbirmanie-nasse-resserre-resistants-putsch%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F02%2Fbirmanie-nasse-resserre-resistants-putsch%2F&title=Birmanie+%3A+la+nasse+se+resserre+sur+les+r%C3%A9sistants+au+putsch\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2021%2F03%2F02%2Fbirmanie-nasse-resserre-resistants-putsch%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2021%2F03%2Frepression-birmanie-manifestants-anti-coup-etat-250x167.jpeg&description=Birmanie+%3A+la+nasse+se+resserre+sur+les+r%C3%A9sistants+au+putsch\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/portrait-francis-christophe-150x150.jpeg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/francischristophe\/\">\n\t\t\t\t\t\t\tFrancis Christophe\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tAncien journaliste \u00e0 l'AFP et de Bakchich, ancien enqu\u00eateur pour l'Observatoire G\u00e9opolitique des Drogues, de Bakchich, Christophe est journaliste ind\u00e9pendant. Auteur du livre \"Birmanie, la dictature du Pavot\" (Picquier, 1998), il est passionn\u00e9 par les \"trous noirs de l'information\". La Birmanie fut, de 1962 \u00e0 1988 le pays r\u00e9pondant le mieux \u00e0 cette d\u00e9finition. Aucune information ne sortait de cette dictature militaire autarcique, archa\u00efque, guerroyant contre ses minorit\u00e9s, clamant sans le d\u00e9sert sa marche sur la voie birmane vers le socialisme.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2021\/02\/23\/birmanie-constance-militaires-min-aung-hlaing-face-refus-passe-honni\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-600x337.jpg\" class=\"img-responsive wp-post-image\" alt=\"Le g\u00e9n\u00e9ral birman Min Aung Hlaing, chef de la junte militaire qui a renverser le gouvernement civil d&#039;Aung San Suu Kyi le 1er f\u00e9vrier 2021. (Source : Asia Nikkei)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-600x337.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-250x141.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-1024x576.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-150x84.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-768x432.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-1536x864.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-2048x1152.jpg 2048w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-200x112.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-300x169.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-900x506.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-1280x720.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-1600x900.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/min-aung-hlaing-birmanie-general-680x382.jpg 680w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Birmanie: la constance des militaires face au refus d'un pass\u00e9 honni<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2021\/02\/19\/coup-etat-birmanie-resistance-face-spectre-1988\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"395\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-600x395.jpeg\" class=\"img-responsive wp-post-image\" alt=\"Les manifestants birmans contre le coup d&#039;\u00c9tat militaire, ici dans les rues de Rangoun le 18 f\u00e9vrier 2021, poursuivent le &quot;Mouvement pour la d\u00e9sob\u00e9issance civile&quot; (Civil Disobedience Movement, CDM). (Source : APNEWS)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-600x395.jpeg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-250x165.jpeg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-150x99.jpeg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-768x506.jpeg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-200x132.jpeg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-300x198.jpeg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi-680x448.jpeg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/birmanie-manifestation-coup-aung-san-suu-kyi.jpeg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Coup d'\u00c9tat en Birmanie : la r\u00e9sistance face au spectre de 1988<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d&rsquo;\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d&rsquo;Administration de l&rsquo;Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu&rsquo;ait connu l&rsquo;Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d&rsquo;esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l&rsquo;\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu&rsquo;\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d&rsquo;autres villes de province.<\/p>\n","protected":false},"author":1651,"featured_media":51221,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[14,494,46,1360,106,418,1705,801],"class_list":["post-51217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-asie-du-sud-est","tag-aung-san-suu-kyi","tag-birmanie","tag-coup-detat","tag-democratie","tag-junte","tag-militaires","tag-tatmadaw"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch - Asialyst<\/title>\n<meta name=\"description\" content=\"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d&#039;\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d&#039;Administration de l&#039;Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu&#039;ait connu l&#039;Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d&#039;esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l&#039;\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu&#039;\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d&#039;autres villes de province.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch\" \/>\n<meta property=\"og:description\" content=\"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d&#039;\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d&#039;Administration de l&#039;Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu&#039;ait connu l&#039;Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d&#039;esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l&#039;\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu&#039;\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d&#039;autres villes de province.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-02T03:39:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-02T06:32:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francis Christophe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch\" \/>\n<meta name=\"twitter:description\" content=\"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d&#039;\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d&#039;Administration de l&#039;Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu&#039;ait connu l&#039;Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d&#039;esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l&#039;\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu&#039;\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d&#039;autres villes de province.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francis Christophe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/\"},\"author\":{\"name\":\"Francis Christophe\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/b3f02ad1bb0d5386042916efb2ba8869\"},\"headline\":\"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch\",\"datePublished\":\"2021-03-02T03:39:34+00:00\",\"dateModified\":\"2021-03-02T06:32:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/\"},\"wordCount\":1221,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\",\"keywords\":[\"Asie du Sud-Est\",\"Aung san Suu Kyi\",\"Birmanie\",\"Coup d'Etat\",\"d\u00e9mocratie\",\"junte\",\"militaires\",\"Tatmadaw\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/\",\"name\":\"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\",\"datePublished\":\"2021-03-02T03:39:34+00:00\",\"dateModified\":\"2021-03-02T06:32:54+00:00\",\"description\":\"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d'\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d'Administration de l'Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu'ait connu l'Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d'esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l'\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu'\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d'autres villes de province.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Le 2! f\u00e9vrier 2021, la police birmane avait proc\u00e9d\u00e9 \u00e0 plus de 1 100 arrestations parmi les manifestants contre le coup d'\u00c9tat militaire. (Source : APNEWS)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2021\\\/03\\\/02\\\/birmanie-nasse-resserre-resistants-putsch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/b3f02ad1bb0d5386042916efb2ba8869\",\"name\":\"Francis Christophe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/portrait-francis-christophe-150x150.jpeg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/portrait-francis-christophe-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/portrait-francis-christophe-150x150.jpeg\",\"caption\":\"Francis Christophe\"},\"description\":\"Ancien journaliste \u00e0 l'AFP et de Bakchich, ancien enqu\u00eateur pour l'Observatoire G\u00e9opolitique des Drogues, de Bakchich, Christophe est journaliste ind\u00e9pendant. Auteur du livre \\\"Birmanie, la dictature du Pavot\\\" (Picquier, 1998), il est passionn\u00e9 par les \\\"trous noirs de l'information\\\". La Birmanie fut, de 1962 \u00e0 1988 le pays r\u00e9pondant le mieux \u00e0 cette d\u00e9finition. Aucune information ne sortait de cette dictature militaire autarcique, archa\u00efque, guerroyant contre ses minorit\u00e9s, clamant sans le d\u00e9sert sa marche sur la voie birmane vers le socialisme.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/francischristophe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch - Asialyst","description":"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d'\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d'Administration de l'Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu'ait connu l'Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d'esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l'\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu'\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d'autres villes de province.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/","og_locale":"fr_FR","og_type":"article","og_title":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch","og_description":"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d'\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d'Administration de l'Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu'ait connu l'Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d'esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l'\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu'\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d'autres villes de province.","og_url":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2021-03-02T03:39:34+00:00","article_modified_time":"2021-03-02T06:32:54+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg","type":"image\/jpeg"}],"author":"Francis Christophe","twitter_card":"summary_large_image","twitter_title":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch","twitter_description":"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d'\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d'Administration de l'Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu'ait connu l'Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d'esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l'\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu'\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d'autres villes de province.","twitter_image":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg","twitter_misc":{"\u00c9crit par":"Francis Christophe","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/"},"author":{"name":"Francis Christophe","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/b3f02ad1bb0d5386042916efb2ba8869"},"headline":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch","datePublished":"2021-03-02T03:39:34+00:00","dateModified":"2021-03-02T06:32:54+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/"},"wordCount":1221,"commentCount":0,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg","keywords":["Asie du Sud-Est","Aung san Suu Kyi","Birmanie","Coup d'Etat","d\u00e9mocratie","junte","militaires","Tatmadaw"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/","url":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/","name":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg","datePublished":"2021-03-02T03:39:34+00:00","dateModified":"2021-03-02T06:32:54+00:00","description":"Pendant les quatre premi\u00e8res semaines de leur pouvoir absolu sur la Birmanie apr\u00e8s le coup d'\u00c9tat, le g\u00e9n\u00e9ral Min Aung Hlaing et son Conseil d'Administration de l'Etat (SAC) affrontent \u00e0 la plus grande campagne de d\u00e9sob\u00e9issance civile qu'ait connu l'Asie du Sud-Est. Un pays paralys\u00e9, o\u00f9 les banques sont \u00e0 court d'esp\u00e8ces depuis trois semaines, o\u00f9 les trains roulent rarement. Mais l'\u00e9tau se resserre sur la r\u00e9sistance au putsch. Ce dimanche 28 f\u00e9vrier, le nombre des manifestants tu\u00e9s r\u00e9pertori\u00e9s a brutalement \u00e9t\u00e9 multipli\u00e9 par 10, compar\u00e9 au total des victimes jusqu'\u00e0 pr\u00e9sent. La plupart ont \u00e9t\u00e9 tu\u00e9s par balles r\u00e9elles \u00e0 Rangoun, Mandalay et d'autres villes de province.","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/03\/repression-birmanie-manifestants-anti-coup-etat-scaled.jpeg","width":2560,"height":1707,"caption":"Le 2! f\u00e9vrier 2021, la police birmane avait proc\u00e9d\u00e9 \u00e0 plus de 1 100 arrestations parmi les manifestants contre le coup d'\u00c9tat militaire. (Source : APNEWS)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2021\/03\/02\/birmanie-nasse-resserre-resistants-putsch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Birmanie : la nasse se resserre sur les r\u00e9sistants au putsch"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/b3f02ad1bb0d5386042916efb2ba8869","name":"Francis Christophe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/portrait-francis-christophe-150x150.jpeg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/portrait-francis-christophe-150x150.jpeg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2021\/02\/portrait-francis-christophe-150x150.jpeg","caption":"Francis Christophe"},"description":"Ancien journaliste \u00e0 l'AFP et de Bakchich, ancien enqu\u00eateur pour l'Observatoire G\u00e9opolitique des Drogues, de Bakchich, Christophe est journaliste ind\u00e9pendant. Auteur du livre \"Birmanie, la dictature du Pavot\" (Picquier, 1998), il est passionn\u00e9 par les \"trous noirs de l'information\". La Birmanie fut, de 1962 \u00e0 1988 le pays r\u00e9pondant le mieux \u00e0 cette d\u00e9finition. Aucune information ne sortait de cette dictature militaire autarcique, archa\u00efque, guerroyant contre ses minorit\u00e9s, clamant sans le d\u00e9sert sa marche sur la voie birmane vers le socialisme.","url":"https:\/\/asialyst.com\/fr\/auteur\/francischristophe\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/51217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/1651"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=51217"}],"version-history":[{"count":6,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/51217\/revisions"}],"predecessor-version":[{"id":51225,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/51217\/revisions\/51225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/51221"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=51217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=51217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=51217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}