﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":48308,"date":"2020-05-18T11:26:55","date_gmt":"2020-05-18T09:26:55","guid":{"rendered":"https:\/\/asialyst.com\/fr\/2020\/05\/08\/brouillon-regards-copy-3-copy-copy-copy-copy-2-copy-copy-copy-11-copy-copy-4\/"},"modified":"2020-05-18T23:53:57","modified_gmt":"2020-05-18T21:53:57","slug":"chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/","title":{"rendered":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2020-05-18T11:26:55Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 18 Mai 2020<br \/>\n\t\tMis \u00e0 jour 18 Mai 2020\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2020-05-18T23:53:57Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">S\u00e9rie - Chine, superpuissance maritime<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/joaquimgaignard\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Joaquim Gaignard            <\/span>\n            <img data-del=\"avatar\" alt=\"Joaquim Gaignard\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2019\/10\/portrait-joaquim-gaignard.jpg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg\" class=\"article-image\" title=\"La station chinoise Grande Muraille situ\u00e9e sur l\u2019\u00eele du Roi-George. (Source : Wikimedia Commons)\"><img loading=\"lazy\" decoding=\"async\" width=\"912\" height=\"413\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg\" class=\"img-responsive\" alt=\"La station chinoise Grande Muraille situ\u00e9e sur l\u2019\u00eele du Roi-George. (Source : Wikimedia Commons)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg 912w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-250x113.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-150x68.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-768x348.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-200x91.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-300x136.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-600x272.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-900x408.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station-680x308.jpg 680w\" sizes=\"auto, (max-width: 912px) 100vw, 912px\" \/><\/a>\n      <meta itemprop=\"height\" content=\"912\"\/>\n      <meta itemprop=\"width\" content=\"413\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tLa station chinoise Grande Muraille situ\u00e9e sur l\u2019\u00eele du Roi-George. (Source : <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/9\/90\/Antarctic_Great_Wall_Station.JPG\" rel=\"noopener noreferrer\" target=\"_blank\">Wikimedia Commons<\/a>)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tRecherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs&#8230; La Chine s&rsquo;affirme en Antarctique. L&rsquo;enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !\t<\/div>\n<\/div>\n<div class=\"large large\" style=\"background-color:#961157;\">\n\t<div class=\"container\">\n\t\t<div class=\"sub-article\">\n\t\t\t<h2>Dossier sp\u00e9cial : La Chine, superpuissance maritime<\/h2>\n\t\t\t<p>Le tour d&rsquo;horizon d&rsquo;Asialyst sur la \u00ab\u00a0Chine hauturi\u00e8re\u00a0\u00bb continue. Pour marquer \u00e0 notre mani\u00e8re les 70 ans de la Chine populaire, nous vous proposons d&rsquo;appr\u00e9hender la projection chinoise en haute mer sous toutes ses composantes. Deuxi\u00e8me volet : \u00ab\u00a0La Chine maritime dans les r\u00e9gions polaires\u00a0\u00bb.<\/p>\n<p>Entre la signature du trait\u00e9 du Svalbard dans les ann\u00e9es 1920 et l&rsquo;\u00e9tablissement des deux premi\u00e8res stations chinoises en Antarctique dans les ann\u00e9es 1980, on ne peut pas dire que l&#8217;empire du Milieu se soit passionn\u00e9 pour ces territoires. Mais les temps ont chang\u00e9.<\/p>\n<p>Retrouvez l&rsquo;int\u00e9grale de notre s\u00e9rie <a href=\"https:\/\/asialyst.com\/fr\/2019\/10\/18\/chine-superpuissance-maritime-hier-aujourd-hui-demain\/\" rel=\"noopener noreferrer\" target=\"_blank\">\u00ab\u00a0La Chine, superpuissance maritime\u00a0\u00bb<\/a> et le d\u00e9but de la <a href=\"https:\/\/asialyst.com\/fr\/2020\/03\/21\/saison-2-chine-regions-polaires\/\" rel=\"noopener noreferrer\" target=\"_blank\">saison 2, \u00ab\u00a0La Chine et les r\u00e9gions polaires\u00a0\u00bb.<\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t15 octobre 2019, un dragon s&rsquo;\u00e9veille pour r\u00e9pondre \u00e0 <a href=\"http:\/\/english.www.gov.cn\/news\/photos\/201910\/15\/content_WS5da52189c6d0bcf8c4c15182.html\" rel=\"noopener noreferrer\" target=\"_blank\">l&rsquo;appel glacial du continent le plus au Sud<\/a>. Une semaine plus tard, il est rejoint par son grand fr\u00e8re, pour la m\u00eame destination. Ils quittent la Chine par la mer et prennent un chemin que le plus \u00e2g\u00e9 conna\u00eet bien d\u00e9sormais. Ils voguent tous azimuts vers la station scientifique chinoise en Antarctique : Zhongshan (\u4e2d\u5c71\u7ad9). Les \u00ab\u00a0dragons des neiges\u00a0\u00bb, \u00ab\u00a0Xuelong\u00a0\u00bb (\u96ea\u9f99) en chinois, sont des brise-glaces qui font la fiert\u00e9 de l&#8217;empire du Milieu. Ils d\u00e9montrent sa capacit\u00e9 \u00e0 mener des exp\u00e9ditions l\u00e0 o\u00f9 les conditions sont les plus hostiles. Il y a donc un <em>Xuelong 1<\/em> et un <em>Xuelong 2<\/em> d\u00e9sormais. Entre les 4 et 9 novembre, les deux navires <a href=\"http:\/\/www.xinhuanet.com\/english\/2019-11\/09\/c_138542741.htm\" rel=\"noopener noreferrer\" target=\"_blank\">faisaient escale<\/a> \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Hobart#\/maplink\/0\" rel=\"noopener noreferrer\" target=\"_blank\">Hobart<\/a>, port australien et porte d&rsquo;entr\u00e9e vers l\u2019Antarctique. Le 2 d\u00e9cembre, l&rsquo;agence de presse officielle chinoise Xinhua rapportait qu&rsquo;ils avaient <a href=\"http:\/\/www.xinhuanet.com\/english\/2019-12\/02\/c_138600007_4.htm\" rel=\"noopener noreferrer\" target=\"_blank\">atteint le premier objectif<\/a> de leur mission, la station de Zhongshan. Apr\u00e8s <a href=\"http:\/\/www.xinhuanet.com\/english\/2020-01\/22\/c_138725323_2.htm\" rel=\"noopener noreferrer\" target=\"_blank\">une escale<\/a> du 20 au 22 janvier dans le port du Cap en Afrique du Sud, le <em>Xuelong 2<\/em>, seul cette fois, retournait vers une seconde station, la base antarctique Grande Muraille, en mer de Weddell. Ravitaillement et tests scientifiques effectu\u00e9s, le fier dragon se remettra ensuite en route <a href=\"http:\/\/french.china.org.cn\/foreign\/txt\/2020-02\/21\/content_75730405.htm\" rel=\"noopener noreferrer\" target=\"_blank\">le 20 f\u00e9vrier<\/a>, pour la derni\u00e8re \u00e9tape de son premier \u00e9t\u00e9 austral : la cinqui\u00e8me station chinoise en construction, en mer de Ross.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"photo-text\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-1142x853.jpg\" class=\"article-image\" title=\"L'Antarctique et la Chine. Carte de Jeremy Masse. (Cr\u00e9dit : Jeremy Masse pour Asialyst)\"><img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"853\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-1142x853.jpg\" class=\"img-responsive\" alt=\"L&#039;Antarctique et la Chine. Carte de Jeremy Masse. (Cr\u00e9dit : Jeremy Masse pour Asialyst)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-1142x853.jpg 1142w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-250x187.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-1024x765.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-150x112.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-768x574.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-1536x1147.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-200x149.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-268x200.jpg 268w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-535x400.jpg 535w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-803x600.jpg 803w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-1428x1067.jpg 1428w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique-680x508.jpg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/de\u0301finitive2020-05-08-Asialyst_Chine_Po\u0302les_Antarctique.jpg 2000w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/><\/a>\n\t\t\t<meta itemprop=\"height\" content=\"1142\"\/>\n\t\t\t<meta itemprop=\"width\" content=\"853\"\/>\n\t\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\"\/>\n\t\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t\t  \tL'Antarctique et la Chine. Carte de Jeremy Masse. (Cr\u00e9dit : Jeremy Masse pour Asialyst)\t\t\t<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Quelques \u00e9l\u00e9ments de g\u00e9ographie<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Stefan Zweig, <em>Les tr\u00e8s riches heures de l\u2019humanit\u00e9,<\/em> Traduit par Alzir Hella et H\u00e9l\u00e8ne Denis-Jeanroy, Litt\u00e9rature \u00e9trang\u00e8re, Paris : P. Belfond, 1989.<\/div><em>\u00ab\u00a0Le p\u00f4le inhabit\u00e9 depuis des milliers d&rsquo;ann\u00e9es et qu&rsquo;aucun \u0153il humain n&rsquo;a probablement jamais contempl\u00e9 depuis la cr\u00e9ation a \u00e9t\u00e9 d\u00e9couvert deux fois dans un temps infime, deux semaines\u00a0\u00bb,<\/em> \u00e9crit Stefan Zweig en 1927, dans sa nouvelle <em>La lutte pour le p\u00f4le Sud.<\/em>* Il y relate la comp\u00e9tition acharn\u00e9e entre le capitaine Scott, un Britannique, et l&rsquo;explorateur Amundsen, un Norv\u00e9gien, du point de vue du premier. La nouvelle raconte la d\u00e9faite tragique de Scott qui, le 17 janvier 1912, arrivant au p\u00f4le Sud au prix d&rsquo;\u00e9preuves mortelles, d\u00e9couvre le drapeau norv\u00e9gien. Amundsen l&rsquo;a plant\u00e9 quelques semaines plus t\u00f4t, le 14 d\u00e9cembre 1911. Dans cette nouvelle captivante et po\u00e9tique, l&rsquo;on saisit toute l&rsquo;hostilit\u00e9 et l&rsquo;inhabilit\u00e9 du continent blanc.<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t\t<\/div>\n<\/div>\n\u00c0 l&rsquo;inverse de l&rsquo;Arctique, qui est un oc\u00e9an, l&rsquo;Antarctique est un continent. Les eaux le bordant constituent l&rsquo;oc\u00e9an Austral et sont connect\u00e9es aux oc\u00e9ans Atlantique, Pacifique et Indien. C&rsquo;est le c\u0153ur de la r\u00e9gion, qui inclut \u00e9galement des \u00eeles de la plaque antarctique. Avec ses 14 millions de kilom\u00e8tres carr\u00e9s, seules l&rsquo;Europe et l&rsquo;Oc\u00e9anie sont plus petites que lui. En hiver, sa superficie double en raison de la formation de la banquise, jusqu&rsquo;\u00e0 pr\u00e8s de 800 km du rivage et des glaces flottantes. Environ 98 % de cette surface est recouverte d&rsquo;une glace \u00e9paisse en moyenne de 1 600 m\u00e8tres. Ce qui contribue \u00e0 lui donner l&rsquo;altitude moyenne la plus \u00e9lev\u00e9e du monde. Si toutes ces glaces fondaient, le niveau des mers et des oc\u00e9ans <a href=\"https:\/\/science.howstuffworks.com\/environmental\/earth\/geophysics\/question473.htm\" rel=\"noopener noreferrer\" target=\"_blank\">monterait de 60 m\u00e8tres<\/a>. L&rsquo;int\u00e9rieur du continent constitue le plus grand d\u00e9sert du monde, avec moins de 20 mm de pr\u00e9cipitations par an.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"photo-text\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael.jpg\" class=\"article-image\" title=\"Le HMS Erebus et HMS Terror en Antarctique par John Wilson Carmichael, 1847, National Maritime Museum, Greenwich, Londres. (Source : Wikimedia Commons)\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"850\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael.jpg\" class=\"img-responsive\" alt=\"Le HMS Erebus et HMS Terror en Antarctique par John Wilson Carmichael, 1847, National Maritime Museum, Greenwich, Londres. (Source : Wikimedia Commons)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-250x166.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-1024x680.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-150x100.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-768x510.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-200x133.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-300x200.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-600x398.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-900x598.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael-680x452.jpg 680w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<meta itemprop=\"height\" content=\"1280\"\/>\n\t\t\t<meta itemprop=\"width\" content=\"850\"\/>\n\t\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\"\/>\n\t\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t\t  \tLe HMS Erebus et HMS Terror en Antarctique par John Wilson Carmichael, 1847, National Maritime Museum, Greenwich, Londres. (Source : <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/a\/ad\/HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael.jpg\/1280px-HMS_Erebus_and_Terror_in_the_Antarctic_by_John_Wilson_Carmichael.jpg\" rel=\"noopener noreferrer\" target=\"_blank\">Wikimedia Commons<\/a>)\t\t\t<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL&rsquo;Antarctique est in\u00e9galement coup\u00e9 en deux par les monts Transantarctiques. Cette cha\u00eene de montagnes, longue de 3 500 kilom\u00e8tres et d&rsquo;une altitude moyenne de 2 500 m\u00e8tres, forme une courbe en \u00ab\u00a0S\u00a0\u00bb depuis la c\u00f4te de la mer de Weddell, jusqu&rsquo;en face des \u00eeles Balleny. Ces monts bordent la barri\u00e8re de Ross o\u00f9 se trouvent les plus hauts sommets, d\u00e9passant 4 000 m d&rsquo;altitude, le plus haut s&rsquo;approchant des 5 000 m (le mont Vinson, 4 897 m). En face des oc\u00e9ans Atlantique et Indien, on parle d&rsquo;Antarctique oriental. L&rsquo;autre partie est l&rsquo;Antarctique occidental.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tC&rsquo;est dans la p\u00e9ninsule (partie occidentale) qu&rsquo;affleure la roche. Cette p\u00e9ninsule est la plus proche d&rsquo;un autre continent : l&rsquo;Am\u00e9rique. Depuis sa pointe Sud, la Terre de Feu, la distance est d&rsquo;environ 1 000 km. Autrement, les plus proches sont les \u00eeles Antipodes de la Nouvelle-Z\u00e9lande (environ 1 900 km), l&rsquo;\u00eele de Tasmanie en Australie (environ 3 000 km) et l&rsquo;Afrique du Sud (environ 3 600 km).\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"photo-text\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg.jpg\" class=\"article-image\" title=\"Base am\u00e9ricaine de McMurdo. (Source : Wikimedia Commons)\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"842\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg.jpg\" class=\"img-responsive\" alt=\"Base am\u00e9ricaine de McMurdo. (Source : Wikimedia Commons)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-250x164.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-1024x674.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-150x99.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-768x505.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-200x132.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-300x197.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-600x395.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-900x592.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-Mcmurdo_1998_hg-680x447.jpg 680w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<meta itemprop=\"height\" content=\"1280\"\/>\n\t\t\t<meta itemprop=\"width\" content=\"842\"\/>\n\t\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\"\/>\n\t\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t\t  \tBase am\u00e9ricaine de McMurdo. (Source : <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/4\/45\/Mcmurdo_1998_hg.jpg\/1280px-Mcmurdo_1998_hg.jpg\" rel=\"noopener noreferrer\" target=\"_blank\">Wikimedia Commons<\/a>)\t\t\t<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe continent conserve pourtant sa rudesse et son hostilit\u00e9, avec des conditions climatiques rappelant l&rsquo;espace interplan\u00e9taire. C&rsquo;est sur ce continent que les temp\u00e9ratures les plus basses ont \u00e9t\u00e9 enregistr\u00e9es : <a href=\"https:\/\/www.nasa.gov\/content\/goddard\/nasa-usgs-landsat-8-satellite-pinpoints-coldest-spots-on-earth\" rel=\"noopener noreferrer\" target=\"_blank\">-93,2\u00b0C en 2010<\/a>, au mois d&rsquo;ao\u00fbt puisque les saisons sont invers\u00e9es dans l&rsquo;h\u00e9misph\u00e8re Sud. Sur les c\u00f4tes, de forts <a href=\"https:\/\/www.persee.fr\/doc\/htn_0018-439x_1989_num_3_1_2225\" rel=\"noopener noreferrer\" target=\"_blank\">vents catabatiques<\/a> balaient le plateau Antarctique. Ils r\u00e9sultent du poids d&rsquo;une masse d&rsquo;air froid d\u00e9valant un relief g\u00e9ographique, en l&rsquo;occurrence l&rsquo;int\u00e9rieur du continent, plus \u00e9lev\u00e9. Ensuite, l&rsquo;hiver polaire est une p\u00e9riode continue d&rsquo;obscurit\u00e9 sur plusieurs mois. Enfin s&rsquo;ajoutent l&rsquo;isolement et les distances qui ne sont pas raccourcies en l&rsquo;absence d&rsquo;infrastructures ou de transports r\u00e9guliers. N\u00e9anmoins, des routes existent en Antarctique. La premi\u00e8re, qui relie la station am\u00e9ricaine de McMurdo \u00e0 la station n\u00e9o-z\u00e9landaise Scott Base, est d&rsquo;une distance \u00e0 peine sup\u00e9rieure \u00e0 trois kilom\u00e8tres. Une autre route, longue de 1 600 km, lie depuis 2006 les stations de McMurdo et d&rsquo;Amundsen-Scott.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"photo-text\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica.jpg\" class=\"article-image\" title=\"Aurore australe prise depuis la Station spatiale internationale. (Source : Wikimedia Commons)\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica.jpg\" class=\"img-responsive\" alt=\"Aurore australe prise depuis la Station spatiale internationale. (Source : Wikimedia Commons)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-250x166.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-1024x682.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-150x100.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-768x511.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-200x133.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-300x200.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-600x400.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-900x600.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/1280px-ISS-52_Aurora_australis_above_Antarctica-680x453.jpg 680w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<meta itemprop=\"height\" content=\"1280\"\/>\n\t\t\t<meta itemprop=\"width\" content=\"852\"\/>\n\t\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\"\/>\n\t\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t\t  \tAurore australe prise depuis la Station spatiale internationale. (Source : <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/f\/f3\/ISS-52_Aurora_australis_above_Antarctica.jpg\/1280px-ISS-52_Aurora_australis_above_Antarctica.jpg\" rel=\"noopener noreferrer\" target=\"_blank\">Wikimedia Commons<\/a>)\t\t\t<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t\u00c0 ces extr\u00eames conditions s&rsquo;ajoutent des ph\u00e9nom\u00e8nes conf\u00e9rant une dimension presque magique au continent. Les fascinantes aurores polaires d&rsquo;abord, courantes dans les zones australes. Ce ph\u00e9nom\u00e8ne lumineux visible pr\u00e8s du p\u00f4le Sud r\u00e9sulte de l&rsquo;interaction des vents solaires avec la haute atmosph\u00e8re terrestre. L&rsquo;espace s&rsquo;invite alors sur Terre. Il y a aussi les parh\u00e9lies, ph\u00e9nom\u00e8ne optique permettant de voir un ou plusieurs point(s) lumineux pr\u00e8s du Soleil, donnant l&rsquo;illusion que la Terre aurait plusieurs \u00e9toiles.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Une puissance scientifique qui s&rsquo;affirme<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*\u00a0\u00bbIt will also conduct preliminary construction work of China&rsquo;s fifth research station on Inexpressible Island\u00a0\u00bb, Xinhua et \u00ab\u00a0China\u2019s first homegrown polar icebreaker to start its maiden voyage\u00a0\u00bb, in English.gov.cn, 15 octobre 2019.<\/div>La Chine est la troisi\u00e8me nation la plus d\u00e9pensi\u00e8re au monde en termes de financements publics pour la recherche scientifique en Antarctique. Concr\u00e8tement, cela se traduit par environ 600 chercheurs r\u00e9partis sur quatre et bient\u00f4t cinq stations install\u00e9es sur le continent. Cinq, car la Chine est <a href=\"http:\/\/english.www.gov.cn\/news\/photos\/201910\/15\/content_WS5da52189c6d0bcf8c4c15182.htmlhttp:\/\/english.www.gov.cn\/news\/photos\/201910\/15\/content_WS5da52189c6d0bcf8c4c15182.html\" rel=\"noopener noreferrer\" target=\"_blank\">en train d&rsquo;ajouter<\/a> la station de <a href=\"http:\/\/www.pric.org.cn\/detail\/News.aspx?id=5673b1a6-f119-46f1-9814-a95035bd2c4d\" rel=\"noopener noreferrer\" target=\"_blank\">l&rsquo;\u00eele Inexpressible<\/a> aux stations existantes de Changcheng, la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Base_antarctique_Grande_Muraille#\/maplink\/0\" rel=\"noopener noreferrer\" target=\"_blank\">Grande Muraille<\/a> (1985), <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Base_antarctique_Zhongshan#\/maplink\/0\" rel=\"noopener noreferrer\" target=\"_blank\">Zhongshan<\/a> (1989), Kunlun (2009) et Taishan (2014)*. <em>\u00ab\u00a0Le 7 f\u00e9vrier 2018, pendant la 34\u00e8me exp\u00e9dition antarctique, les chercheurs chinois ont pos\u00e9 les fondations de la cinqui\u00e8me station de recherche sur l&rsquo;\u00eele Inexpressible, en Terra Nova de la mer de Ross\u00a0\u00bb,<\/em> <a href=\"https:\/\/thediplomat.com\/2018\/06\/what-does-chinas-fifth-research-station-mean-for-antarctic-governance\/\" rel=\"noopener noreferrer\" target=\"_blank\">expliquait en 2018 Nengye Liu<\/a>, professeur \u00e0 l&rsquo;universit\u00e9 d&rsquo;Ad\u00e9la\u00efde en Australie, \u00e0 <em>The Diplomat.<\/em> La construction devrait s&rsquo;achever en 2022. Cette <em>\u00ab\u00a0nouvelle station de la mer de Ross\u00a0\u00bb <\/em>(\u7f57\u65af\u6d77\u65b0\u7ad9) est con\u00e7ue comme permanente, afin d&rsquo;accueillir 80 personnes en \u00e9t\u00e9 et 30 en hiver. En janvier 2019, le <em>Xuelong 1<\/em> avait <a href=\"https:\/\/www.dailymotion.com\/video\/x714mr2\" rel=\"noopener noreferrer\" target=\"_blank\">percut\u00e9 un iceberg<\/a>, causant des avaries relativement s\u00e9v\u00e8res, en man\u0153uvrant pour les travaux de construction de la station.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCes installations scientifiques sont un enjeu g\u00e9opolitique, notamment pour l&rsquo;avenir du <a href=\"https:\/\/documents.ats.aq\/keydocs\/vol_1\/vol1_2_AT_Antarctic_Treaty_f.pdf\" rel=\"noopener noreferrer\" target=\"_blank\">trait\u00e9 sur l&rsquo;Antarctique de 1959<\/a>, v\u00e9ritable pi\u00e8ce ma\u00eetresse de la gouvernance de la r\u00e9gion, et remarquable par les principes qu&rsquo;il consacre. La Chine s&rsquo;int\u00e9resse particuli\u00e8rement \u00e0 la partie orientale du continent, celle revendiqu\u00e9e par l&rsquo;Australie et la France. Elle propose en effet depuis plusieurs ann\u00e9es le projet \u00ab\u00a0ABC\u00a0\u00bb, qui lui permettrait de relier sa station Zhongshan, sur la fa\u00e7ade indo-australe, \u00e0 sa nouvelle station <a href=\"http:\/\/www.pric.org.cn\/detail\/News.aspx?id=5673b1a6-f119-46f1-9814-a95035bd2c4d\" rel=\"noopener noreferrer\" target=\"_blank\">faisant face<\/a> \u00e0 l&rsquo;oc\u00e9an Pacifique, sur l&rsquo;\u00eele Inexpressible.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Nengye Liu, \u00ab\u00a0What Does China\u2019s Fifth Research Station Mean for Antarctic Governance ?\u00a0\u00bb, <em>The Diplomat,<\/em> 28 juin 2018.<\/div>Certains sp\u00e9cialistes, notamment am\u00e9ricains, n\u00e9o-z\u00e9landais et australiens, sont sur leurs gardes et expliquent que cela pourrait \u00eatre un premier pas vers une politique plus offensive. Nengye Liu, de l&rsquo;universit\u00e9 d&rsquo;Ad\u00e9la\u00efde, se montre attentif : <em>\u00ab\u00a0La Chine am\u00e9liore ses capacit\u00e9s scientifiques et diplomatiques, tout en restant aux aguets pour une r\u00e9forme du trait\u00e9 sur l&rsquo;Antarctique dans un environnement g\u00e9opolitique mouvant. On peut s&rsquo;attendre \u00e0 ce que la Chine publie une politique antarctique officielle avec l&rsquo;ach\u00e8vement de cette cinqui\u00e8me station.\u00a0\u00bb<\/em>* Le trait\u00e9 sur l&rsquo;Antarctique ne l&rsquo;interdit pas, mais g\u00e8le jusqu&rsquo;en 2048 l&rsquo;\u00e9mission de nouvelles revendications territoriales sur le continent, date \u00e0 laquelle l&rsquo;ouverture de n\u00e9gociations ayant trait \u00e0 cette probl\u00e9matique sera permise.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLa Chine est aussi l&rsquo;un de pays initiateurs du <a href=\"http:\/\/www.afops.org\/m11.php\" rel=\"noopener noreferrer\" target=\"_blank\">Forum asiatique pour les sciences polaires<\/a> (AFoPS) form\u00e9 en 2004. Ce forum permet aux chercheurs asiatiques de se constituer en groupe r\u00e9gional, afin de peser plus lourd, notamment dans les nombreuses instances de gouvernance de l&rsquo;Antarctique. On y retrouve ainsi des chercheurs chinois, japonais, sud-cor\u00e9ens, indiens, malaisiens, tha\u00eflandais, indon\u00e9siens, philippins, sri-lankais ou encore vietnamiens.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Ressources halieutiques : l&rsquo;app\u00e2t du krill<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Nengye Liu, \u00ab\u00a0What Are China\u2019s Intentions in Antarctica ?\u00a0\u00bb, <em>The Diplomat,<\/em> 14 juin 2019.<\/div>Comme la France, la Russie, le Japon, la Norv\u00e8ge, l&rsquo;Argentine, le Chili, l&rsquo;Australie ou encore la Nouvelle-Z\u00e9lande, pr\u00e9sents dans les eaux australes, la Chine a un app\u00e9tit consid\u00e9rable pour les ressources marines en poisson, et plus encore en krill. Cet animal microscopique est une pi\u00e8ce \u00e9l\u00e9mentaire dans les cha\u00eenes alimentaires marines. Les qualit\u00e9s nutritives et sanitaires de ce crustac\u00e9 sont une aubaine. Le 1er novembre 2019 \u00e0 Hobart, les 24 pays membres de la Convention sur la conservation de la faune et la flore marines de l&rsquo;Antarctique (CCAMLR) et l&rsquo;Union europ\u00e9enne (UE) se sont r\u00e9unis. Cette convention des \u00c9tats parties du trait\u00e9 de 1959 a \u00e9tudi\u00e9 les propositions faites par la France et l&rsquo;Australie d&rsquo;aires marines prot\u00e9g\u00e9es, des \u00ab\u00a0AMPA\u00a0\u00bb, aux r\u00e9glementations environnementales strictes, pour limiter la p\u00eache dans certaines zones de l&rsquo;oc\u00e9an Austral. Mais la Russie et la Chine ont bloqu\u00e9 les n\u00e9gociations. <em>The Diplomat<\/em> <a href=\"https:\/\/thediplomat.com\/2019\/06\/what-are-chinas-intentions-in-antarctica\/\" rel=\"noopener noreferrer\" target=\"_blank\">expose<\/a> l&rsquo;enjeu : <em>\u00ab\u00a0La Chine porte de l&rsquo;attention au krill antarctique [&#8230;]. Pour l&rsquo;instant, les prises sont faibles. Pourtant, la Chine voit le potentiel du krill m\u00eame sous la gestion de la CCAMLR, et est int\u00e9ress\u00e9e par l&rsquo;id\u00e9e d&rsquo;augmenter ses prises dans la zone. C&rsquo;est bien l\u00e0 l&rsquo;origine de l&rsquo;impasse des n\u00e9gociations concernant l&rsquo;\u00e9tablissement d&rsquo;AMPA.\u00a0\u00bb<\/em>*\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLes ressources marines du Grand Sud sont exploit\u00e9es depuis au moins le XVIII\u00e8me si\u00e8cle. Les marins y capturaient otaries et \u00e9l\u00e9phants de mer, pr\u00e9cieux pour leur fourrure. Les manchots, alors, et les baleines, toujours, pour leur graisse et leur viande. De nos jours, les poissons (l\u00e9gine, bocasse, poissons des glaces), les crabes, calamars et \u00e9videmment les krills, sont les plus pr\u00e9cieux pour nourrir des populations grandissantes.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Haijun Chi, Xiaolong Li et Xianshi Yang, <a href=\"http:\/\/https:\/\/doi.org\/10.5829\/idosi.wjfms.2013.05.03.71138\" rel=\"noopener noreferrer\" target=\"_blank\">\u00ab\u00a0Processing Status and Utilization Strategies of Antarctic Krill (Euphausia Superba) in China\u00a0\u00bb<\/a>, in <em>World Journal of Fish and Marine Sciences 3<\/em>, no 5 (2013), p. 275\u201181.<\/div>Les Chinois sont renomm\u00e9s pour les prises massives de krill, absolument strat\u00e9gique pour leur march\u00e9 alimentaire en raison de son tr\u00e8s bon rapport prot\u00e9ines-graisse. Des \u00e9tudes comme celle de l&rsquo;Acad\u00e9mie chinoise des sciences halieutiques de Shanghai de 2013, mettent en avant les vertus nutritionnelles, les ressources exploitables et les b\u00e9n\u00e9fices potentiels qu\u2019il est possible de tirer du krill.*\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLes p\u00eacheurs chinois sont pr\u00e9sents dans l&rsquo;oc\u00e9an Austral, et <a href=\"https:\/\/asialyst.com\/fr\/2019\/10\/10\/chine-maritime-navale-6-7-peche-prospection-avant-poste-puissance\/\" rel=\"noopener noreferrer\" target=\"_blank\">souvent ill\u00e9galement<\/a>. Alors que la CCAMLR limite la prise annuelle totale de krill \u00e0 680 000 tonnes, la part chinoise en 2014 \u00e9tait de 55 000 tonnes, environ 9 % de ce total. <em>\u00ab\u00a0La Chine devrait avoir pour objectif de p\u00eacher un \u00e0 deux millions de tonnes\u00a0\u00bb<\/em>, <a href=\"http:\/\/usa.chinadaily.com.cn\/epaper\/2015-03\/04\/content_19716649.htm\" rel=\"noopener noreferrer\" target=\"_blank\">disait<\/a> en 2015 Liu Shenli, membre du Comit\u00e9 national de la Conf\u00e9rence consultative politique du peuple chinois.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Le tourisme, autre facette visible de l&rsquo;iceberg chinois<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*\u00c9ric Canobbio et Am\u00e9lie Boissi\u00e8re, <em>Atlas des p\u00f4les : r\u00e9gions polaires : questions sur un avenir incertain,<\/em> Collection Atlas Monde, Paris, \u00c9d. Autrement, 2007, p. 65. **En 2014-2015, 3 042 touristes chinois ont visit\u00e9 l&rsquo;Antarctique ; en 2016-2017, plus de 5 280. ***Bauer Cheung et Deng, <a href=\"https:\/\/doi.org\/10.1080\/2154896X.2019.1618552\" rel=\"noopener noreferrer\" target=\"_blank\">\u00ab\u00a0The growth of Chinese tourism to Antarctica : a profile of their connectedness to nature, motivations, and perceptions\u00a0\u00bb<\/a>, in <em>The Polar Journal<\/em>, n\u00b09 vol.1, 2019, p. 197-213.<\/div>Depuis plusieurs ann\u00e9es, des milliers de touristes chinois <a href=\"https:\/\/asialyst.com\/fr\/2019\/10\/12\/chine-maritime-navale-7-7-touristes-chinois-sur-tous-oceans\/\" rel=\"noopener noreferrer\" target=\"_blank\">s&rsquo;aventurent<\/a> aussi par-del\u00e0 les mers, sur la banquise pour d\u00e9couvrir l&rsquo;Antarctique. <em>\u00ab\u00a0Sympt\u00f4me de la contradiction inh\u00e9rente \u00e0 la pr\u00e9servation du continent austral, le tourisme est \u00e0 la fois nourri de l&rsquo;attractivit\u00e9 \u00e9cologique qu&rsquo;exerce le Grand Sud et un \u00e9l\u00e9ment ext\u00e9rieur vecteur de nuisances dans un espace de protection sans cesse renforc\u00e9.\u00a0\u00bb<\/em>* Entre 2014 et 2017, la Chine est pass\u00e9e de la 4\u00e8me \u00e0 la 2\u00e8me place en nombre de ressortissants**. Depuis 2018, un touriste austral sur six est chinois. Mais que motive donc ces ressortissants \u00e0 aller braver ce froid extr\u00eame ?*** <em>\u00ab\u00a0Une base de march\u00e9 plus importante \u00e0 mesure que la classe moyenne chinoise grandit, un attrait de plus en plus marqu\u00e9 pour le tourisme exp\u00e9rientiel plut\u00f4t que le tourisme de masse, et enfin, un int\u00e9r\u00eat marqu\u00e9 pour les enjeux de la d\u00e9t\u00e9rioration de l&rsquo;environnement. [&#8230;] Ce ne sont pas les images montrant la fonte des glaces, diffus\u00e9es par les artistes et les m\u00e9dias, qui poussent les Chinois \u00e0 parcourir l&rsquo;Antarctique ; mais plut\u00f4t l&rsquo;insupportable pollution des grandes m\u00e9tropoles du pays.\u00a0\u00bb<\/em> S&rsquo;offrir le luxe de respirer un air non pollu\u00e9 est le lot des touristes les plus fortun\u00e9s. Ils optent alors pour ce tourisme, qui permet de se distinguer socialement de destinations moins extravagantes. Cela fait partie du parcours r\u00eav\u00e9 des classes moyennes et ais\u00e9es.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe tourisme en Antarctique a \u00e9t\u00e9 brusquement rattrap\u00e9 par l&rsquo;actualit\u00e9 angoissante du SARS-CoV-2. Nicolas est fran\u00e7ais. Il a effectu\u00e9 une croisi\u00e8re de 15 jours en Antarctique entre janvier et f\u00e9vrier derniers, au d\u00e9part d&rsquo;Ushua\u00efa. Navires de croisi\u00e8re \u00e0 moiti\u00e9 ou m\u00eame totalement vides, modification des tarifs et des itin\u00e9raires ; les annulations massives de s\u00e9jours des touristes chinois ont tout chamboul\u00e9, dit-il. Et d&rsquo;expliquer avoir pay\u00e9 son ticket pour le continent blanc, <em>\u00ab\u00a0la plan\u00e8te Hoth dans Star Wars\u00a0\u00bb<\/em>, moins de 5 000 dollars, au lieu de 10 \u00e0 11 000 en temps normal, et ce pour une croisi\u00e8re de 15 jours, au rythme intense de 14 accostages. La fermeture de la province argentine de Terre de Feu, Antarctique et \u00eeles de l&rsquo;Atlantique Sud a fini par avoir raison des croisi\u00e8res. Mais au moment de la discussion, en mars, Nicolas expliquait recevoir encore de nombreux e-mails publicitaires pour des croisi\u00e8res brad\u00e9es tr\u00e8s haut de gamme.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*<a href=\"https:\/\/iaato.org\/home\" rel=\"noopener noreferrer\" target=\"_blank\">International Association of Antarctica Tour Operators<\/a>. Le but de cette association fond\u00e9e par les entreprises du secteur touristique est de promouvoir la pratique s\u00fbre et responsable du tourisme dans la r\u00e9gion. Ce secteur est donc auto-r\u00e9gul\u00e9, dans le cadre du trait\u00e9 sur l&rsquo;Antarctique.<\/div>Reparti avec la parka offerte par le tour-op\u00e9rateur, Nicolas t\u00e9moigne \u00e9galement du cadre tr\u00e8s strict de l&rsquo;activit\u00e9 touristique en Antarctique. <em>\u00ab\u00a0L&rsquo;IAATO* impose des consignes, en termes de respect de l&rsquo;environnement comme de s\u00e9curisation sanitaire,<\/em> confie-t-il. <em>Des bottes sont pr\u00eat\u00e9es pour les sorties, et \u00e0 chaque retour sur le bateau, d\u00e9sinfection et lavage intensif sont ritualis\u00e9s. Afin de se prot\u00e9ger soi-m\u00eame de bact\u00e9ries, et de prot\u00e9ger aussi la faune et la flore locale. Et avant le premier d\u00e9barquement, le staff proc\u00e8de \u00e0 l&rsquo;aspiration de tous les pollens et autres agents exog\u00e8nes sur les v\u00eatements que l\u2019on compte porter lors de la sortie. Il y a une stricte interdiction de ramener quoi que ce soit : plumes, os, etc.\u00a0\u00bb<\/em> Au moins deux croisi\u00e8res, celles des navires <em>Ocean Atlantic<\/em> et <em>Greg Mortimer<\/em>, ont d\u00fb \u00eatre \u00e9court\u00e9es puis d\u00e9rout\u00e9es vers Montevideo en mars, apr\u00e8s des suspicions de coronavirus \u00e0 bord.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>L&rsquo;Antarctique et le programme spatial chinois<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<div class=\"bulle\">\n\t*Cyprien Verseux, <a href=\"https:\/\/www.huffingtonpost.fr\/cyprien-verseux\/notre-mission-dans-la-base-scientifique-la-plus-isolee-du-monde-mars-la-blanche_a_23359419\/\" rel=\"noopener noreferrer\" target=\"_blank\">\u00ab\u00a0Mars la Blanche : notre mission dans la base scientifique la plus isol\u00e9e du monde\u00a0\u00bb<\/a>, <em>The Huffington Post, <\/em>14 f\u00e9vrier 2018.<\/div>De par ses conditions g\u00e9ologiques et climatiques exceptionnelles, l&rsquo;Antarctique permet une observation unique de l&rsquo;espace depuis la Terre : des montagnes de haute altitude, un ciel sans pollution lumineuse ni atmosph\u00e9rique, un air froid et sec facilitant le calibrage des appareils, et la nuit polaire. Tout cela permet des observations prolong\u00e9es du ciel. La France et l&rsquo;Italie disposent ainsi de la base Concordia, o\u00f9 de nombreuses recherches astronomiques sont men\u00e9es.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDe l&rsquo;autre c\u00f4t\u00e9 du t\u00e9lescope, l&rsquo;espace est \u00e9galement un lieu privil\u00e9gi\u00e9 pour observer les p\u00f4les et donc l&rsquo;Antarctique. La Chine l&rsquo;a bien compris ; elle y porte une politique spatiale de premier plan. Par ailleurs, les orbites polaires, effectuant des r\u00e9volutions sur un axe perpendiculaire \u00e0 l&rsquo;\u00e9quateur, se r\u00e9v\u00e8lent tr\u00e8s utiles pour les pr\u00e9visions m\u00e9t\u00e9orologiques, et de nombreux \u00c9tats ont envoy\u00e9 des satellites d\u00e9di\u00e9s sur de telles orbites. Dans cette dynamique, le 28 novembre dernier, le Centre national des satellites m\u00e9t\u00e9orologiques annon\u00e7ait la nouvelle g\u00e9n\u00e9ration de satellites \u00e0 orbite polaire de basse altitude. L&rsquo;agence Xinhua <a href=\"http:\/\/www.xinhuanet.com\/english\/2019-11\/28\/c_138590244.htm\" rel=\"noopener noreferrer\" target=\"_blank\">rapporte ainsi<\/a> que les satellites Fengyun-5 seront \u00e0 m\u00eame de totalement remplacer la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente d&rsquo;ici 2025. Le syst\u00e8me m\u00e9t\u00e9orologique chinois s&rsquo;en trouvera am\u00e9lior\u00e9.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tMais les applications peuvent avoir des implications plus offensives que la recherche scientifique. Les \u00c9tats installent ainsi des syst\u00e8mes permettant de calibrer les r\u00e9seaux de positionnement par satellite tels le GPS am\u00e9ricain, le GLONASS russe ou encore le BeiDou chinois. <em>\u00ab\u00a0le 23 septembre \u00e0 05h10 heure locale, la CASC a proc\u00e9d\u00e9 avec succ\u00e8s au lancement de deux satellites de navigation Beidou-3\u00a0\u00bb<\/em>, <em>\u00ab\u00a0ces deux satellites constituent les 47\u00e8me et 48\u00e8me appareils en orbite\u00a0\u00bb,<\/em> indique la <a href=\"http:\/\/www.spacechina.com\/n25\/n2014789\/n2014804\/c2722977\/content.html\" target=\"_blank\" rel=\"noopener noreferrer\">CASC<\/a>, traduite par le site <a href=\"https:\/\/eastisred.fr\/longue-vue-n8-quinzaine-du-17-septembre-au-29-septembre\/\" rel=\"noopener noreferrer\" target=\"_blank\">EastIsRead<\/a>. Et ces relais peuvent concourir \u00e0 des activit\u00e9s de renseignement, l&rsquo;activit\u00e9 en elle-m\u00eame n&rsquo;\u00e9tant pas une activit\u00e9 militaire offensive formellement interdite par le trait\u00e9 sur l&rsquo;Antarctique. Le site <a href=\"http:\/\/www.eastpendulum.com\/lancement-des-satellites-beidou-m9-et-m10\" rel=\"noopener noreferrer\" target=\"_blank\">East Pendulum<\/a> est revenu sur le lancement des <a href=\"https:\/\/www.nasaspaceflight.com\/2018\/07\/beidou-3m5-and-3m6-launched-by-long-march-3b\/\" rel=\"noopener noreferrer\" target=\"_blank\">Beidou-3 M9 et M10<\/a>.\t<\/div>\n<\/div>\n\n<div class=\"photo-text paragraph\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-480x853.jpg\" class=\"article-image\" title=\"Lancement de la fus\u00e9e Longue Marche 3B (c) emportant des satellites Beidou-3, MEO-5 et 6. (Source : Wikimedia Commons)\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"853\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-480x853.jpg\" class=\"img-responsive\" alt=\"Lancement de la fus\u00e9e Longue Marche 3B (c) emportant des satellites Beidou-3, MEO-5 et 6. (Source : Wikimedia Commons)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-480x853.jpg 480w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-141x250.jpg 141w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-84x150.jpg 84w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-113x200.jpg 113w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-225x400.jpg 225w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine-338x600.jpg 338w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/fusee-chine.jpg 576w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a>\n\t\t<meta itemprop=\"height\" content=\"480\"\/>\n\t\t<meta itemprop=\"width\" content=\"853\"\/>\n\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\"\/>\n\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t  \tLancement de la fus\u00e9e Longue Marche 3B (c) emportant des satellites Beidou-3, MEO-5 et 6. (Source : <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/4\/4e\/%E9%95%BF%E5%BE%81%E4%BA%94%E5%8F%B7%E9%81%A5%E4%BA%8C%E7%81%AB%E7%AE%AD%E8%BD%AC%E5%9C%BA.jpg\/576px-%E9%95%BF%E5%BE%81%E4%BA%94%E5%8F%B7%E9%81%A5%E4%BA%8C%E7%81%AB%E7%AE%AD%E8%BD%AC%E5%9C%BA.jpg\" rel=\"noopener noreferrer\" target=\"_blank\">Wikimedia Commons<\/a>)\t\t<\/figcaption>\n\t<\/figure>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPar ailleurs, la constellation de satellites Ice Pathfinder (BNU) pr\u00e9occupe certains sp\u00e9cialistes. Ces objets, dont le lancement a \u00e9t\u00e9 annonc\u00e9 le 30 ao\u00fbt 2019, sont d\u00e9di\u00e9s \u00e0 la communication et \u00e0 la navigation en milieu polaire. Le BNU-1 <a href=\"https:\/\/www.chinadaily.com.cn\/a\/201909\/12\/WS5d79c52ea310cf3e3556b39b.html\" rel=\"noopener noreferrer\" target=\"_blank\">lanc\u00e9 le 12 septembre dernier<\/a> annonce une constellation de 24 autres qui devraient fournir \u00e0 la Chine une capacit\u00e9 d&rsquo;observation permanente des icebergs d\u00e9rivant et de communication haut d\u00e9bit tant en Antarctique qu&rsquo;en Arctique. Le 13 mars dernier, Xinhua <a href=\"http:\/\/www.xinhuanet.com\/english\/2020-03\/13\/c_138874031.htm\" rel=\"noopener noreferrer\" target=\"_blank\">faisait un bref bilan de ce satellite<\/a> et de sa mission d&rsquo;observation de l&rsquo;Antarctique. <em>\u00ab\u00a0Plus de 1 000 images couvrant la r\u00e9gion polaire\u00a0\u00bb,<\/em> et notamment <em>\u00ab\u00a0deux effondrements massifs de la calotte glaciaire du continent, l&rsquo;un au niveau de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Barri%C3%A8re_d'Amery#\/maplink\/0\" rel=\"noopener noreferrer\" target=\"_blank\">la barri\u00e8re d&rsquo;Amery<\/a> le 25 septembre 2019, l&rsquo;autre au <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Glacier_de_l'%C3%AEle_du_Pin\" rel=\"noopener noreferrer\" target=\"_blank\">glacier de l&rsquo;\u00eele du Pin<\/a>, en f\u00e9vrier.\u00a0\u00bb<\/em> Selon Cheng Xiao, directeur scientifique du projet, embarqu\u00e9 sur le <em>Xuelong 2<\/em> pour l&rsquo;exp\u00e9dition antarctique en cours, <em>\u00ab\u00a0ces donn\u00e9es seront aussi utilis\u00e9es pour \u00e9tudier les changements climatiques, et d\u00e9velopper les routes maritimes arctiques\u00a0\u00bb<\/em> ; ces satellites permettront de r\u00e9duire la d\u00e9pendance chinoise aux technologies \u00e9trang\u00e8res. Le but affich\u00e9 est aussi l&rsquo;identification automatique de vaisseaux navigant dans les r\u00e9gions polaires. Des donn\u00e9es qui serviront au projet chinois de \u00ab\u00a0Route de la Soie polaire\u00a0\u00bb.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Voir cette vid\u00e9o de mars 2018 montrant un lancement de satellites jumeaux rejoignant la constellation de BeiDou 3 :<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/WAtrJxqCif8\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe ton du m\u00e9dia <a href=\"https:\/\/thediplomat.com\/2019\/01\/what-chinas-antarctic-behavior-tells-us-about-the-future-of-space\/\" rel=\"noopener noreferrer\" target=\"_blank\"><em>The Diplomat<\/em><\/a> est nettement plus alarmiste, pointant les diff\u00e9rentes implications strat\u00e9giques, notamment pour les technologies anti-missiles, qui pourraient <em>\u00ab\u00a0rendre le pointage de bases en Antarctique bien r\u00e9el alors m\u00eame que le conflit ne se trouverait pas sur le continent\u00a0\u00bb<\/em>. La comparaison que font les deux chercheurs entre la rh\u00e9torique gouvernementale chinoise sur sa strat\u00e9gie spatiale et sa politique en Antarctique est int\u00e9ressante, mais semble quelque peu exag\u00e9r\u00e9e sur la base des faits observables aujourd&rsquo;hui. Ce qui explique l&rsquo;inqui\u00e9tude des observateurs vient de l&rsquo;extrapolation du comportement de P\u00e9kin dans d&rsquo;autres parties du monde, telles que les mers de Chine. De l&rsquo;habitude du flou diplomatique aussi. Comment ne pas penser aux p\u00eacheurs sous pavillon chinois, secr\u00e8tement subventionn\u00e9s par des agences gouvernementales ? Mais l&rsquo;incrimination directe du gouvernement est p\u00e9rilleuse pour les autre parties au trait\u00e9.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCependant, la Chine est aujourd&rsquo;hui partie consultative adh\u00e9rente du trait\u00e9 sur l&rsquo;Antarctique. Cela signifie qu&rsquo;\u00e0 ce titre, elle dispose d&rsquo;un droit de vote aux r\u00e9unions des parties consultatives (les r\u00e9unions consultatives au trait\u00e9 sur l&rsquo;Antarctique, RCTA), par sa ratification, et donc d&rsquo;un engagement juridiquement contraignant pour l&rsquo;\u00c9tat chinois.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Une pr\u00e9sence cruciale pour investir l&rsquo;ar\u00e8ne des grandes puissances<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t\u00c0 quel jeu s&rsquo;adonne la Chine en Antarctique, et quelles cons\u00e9quences pour les autres puissances ? L&rsquo;aspect g\u00e9opolitique et strat\u00e9gique est assur\u00e9ment le plus sujet aux fantasmes et extrapolations. La mont\u00e9e en puissance chinoise se double en effet d&rsquo;une opacit\u00e9 du processus d\u00e9cisionnel. Dans un contexte qui semble d&rsquo;expansion de port\u00e9e mondiale, cela nourrit les sp\u00e9culations des analystes et d\u00e9cideurs. Aux \u00c9tats-Unis, en Nouvelle-Z\u00e9lande et en Australie, on voit fleurir des avertissements quant aux activit\u00e9s chinoises en Antarctique, qui pr\u00e9figureraient un changement des r\u00e8gles du jeu d&rsquo;ici 2050. Force est de constater que le gouvernement chinois suit bel et bien une feuille de route. Ainsi, les moindres actions de P\u00e9kin sont tr\u00e8s vite lues comme des petits pas afin d&rsquo;atteindre ce but, et donc d\u00e9classer les autres, Am\u00e9ricains en t\u00eate.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPour <em>The Diplomat<\/em>, Rebecca Pincus, de l&rsquo;\u00c9cole navale de guerre des \u00c9tats-Unis, <a href=\"https:\/\/thediplomat.com\/2018\/07\/chinas-polar-strategy-an-emerging-gray-zone\/\" rel=\"noopener noreferrer\" target=\"_blank\">d\u00e9crit toutes les zones grises<\/a> dans lesquelles la Chine semble s&rsquo;engouffrer : <em>\u00ab\u00a0\u00c0 l&rsquo;horizon 2050, les strat\u00e8ges am\u00e9ricains pourraient se confronter \u00e0 une situation radicalement diff\u00e9rente, avec un Arctique se lib\u00e9rant des glaces en \u00e9t\u00e9 et l&rsquo;Antarctique potentiellement lieu de grande contestation &#8211; et la Chine devenant une puissance dominante dans les deux.\u00a0\u00bb<\/em> Les r\u00e9gions antarctiques et arctiques sont l\u00e0 per\u00e7ues comme des espaces extra-territoriaux, qui se connectent tant \u00e0 la haute mer qu&rsquo;\u00e0 l&rsquo;espace, et que la Chine peut investir pour avoir des leviers de pression, constituant ce que Rebecca Pincus appelle des <em>\u00ab\u00a0campagnes de zones grises\u00a0\u00bb<\/em> susceptibles de rebattre les cartes de la g\u00e9opolitique actuelle. La perception de ces espaces, dits communs tels que la haute mer, l&rsquo;Antarctique, ainsi qu&rsquo;une certaine fraction de l&rsquo;Arctique ou encore l&rsquo;espace extra-atmosph\u00e9rique, auxquels tous les \u00c9tats ont acc\u00e8s mais qui n&rsquo;appartiennent \u00e0 personne, fait \u00e9merger un nouveau terrain de comp\u00e9tition internationale. C&rsquo;est ce que Fr\u00e9d\u00e9ric Ramel examine, <a href=\"https:\/\/www.irsem.fr\/data\/files\/irsem\/documents\/document\/file\/1167\/Etude%20IRSEM%2030-%20Espaces%20communs.pdf\" rel=\"noopener noreferrer\" target=\"_blank\">rappelant que<\/a> <em>\u00ab\u00a0pr\u00e9server leur acc\u00e8s est une condition fondamentale tant pour la projection des forces arm\u00e9es que pour le fonctionnement de l&rsquo;\u00e9conomie mondialis\u00e9e.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL&rsquo;Australie aussi voit d\u2019un \u0153il m\u00e9fiant la suractivit\u00e9 chinoise en Antarctique. Aujourd&rsquo;hui, Canberra fait partie des 50 parties du trait\u00e9 sur l&rsquo;Antarctique. Parmi ces pays, <em>\u00ab\u00a0sept sont dits \u00ab\u00a0possessionn\u00e9s\u00a0\u00bb, c&rsquo;est-\u00e0-dire qu&rsquo;ils revendiquent la possession d&rsquo;une partie du continent (la Terre Ad\u00e9lie pour la France par exemple)\u00a0\u00bb,<\/em> explique <a href=\"https:\/\/www.institut-polaire.fr\/ipev\/informations-polaires\/en-antarctique\/\" rel=\"noopener noreferrer\" target=\"_blank\">l&rsquo;Institut polaire fran\u00e7ais Paul-\u00c9mile Victor<\/a>. L&rsquo;article IV du trait\u00e9 fait provisoirement taire les revendications territoriales des signataires sur l&rsquo;Antarctique. Mais le texte n&rsquo;induit pas la renonciation d&rsquo;un \u00c9tat \u00e0 ses droits ou revendications de souverainet\u00e9 sur le continent.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<blockquote>\n\t\t<em>\u00ab\u00a01. Aucune disposition du pr\u00e9sent trait\u00e9 ne doit \u00eatre interpr\u00e9t\u00e9e comme : (a) une renonciation par une partie contractante \u00e0 des droits ou revendications de souverainet\u00e9 territoriale sur l&rsquo;Antarctique qu&rsquo;elle a d\u00e9j\u00e0 fait valoir ; [\u2026] 2. Aucun acte ou activit\u00e9 se d\u00e9roulant pendant que le pr\u00e9sent trait\u00e9 est en vigueur ne constitue une base pour affirmer, appuyer ou nier une revendication de souverainet\u00e9 territoriale en Antarctique ou pour cr\u00e9er des droits de souverainet\u00e9 en Antarctique. Aucune nouvelle revendication, ou \u00e9largissement d&rsquo;une revendication existante de souverainet\u00e9 territoriale en Antarctique, ne peut \u00eatre revendiqu\u00e9e tant que le pr\u00e9sent trait\u00e9 est en vigueur.\u00a0\u00bb<\/em>\t<\/blockquote>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tEt sur ses propres territoires revendiqu\u00e9s, l&rsquo;Australie voit donc fleurir plusieurs sites de recherche chinois. Anne-Marie Brady, universitaire mondialement reconnue pour ses travaux sur les politiques polaires chinoises, donne le ton dans son <a href=\"https:\/\/s3-ap-southeast-2.amazonaws.com\/ad-aspi\/2017-08\/SR109%20Chinas%20expanding%20interests%20in%20Antarctica.pdf\" rel=\"noopener noreferrer\" target=\"_blank\">rapport de l&rsquo;Australian Strategic Policy Institute d&rsquo;ao\u00fbt 2017<\/a> : <em>\u00ab\u00a0La Chine a conduit des activit\u00e9s militaires non d\u00e9clar\u00e9es en Antarctique, construit les conditions n\u00e9cessaires \u00e0 l&rsquo;\u00e9mission de revendications territoriales et s&rsquo;engage dans la prospection min\u00e9rale.\u00a0\u00bb<\/em> Ce qui n&rsquo;a pu se produire que parce que les inspections normalement pr\u00e9vues par le trait\u00e9 sur l&rsquo;Antarctique n&rsquo;ont pas \u00e9t\u00e9 mises en \u0153uvre par les autres parties du trait\u00e9, Australie en t\u00eate en tant qu&rsquo;\u00c9tat <em>\u00ab\u00a0possessionn\u00e9\u00a0\u00bb.<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCependant, le syst\u00e8me du trait\u00e9 sur l&rsquo;Antarctique pourrait bien rester tel quel, \u00e0 cause ou gr\u00e2ce au mode de prise de d\u00e9cision, qui n\u00e9cessite le consensus des \u00c9tats parties. Or, pour beaucoup, il y a tout int\u00e9r\u00eat \u00e0 maintenir la situation actuelle. Pour autant, il est ind\u00e9niable que la Chine se positionne activement en Antarctique, faisant craindre \u00e0 des d\u00e9cideurs politiques et strat\u00e8ges occidentaux la pr\u00e9paration du terrain \u00e0 un changement de donne. Les cartes restent \u00e0 jouer, bien que les r\u00e8gles du jeu soient strictes et historiquement tr\u00e8s suivies.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Joaquim Gaignard<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"large large\" style=\"background-color:#961157;\">\n\t<div class=\"container\">\n\t\t<div class=\"sub-article\">\n\t\t\t<h2>Pour approfondir<\/h2>\n\t\t\t<p>&#8211; En anglais, le <a href=\"https:\/\/www.aspi.org.au\/\" rel=\"noopener noreferrer\" target=\"_blank\">site internet<\/a> du think-tank Australian Strategic Policy Institute (ASPI), qui garde un \u0153il extr\u00eamement vigilant et avis\u00e9 sur les activit\u00e9s chinoises, notamment en Antarctique.<\/p>\n<p>&#8211; En anglais, et de fa\u00e7on g\u00e9n\u00e9rale, le <a href=\"https:\/\/www.canterbury.ac.nz\/science\/schools-and-departments\/antarctica\/gateway-research\/antarctic-and-southern-ocean-governance-programme\/accordion\/chinas-polar-strategy-and-global-governance\/researcher\/anne-marie-brady.html\" rel=\"noopener noreferrer\" target=\"_blank\">travail universitaire<\/a> de la professeure Anne-Marie Brady, de l&rsquo;universit\u00e9 de Canterbury, en Nouvelle-Z\u00e9lande.<\/p>\n<p>&#8211; Le <a href=\"https:\/\/www.ats.aq\/\" rel=\"noopener noreferrer\" target=\"_blank\">site internet<\/a> du secr\u00e9tariat du trait\u00e9 sur l&rsquo;Antarctique.<\/p>\n<p>&#8211; Ce <a href=\"https:\/\/chinadialogueocean.net\/12175-podcast-chinas-interest-in-antarctica\/\" rel=\"noopener noreferrer\" target=\"_blank\">podcast<\/a> passionnant du China Dialogue Ocean (en anglais).<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/aerospatiale\/\" rel=\"tag\">A\u00e9rospatiale<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/antarctique\/\" rel=\"tag\">Antarctique<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/arctique\/\" rel=\"tag\">Arctique<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/argentine\/\" rel=\"tag\">Argentine<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/australie\/\" rel=\"tag\">Australie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/chine\/\" rel=\"tag\">Chine<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/coronavirus\/\" rel=\"tag\">coronavirus<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/diplomatie\/\" rel=\"tag\">Diplomatie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/epidemie\/\" rel=\"tag\">\u00e9pid\u00e9mie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/pandemie\/\" rel=\"tag\">pand\u00e9mie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/peche\/\" rel=\"tag\">p\u00eache<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/sciences\/\" rel=\"tag\">sciences<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/superpuissance-maritime\/\" rel=\"tag\">superpuissance maritime<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/tourisme\/\" rel=\"tag\">tourisme<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F05%2F18%2Fchine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=La+Chine+et+les+r%C3%A9gions+polaires+%283%2F7%29+%3A+en+Antarctique%2C+P%C3%A9kin+affirme+sa+puissance+australe&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F05%2F18%2Fchine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F05%2F18%2Fchine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire%2F&title=La+Chine+et+les+r%C3%A9gions+polaires+%283%2F7%29+%3A+en+Antarctique%2C+P%C3%A9kin+affirme+sa+puissance+australe\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F05%2F18%2Fchine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2020%2F05%2FAntarctic_Great_Wall_Station-250x113.jpg&description=La+Chine+et+les+r%C3%A9gions+polaires+%283%2F7%29+%3A+en+Antarctique%2C+P%C3%A9kin+affirme+sa+puissance+australe\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2019\/10\/portrait-joaquim-gaignard.jpg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/joaquimgaignard\/\">\n\t\t\t\t\t\t\tJoaquim Gaignard\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tLicenci\u00e9 de Paris 1 Panth\u00e9on-Sorbonne en histoire, Joaquim Gaignard est \u00e9tudiant en Master de Relations Internationales \u00e0 l'\u00e9cole doctorale de Sciences Po. Ses th\u00e8mes g\u00e9opolitiques de pr\u00e9dilection : l'Asie, la Chine, les r\u00e9gions polaires, les relations diplomatiques et le transnational.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2020\/03\/21\/chine-regions-polaires-1-7-quand-boussole-indique-nord-empire-milieu\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"376\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-600x376.jpg\" class=\"img-responsive wp-post-image\" alt=\"Les deux brises-glaces de la Chine dans le cercle arctique : le Xuelong (Dragon des neiges) et le Xuelong 2. Dessin : Baptiste Condominas. (Copyright : Baptiste Condominas pour Asialyst)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-600x376.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-250x157.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-1024x641.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-150x94.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-768x481.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-1536x962.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-2048x1283.jpg 2048w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-200x125.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-300x188.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-900x564.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-1280x802.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-1600x1002.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/03\/Xue-long-1-et-2-680x426.jpg 680w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-category-\">Histoire, Politique<\/span><h4>La Chine et les r\u00e9gions polaires (1\/7) : quand la boussole indique le Nord \u00e0 l'empire du Milieu<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2020\/05\/01\/chine-regions-polaires-2-7-comment-chine-pekin-trace-route-antarctique-argentine-chili\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"223\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-600x223.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-600x223.jpeg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-250x93.jpeg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-1024x380.jpeg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-150x56.jpeg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-768x285.jpeg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-1536x571.jpeg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-200x74.jpeg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-300x111.jpeg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-900x334.jpeg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-1280x476.jpeg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-1600x595.jpeg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1-680x253.jpeg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/04\/cba1a788-69bd-11e9-a2c3-042d2f2c8874_image_hires_004338-1.jpeg 1892w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Soci\u00e9t\u00e9<\/span><h4>La Chine et les r\u00e9gions polaires (2\/7) : comment P\u00e9kin trace sa route en Antarctique via l'Argentine et le Chili<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs&#8230; La Chine s&rsquo;affirme en Antarctique. L&rsquo;enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !<\/p>\n","protected":false},"author":1631,"featured_media":48480,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[301,1826,1414,1871,142,22,1848,362,1301,1868,574,1097,1873,212],"class_list":["post-48308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-aerospatiale","tag-antarctique","tag-arctique","tag-argentine","tag-australie","tag-chine","tag-coronavirus","tag-diplomatie","tag-epidemie","tag-pandemie","tag-peche","tag-sciences","tag-superpuissance-maritime","tag-tourisme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe - Asialyst<\/title>\n<meta name=\"description\" content=\"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s&#039;affirme en Antarctique. L&#039;enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin s&#039;affirme en grande puissance polaire\" \/>\n<meta property=\"og:description\" content=\"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s&#039;affirme en Antarctique. L&#039;enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T09:26:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-18T21:53:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"912\" \/>\n\t<meta property=\"og:image:height\" content=\"413\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaquim Gaignard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin s&#039;affirme en grande puissance polaire\" \/>\n<meta name=\"twitter:description\" content=\"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s&#039;affirme en Antarctique. L&#039;enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaquim Gaignard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/\"},\"author\":{\"name\":\"Joaquim Gaignard\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/633db7195b8a5646f8aee995b3f1b7f4\"},\"headline\":\"La Chine et les r\u00e9gions polaires (3\\\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe\",\"datePublished\":\"2020-05-18T09:26:55+00:00\",\"dateModified\":\"2020-05-18T21:53:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/\"},\"wordCount\":4803,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Antarctic_Great_Wall_Station.jpg\",\"keywords\":[\"A\u00e9rospatiale\",\"Antarctique\",\"Arctique\",\"Argentine\",\"Australie\",\"Chine\",\"coronavirus\",\"Diplomatie\",\"\u00e9pid\u00e9mie\",\"pand\u00e9mie\",\"p\u00eache\",\"sciences\",\"superpuissance maritime\",\"tourisme\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/\",\"name\":\"La Chine et les r\u00e9gions polaires (3\\\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Antarctic_Great_Wall_Station.jpg\",\"datePublished\":\"2020-05-18T09:26:55+00:00\",\"dateModified\":\"2020-05-18T21:53:57+00:00\",\"description\":\"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s'affirme en Antarctique. L'enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Antarctic_Great_Wall_Station.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Antarctic_Great_Wall_Station.jpg\",\"width\":912,\"height\":413,\"caption\":\"La station chinoise Grande Muraille situ\u00e9e sur l\u2019\u00eele du Roi-George. (Source : Wikimedia Commons)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/05\\\/18\\\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Chine et les r\u00e9gions polaires (3\\\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/633db7195b8a5646f8aee995b3f1b7f4\",\"name\":\"Joaquim Gaignard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/portrait-joaquim-gaignard-115x150.jpg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/portrait-joaquim-gaignard-115x150.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/portrait-joaquim-gaignard-115x150.jpg\",\"caption\":\"Joaquim Gaignard\"},\"description\":\"Licenci\u00e9 de Paris 1 Panth\u00e9on-Sorbonne en histoire, Joaquim Gaignard est \u00e9tudiant en Master de Relations Internationales \u00e0 l'\u00e9cole doctorale de Sciences Po. Ses th\u00e8mes g\u00e9opolitiques de pr\u00e9dilection : l'Asie, la Chine, les r\u00e9gions polaires, les relations diplomatiques et le transnational.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/joaquimgaignard\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe - Asialyst","description":"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s'affirme en Antarctique. L'enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/","og_locale":"fr_FR","og_type":"article","og_title":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin s'affirme en grande puissance polaire","og_description":"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s'affirme en Antarctique. L'enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !","og_url":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2020-05-18T09:26:55+00:00","article_modified_time":"2020-05-18T21:53:57+00:00","og_image":[{"width":912,"height":413,"url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg","type":"image\/jpeg"}],"author":"Joaquim Gaignard","twitter_card":"summary_large_image","twitter_title":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin s'affirme en grande puissance polaire","twitter_description":"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s'affirme en Antarctique. L'enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !","twitter_image":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg","twitter_misc":{"\u00c9crit par":"Joaquim Gaignard","Dur\u00e9e de lecture estim\u00e9e":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/"},"author":{"name":"Joaquim Gaignard","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/633db7195b8a5646f8aee995b3f1b7f4"},"headline":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe","datePublished":"2020-05-18T09:26:55+00:00","dateModified":"2020-05-18T21:53:57+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/"},"wordCount":4803,"commentCount":0,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg","keywords":["A\u00e9rospatiale","Antarctique","Arctique","Argentine","Australie","Chine","coronavirus","Diplomatie","\u00e9pid\u00e9mie","pand\u00e9mie","p\u00eache","sciences","superpuissance maritime","tourisme"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/","url":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/","name":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg","datePublished":"2020-05-18T09:26:55+00:00","dateModified":"2020-05-18T21:53:57+00:00","description":"Recherche scientifique, p\u00eache du krill, tourisme de luxe, programme spatial, acc\u00e8s aux espaces communs... La Chine s'affirme en Antarctique. L'enjeu : faire la d\u00e9monstration de sa stature de grande puissance pr\u00e9sente partout sur Terre, et au-del\u00e0 !","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/05\/Antarctic_Great_Wall_Station.jpg","width":912,"height":413,"caption":"La station chinoise Grande Muraille situ\u00e9e sur l\u2019\u00eele du Roi-George. (Source : Wikimedia Commons)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2020\/05\/18\/chine-regions-polaires-3-7-antarctique-pekin-affirme-grande-puissance-polaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La Chine et les r\u00e9gions polaires (3\/7) : en Antarctique, P\u00e9kin affirme sa puissance australe"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/633db7195b8a5646f8aee995b3f1b7f4","name":"Joaquim Gaignard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2019\/10\/portrait-joaquim-gaignard-115x150.jpg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2019\/10\/portrait-joaquim-gaignard-115x150.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2019\/10\/portrait-joaquim-gaignard-115x150.jpg","caption":"Joaquim Gaignard"},"description":"Licenci\u00e9 de Paris 1 Panth\u00e9on-Sorbonne en histoire, Joaquim Gaignard est \u00e9tudiant en Master de Relations Internationales \u00e0 l'\u00e9cole doctorale de Sciences Po. Ses th\u00e8mes g\u00e9opolitiques de pr\u00e9dilection : l'Asie, la Chine, les r\u00e9gions polaires, les relations diplomatiques et le transnational.","url":"https:\/\/asialyst.com\/fr\/auteur\/joaquimgaignard\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/48308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/1631"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=48308"}],"version-history":[{"count":36,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/48308\/revisions"}],"predecessor-version":[{"id":48502,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/48308\/revisions\/48502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/48480"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=48308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=48308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=48308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}