﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":46450,"date":"2020-02-08T01:15:31","date_gmt":"2020-02-08T00:15:31","guid":{"rendered":"https:\/\/asialyst.com\/fr\/2020\/02\/04\/coronavirus-chine-enchainement-erreurs-gestion-crise-wuhan-epidemie-copy\/"},"modified":"2020-02-09T02:27:20","modified_gmt":"2020-02-09T01:27:20","slug":"coronavirus-chine-france-loi-rumeur-contestation-racisme","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/","title":{"rendered":"Coronavirus : la loi de la rumeur, de la contestation au racisme"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2020-02-08T01:15:31Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 08 F\u00e9vrier 2020<br \/>\n\t\tMis \u00e0 jour 09 F\u00e9vrier 2020\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2020-02-09T02:27:20Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">Analyse<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">Coronavirus : la loi de la rumeur, de la contestation au racisme<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/tamaralui\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Tamara Lui            <\/span>\n            <img data-del=\"avatar\" alt=\"Tamara Lui\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/tamara.jpg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\" class=\"article-image\" title=\"Des passagers portent un masque pour se prot\u00e9ger du coronavirus \u00e0 l'arriv\u00e9e d'un vol en provenance d'Asie \u00e0 l'a\u00e9roport international de Los Angeles, le 29 janvier 2020. (Source : USA Today)\"><img loading=\"lazy\" decoding=\"async\" width=\"2547\" height=\"966\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\" class=\"img-responsive\" alt=\"Des passagers portent un masque pour se prot\u00e9ger du coronavirus \u00e0 l&#039;arriv\u00e9e d&#039;un vol en provenance d&#039;Asie \u00e0 l&#039;a\u00e9roport international de Los Angeles, le 29 janvier 2020. (Source : USA Today)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg 2547w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-250x95.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-1024x388.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-150x57.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-768x291.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-1536x583.jpg 1536w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-2048x777.jpg 2048w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-200x76.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-300x114.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-600x228.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-900x341.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-1280x485.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-1600x607.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845-680x258.jpg 680w\" sizes=\"auto, (max-width: 2547px) 100vw, 2547px\" \/><\/a>\n      <meta itemprop=\"height\" content=\"2547\"\/>\n      <meta itemprop=\"width\" content=\"966\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tDes passagers portent un masque pour se prot\u00e9ger du coronavirus \u00e0 l'arriv\u00e9e d'un vol en provenance d'Asie \u00e0 l'a\u00e9roport international de Los Angeles, le 29 janvier 2020. (Source : <a href=\"https:\/\/eu.usatoday.com\/story\/news\/nation\/2020\/01\/31\/coronavirus-chinese-xenophobia-racism-misinformation\/2860391001\/\" rel=\"noopener noreferrer\" target=\"_blank\">USA Today<\/a>)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tLe coronavirus est-il une nouvelle \u00ab\u00a0pand\u00e9mie de la peur\u00a0\u00bb ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l&rsquo;information officielle dans les villes en quarantaine. \u00c0 l&rsquo;\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tUn des points communs entre l&rsquo;\u00e9pid\u00e9mie et la rumeur, c&rsquo;est qu&rsquo;elles sont toutes les deux virales. Autrefois, elles \u00e9taient transmises essentiellement par le contact humain : l&rsquo;\u00e9pid\u00e9mie par le contact physique, la rumeur de bouche \u00e0 oreille. De nos jours, le mode de transmission d&rsquo;une \u00e9pid\u00e9mie est inchang\u00e9, mais la propagation d&rsquo;une rumeur peut atteindre l&rsquo;autre bout du globe en un seul clic gr\u00e2ce aux r\u00e9seaux sociaux : la dangerosit\u00e9 d&rsquo;une rumeur devient d&rsquo;autant plus difficile \u00e0 \u00e9valuer.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL&rsquo;actualit\u00e9 dans le monde est domin\u00e9e par l&rsquo;\u00e9volution et la propagation du coronavirus de Wuhan (2019-nCoV). Avons-nous d\u00e9j\u00e0 pos\u00e9 cette question : pourquoi ce virus, qui est \u00e0 peine plus grave que la grippe saisonni\u00e8re selon les experts, suscite en nous autant d&rsquo;inqui\u00e9tude, voire de panique chez certains ? Est-ce encore une fois une <a href=\"https:\/\/www.agoravox.fr\/actualites\/international\/article\/la-chine-des-masques-le-221070\" rel=\"noopener noreferrer\" target=\"_blank\">pand\u00e9mie de la peur<\/a> ? Ou bien cette peur grandissante, justifi\u00e9e par l&rsquo;\u00e9volution de l&rsquo;\u00e9pid\u00e9mie \u00e0 partir de Wuhan, son \u00e9picentre, est-elle aliment\u00e9e par le r\u00e9gime politique qui, non d\u00e9mocratique, en accentue les composantes anxiog\u00e8nes ?\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL&rsquo;\u00e9pid\u00e9mie et la rumeur sont souvent concomitantes, et la confusion joue toujours un r\u00f4le dominant dans les deux cas. Avant la confirmation d&rsquo;une \u00e9pid\u00e9mie par les autorit\u00e9s sanitaires, parfois l&rsquo;attente peut \u00eatre longue ; la rumeur, comme un bruit confus, est le seul rep\u00e8re que nous saisissons sans h\u00e9sitation. Dans le langage courant chinois, la rumeur &#8211; \u8c23\u8a00<em>(yaoyan) &#8211; <\/em>signifie une d\u00e9sinformation propag\u00e9e avec une intention de troubler l&rsquo;ordre \u00e9tabli. Ainsi le gouvernement de P\u00e9kin met-il en garde son peuple contre toutes sortes d&rsquo;informations non confirm\u00e9es par les grands m\u00e9dias chinois, ou bien non diffus\u00e9es par les autorit\u00e9s locales ou centrales. Le slogan <em>\u00ab\u00a0Ne pas croire \u00e0 la rumeur, ni la propager\u00a0\u00bb <\/em>(\u4e0d\u4fe1\u8c23\uff0c\u4e0d\u4f20\u8c23 <em>&#8211; buxinyao, buchuanyao) <\/em>est bien ancr\u00e9 dans l&rsquo;esprit de la population.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tEn effet, dans un pays o\u00f9 le lait infantile est frelat\u00e9, les aliments quotidiens fabriqu\u00e9s avec des produits toxiques et les vaccins contrefaits, quand le capital de confiance social s&rsquo;effondre, alors une seule chose \u00e0 laquelle le peuple croit avec une conviction in\u00e9branlable, c&rsquo;est bien l&rsquo;information officielle, o\u00f9 tout ce que disent le <em>Quotidien du Peuple <\/em>et la cha\u00eene CCTV est vrai.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>La rumeur, acte de contestation<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tAujourd&rsquo;hui, si nous pouvons facilement remplacer le mot \u00ab\u00a0rumeur\u00a0\u00bb par \u00ab\u00a0fake news\u00a0\u00bb, malgr\u00e9 les nuances \u00e9pist\u00e9mologiques, le mot \u00ab\u00a0rumeur\u00a0\u00bb et son usage sont en revanche tr\u00e8s difficiles \u00e0 d\u00e9finir en sociologie. En Chine, il est assez facile de constater qu&rsquo;une information, dans la plus grande confusion, peut \u00eatre jug\u00e9e comme une rumeur ou une fake news, ce qui constitue une d\u00e9formation et devient une d\u00e9sinformation. De ce fait, le gouvernement chinois d\u00e9cr\u00e8te que l&rsquo;inventeur d&rsquo;une rumeur comme son diffuseur risquent d&rsquo;\u00eatre punis par la loi. Un exemple tout r\u00e9cent illustre bien l&rsquo;application de cette politique de contr\u00f4le.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tRemontons la chronologie de cette \u00e9pid\u00e9mie de coronavirus :<br \/>\n<strong>\u2022 Le 8 d\u00e9cembre 2019,<\/strong> le tout premier cas confirme une pneumonie aigu\u00eb provoqu\u00e9e par une infection inconnue \u00e0 Wuhan.<br \/>\n<strong>\u2022 Le 22 d\u00e9cembre,<\/strong> la municipalit\u00e9 organise une grande f\u00eate populaire au centre-ville avec plus de vingt mille participants.<br \/>\n<strong>\u2022 Le 31 d\u00e9cembre,<\/strong> les autorit\u00e9s sanitaires de la capitale du Hubei confirment pour la premi\u00e8re fois 27 cas d&rsquo;infection av\u00e9r\u00e9e qui ont eu un contact direct avec le march\u00e9 de fruits de mer de Huanan, dont 7 cas s\u00e9v\u00e8res. Selon les analyses biologiques, c&rsquo;est une pneumonie virale.<br \/>\n<strong>\u2022 Le 1er janvier 2020,<\/strong> le march\u00e9 est ferm\u00e9 sur ordre municipal.<br \/>\n<strong>\u2022 Dans la m\u00eame journ\u00e9e,<\/strong> sur la plateforme de microblogs Weibo, le compte officiel de la police de Wuhan annonce l&rsquo;arrestation de 8 personnes soup\u00e7onn\u00e9es d&rsquo;avoir diffus\u00e9 des fausses informations. Ces personnes, dont on conna\u00eet l&rsquo;identit\u00e9 aujourd&rsquo;hui, ont \u00e9crit dans les diff\u00e9rents groupes de discussion r\u00e9serv\u00e9s aux chercheurs et aux m\u00e9decins : <em>\u00ab\u00a0L&rsquo;h\u00f4pital X a re\u00e7u une famille de 3 personnes qui ont les m\u00eames sympt\u00f4mes que ceux du SRAS\u00a0\u00bb ; \u00ab\u00a07 patients manifestent une infection semblable \u00e0 celle du SRAS de 2003 dans l\u2019H\u00f4pital Y\u00a0\u00bb ; \u00ab\u00a0une autre \u00e9pid\u00e9mie de SRAS probable\u00a0\u00bb.<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCes 8 personnes sont toutes des m\u00e9decins de formation. Certains exercent dans le service des maladies infectieuses \u00e0 l&rsquo;h\u00f4pital de Wuhan. Ces messages alarmants pourraient \u00eatre interpr\u00e9t\u00e9s comme la premi\u00e8re analyse de ce nouveau virus dont \u00e0 l&rsquo;\u00e9poque nul n&rsquo;aurait os\u00e9 imaginer une telle propagation : au moins 37 198 personnes contamin\u00e9es et 811 morts pour la seule Chine ce 8 f\u00e9vrier &#8211; contre 348 morts et 5 900 cas de SRAS dans le pays en 2002-2003.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPourtant, la police de Wuhan d\u00e9nonce ces 8 m\u00e9decins et leurs <em>\u00ab\u00a0informations calomnieuses diffus\u00e9es sur les r\u00e9seaux\u00a0\u00bb <\/em>qui <em>\u00ab\u00a0peuvent cr\u00e9er un environnement malsain. Apr\u00e8s une investigation, ces 8 personnes qualifi\u00e9es de hors-la-loi ont \u00e9t\u00e9 convoqu\u00e9es et vont \u00eatre trait\u00e9es selon la loi.\u00a0\u00bb <\/em> Une mesure annonc\u00e9e \u00e0 toute la Chine le soir du 1er janvier dans le <a href=\"https:\/\/chinadigitaltimes.net\/chinese\/2020\/01\/cctv138%E5%90%8D%E6%95%A3%E5%B8%83%E8%B0%A3%E8%A8%80%E8%80%85%E8%A2%AB%E6%9F%A5%E5%A4%84\/\" rel=\"noopener noreferrer\" target=\"_blank\">journal t\u00e9l\u00e9vis\u00e9 de CCTV13<\/a>. Un mois plus tard, le 28 janvier, la m\u00eame police de Wuhan publie un autre texte sur son compte, pr\u00e9cisant que ces 8 personnes ont \u00e9t\u00e9 rel\u00e2ch\u00e9es en tenant compte de leur l\u00e9g\u00e8re erreur. Pas d&rsquo;excuses officielles.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe jour-m\u00eame, la haute cour du Tribunal du Peuple publie un article p\u00e9dagogique et explicatif sur les r\u00e9seaux sociaux. Le texte se termine ainsi : <em>\u00ab\u00a0En v\u00e9rit\u00e9, cette \u00e9pid\u00e9mie n&rsquo;est pas tout \u00e0 fait la m\u00eame que celle du SRAS, mais elles sont similaires, donc, on peut conclure que le contenu de leur discussion [celle de ces 8 personne interpell\u00e9es, NDLR] n&rsquo;est pas sans fondement. Si nous avions pris au s\u00e9rieux ce qu&rsquo;ils ont dit d\u00e8s le d\u00e9but, et si nous avions su prendre les m\u00eames pr\u00e9cautions que celles du SRAS &#8211; se prot\u00e9ger, d\u00e9sinfecter tous les lieux et s&rsquo;\u00e9loigner du march\u00e9 contamin\u00e9 -, cela aurait \u00e9t\u00e9 une chance pour nous tous aujourd&rsquo;hui dans cette lutte acharn\u00e9e contre cette \u00e9pid\u00e9mie. En effet, d\u00e8s lors que l&rsquo;information reposait sur un certain fondement, que l&rsquo;intention subjective de la diffusion n&rsquo;\u00e9tait pas de nuire, et qu&rsquo;objectivement, elle ne causait aucun d\u00e9g\u00e2t grave sur le moment, nous aurions d\u00fb opter pour une attitude plus tol\u00e9rante vis-\u00e0-vis de ce genre d&rsquo;information dite fallacieuse.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tVoil\u00e0 une mani\u00e8re fort diplomatique de r\u00e9gler cette mauvaise gestion de la rumeur. En donnant raison \u00e0 ces 8 m\u00e9decins faussement accus\u00e9s, le tribunal donne aussi une le\u00e7on sur la capacit\u00e9 d&rsquo;analyse et de hi\u00e9rarchisation des informations non v\u00e9rifi\u00e9es durant les moments difficiles. Depuis, le d\u00e9nouement heureux de ces \u00ab\u00a0fauteurs de trouble\u00a0\u00bb a \u00e9t\u00e9 largement relay\u00e9 sur les r\u00e9seaux sociaux. Ils sont devenus des h\u00e9ros, des lanceurs d&rsquo;alerte en quelque sorte dans un monde o\u00f9 toutes les informations sont contr\u00f4l\u00e9es et verrouill\u00e9es. Leur acte \u00ab\u00a0h\u00e9ro\u00efque\u00a0\u00bb, selon l&rsquo;hommage de nombreux internautes, \u00e9meut particuli\u00e8rement la population de Wuhan endeuill\u00e9e depuis le 11 janvier, date du premier d\u00e9c\u00e8s annonc\u00e9, et confin\u00e9e depuis le 23 janvier.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tIl est encore trop t\u00f4t pour porter un regard distanci\u00e9 et nuanc\u00e9 sur la gestion locale et nationale de l&rsquo;\u00e9pid\u00e9mie. Mais on peut lire les critiques et les contestations sur les r\u00e9seaux sociaux. Les policiers ont-ils fait du z\u00e8le ? Ou bien ont-ils seulement ex\u00e9cut\u00e9 les directives de maintien de l&rsquo;ordre et de la stabilit\u00e9 ? Les discussions dans un cercle restreint sur les r\u00e9seaux sociaux peuvent se propager et devenir virales. En sorte que la rumeur n&rsquo;est qu&rsquo;un processus de transmission d&rsquo;informations qui, par d\u00e9finition, contiennent un certain nombre d&rsquo;incertitudes. Pour qu&rsquo;une information devienne une rumeur, il faut une participation collective pour expliquer un \u00e9v\u00e9nement soudain et dramatique, ou bien survenu dans un contexte conflictuel et confus. Dans la ville de Wuhan, la transformation en rumeur des discussions priv\u00e9es entre les professionnels est un acte collectif signifiant le refus du silence du gouvernement et la col\u00e8re contre l&rsquo;absence d&rsquo;intervention des autorit\u00e9s.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe flux des images provenant des portables priv\u00e9s et des reportages professionnels nous envahit. Faudrait-il inventer d&rsquo;autres mots pour d\u00e9crire la situation r\u00e9elle dans les h\u00f4pitaux \u00e0 Wuhan ? Selon un chiffre non officiel, plus de 30 m\u00e9decins et infirmiers sont contamin\u00e9s, dont Li Wenliang (\u674e\u6587\u4eae), un des 8 m\u00e9decins interpell\u00e9s. Nous l&rsquo;avons appris par les <a href=\"http:\/\/china.caixin.com\/2020-02-07\/101509761.html\" rel=\"noopener noreferrer\" target=\"_blank\">m\u00e9dias chinois<\/a> d&rsquo;abord, avant que l&rsquo;OMS ne confirme, la mort de cet ophtalmologue de 34 ans, d\u00e9c\u00e9d\u00e9 \u00e0 2h58 du matin ce 7 f\u00e9vrier.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>L&rsquo;\u00e9pid\u00e9mie repousse les limites de la stigmatisation<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL&rsquo;absence de v\u00e9rit\u00e9 fournit un terreau favorable \u00e0 la naissance d&rsquo;une rumeur. Sa transmission a le vent en poupe quand l&rsquo;ambiance est incertaine et angoissante. La suspicion, la peur et la haine en deviennent alors les actes concrets.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL&rsquo;OMS a attendu le 30 janvier pour qualifier l&rsquo;\u00e9pid\u00e9mie de coronavirus d&rsquo;urgence de sant\u00e9 publique de port\u00e9e internationale. Mais bien avant cette d\u00e9cision tr\u00e8s attendue par les Chinois, une autre d\u00e9cision, celle de mettre la ville de Wuhan en quarantaine \u00e0 partir du 23 janvier, a suscit\u00e9 une m\u00e9fiance envers les habitants ou les personnes originaires de la capitale provinciale du Hubei. Il faut m\u00eame parler de diabolisation, le mot \u00e9tant clairement utilis\u00e9 sur les r\u00e9seaux sociaux. Faciles \u00e0 trouver, des photos prises par les habitants m\u00eame des villes ou villages avoisinants montrent la construction de barricades en pierres ou en tronc d&rsquo;arbre g\u00e9ant sur les grands axes routiers, comme si l&rsquo;interruption totale de la circulation emp\u00eachait la propagation du virus. Plus encore, de nombreux t\u00e9moignages attestent d&rsquo;une m\u00e9fiance croissante dans les autres grandes villes en Chine. Exemple \u00e0 P\u00e9kin o\u00f9 un h\u00f4tel a refus\u00e9 d&rsquo;accueillir un client dont la carte d&rsquo;identit\u00e9 indiquait son origine du Hubei. Il faut pr\u00e9ciser que les internautes chinois sont r\u00e9volt\u00e9s de voir ces actes irrationnels dans leur pays, d&rsquo;autant plus que la situation est analogue partout dans le monde.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCes deux derni\u00e8res semaines, on commence \u00e0 se passer des touristes chinois. Depuis la suspension des vols directs avec la Chine, les secteurs concern\u00e9s ont pu en mesurer l&rsquo;impact. <em>\u00ab\u00a0Les touristes chinois ne sont pas les bienvenus\u00a0\u00bb,<\/em> lit-on sur la porte de nombreux restaurants au Japon et dans d&rsquo;autres pays asiatiques : le message montre bien que la peur a d\u00e9j\u00e0 gagn\u00e9 la bataille.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tEn France, les actes discriminatoires ne manquent pas. Cela va du simple geste de se d\u00e9caler l\u00e9g\u00e8rement de son si\u00e8ge dans le m\u00e9tro quand la jolie voisine asiatique commence \u00e0 tousser, jusqu&rsquo;\u00e0 l\u00e2cher une phrase portant clairement pr\u00e9judice \u00e0 une personne, en passant par un acte bien calcul\u00e9 : celui de freiner devant l&rsquo;entr\u00e9e d&rsquo;un restaurant asiatique. Il est toutefois important de nuancer les intentions derri\u00e8re ces comportements quand bien m\u00eame l&rsquo;exercice est difficile, pour ne pas confondre le sentiment d&rsquo;\u00eatre discrimin\u00e9 et le racisme av\u00e9r\u00e9.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tDans cet esprit, les communaut\u00e9s asiatiques en France d\u00e9noncent une d\u00e9fiance accrue ces derniers temps en raison de l&rsquo;\u00e9pid\u00e9mie. Que disent les t\u00e9moignages dans la presse et sur les r\u00e9seaux sociaux ? Que certains actes d\u00e9plac\u00e9s et grossiers sont certes des r\u00e9flexes g\u00e9n\u00e9r\u00e9s par la peur d&rsquo;\u00eatre contamin\u00e9. Mais que la personne en face peut aussi se sentir bless\u00e9e, puisqu&rsquo;on la juge sur son apparence : un visage asiatique repr\u00e9sente un potentiel porteur du virus. Le m\u00eame r\u00e9flexe courant de d\u00e9fiance \u00e0 la vue d&rsquo;un barbu dans la rue apr\u00e8s un attentat : c&rsquo;est peut-\u00eatre un terroriste&#8230;\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tAutre exemple, une jeune fille d&rsquo;origine chinoise se plaint sur WeChat : <em>\u00ab\u00a0Je veux bien porter un masque quand je sors, mais j&rsquo;ai peur des regards inqui\u00e9tants des autres.\u00a0\u00bb <\/em>D\u00e8s lors que son dilemme est de choisir entre se prot\u00e9ger et le regard d&rsquo;autrui, elle a finalement c\u00e9d\u00e9 au jugement d&rsquo;autrui au d\u00e9triment de sa propre sant\u00e9 et de celle des autres. La stigmatisation ambiante a atteint son paroxysme.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLa rumeur nous rend irrationnels, jusqu&rsquo;\u00e0 commettre des actes ignobles. Une maman raconte l&rsquo;histoire de sa fille : dans le bus allant \u00e0 la facult\u00e9, la jeune fille d&rsquo;origine chinoise en deuxi\u00e8me ann\u00e9e universitaire est assise en face d&rsquo;un vieux monsieur. Soudain, le monsieur lui dit : <em>\u00ab\u00a0\u00c9loigne-toi avec ton coronavirus chinois.\u00a0\u00bb<\/em> Au lieu de lui r\u00e9pondre, la jeune fille lui souffle dessus, et puis lui dit : <em>\u00ab\u00a0C&rsquo;est bon ? C&rsquo;est pour toi.\u00a0\u00bb<\/em> Le monsieur d\u00e9cide de s&rsquo;\u00e9loigner de la jeune fille et descend du bus.\t<\/div>\n<\/div>\n\n<div class=\"photo-text paragraph\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-1280x800.png\" class=\"article-image\" title=\"Une m\u00e8re raconte l'histoire de sa fille dans le bus \u00e0 Paris. Victime d'une remarque raciste li\u00e9e au coronavirus de la part d'un passager, elle lui souffle dessus en lan\u00e7ant : \"C'est bon ? C'est pour toi.\" Le passager est descendu \u00e0 l'arr\u00eat suivant. (Capture d'\u00e9cran de WeChat)\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"800\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-1280x800.png\" class=\"img-responsive\" alt=\"Une m\u00e8re raconte l&#039;histoire de sa fille dans le bus \u00e0 Paris. Victime d&#039;une remarque raciste li\u00e9e au coronavirus de la part d&#039;un passager, elle lui souffle dessus en lan\u00e7ant : &quot;C&#039;est bon ? C&#039;est pour toi.&quot; Le passager est descendu \u00e0 l&#039;arr\u00eat suivant. (Capture d&#039;\u00e9cran de WeChat)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-1280x800.png 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-250x156.png 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-1024x640.png 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-150x94.png 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-768x480.png 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-200x125.png 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-300x188.png 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-600x375.png 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-900x563.png 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08-680x425.png 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-02-04-a\u0300-08.58.08.png 1440w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t<meta itemprop=\"height\" content=\"1280\"\/>\n\t\t<meta itemprop=\"width\" content=\"800\"\/>\n\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/\"\/>\n\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t  \tUne m\u00e8re raconte l'histoire de sa fille dans le bus \u00e0 Paris. Victime d'une remarque raciste li\u00e9e au coronavirus de la part d'un passager, elle lui souffle dessus en lan\u00e7ant : \"C'est bon ? C'est pour toi.\" Le passager est descendu \u00e0 l'arr\u00eat suivant. (Capture d'\u00e9cran de WeChat)\t\t<\/figcaption>\n\t<\/figure>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLes minorit\u00e9s ethniques sont souvent la cible de discrimination et de racisme. Depuis quelques ann\u00e9es, les personnes originaires d&rsquo;Asie vivant en France d\u00e9noncent un racisme sous-jacent au quotidien. Certains en font fi. Le v\u00e9cu r\u00e9cent des Fran\u00e7ais issus de l&rsquo;immigration montre clairement que le racisme y trouve un exutoire, et la crise sanitaire sa justification.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLa peur est un pr\u00e9texte naturel pour maintenir une grande distance entre la source du danger et soi-m\u00eame. Toutes les mesures de pr\u00e9caution inhabituelles peuvent accentuer l&rsquo;inqui\u00e9tude latente et m\u00eame la rendre visible. Si la meilleure arme contre l&rsquo;\u00e9pid\u00e9mie est la pr\u00e9vention et la protection, l&rsquo;information et la transparence sont vitales quand les drames frappent l&rsquo;ensemble de la population. Les r\u00e9seaux sociaux chinois commencent \u00e0 d\u00e9tr\u00f4ner les m\u00e9dias officiels, si bien que lorsque les informations du gouvernement tardent \u00e0 venir, les rumeurs prennent le dessus et forment une contestation bouillonnante.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Tamara Lui,<\/strong> avec l&rsquo;aide de Patrick Cozette\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/asie-du-nord-est\/\" rel=\"tag\">Asie du Nord-Est<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/chine\/\" rel=\"tag\">Chine<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/chinois-de-france\/\" rel=\"tag\">Chinois de France<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/coronavirus\/\" rel=\"tag\">coronavirus<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/crise-sanitaire\/\" rel=\"tag\">crise sanitaire<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/epidemie\/\" rel=\"tag\">\u00e9pid\u00e9mie<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/france\/\" rel=\"tag\">France<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/organisation-mondiale-de-la-sante\/\" rel=\"tag\">Organisation mondiale de la Sant\u00e9<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/racisme\/\" rel=\"tag\">racisme<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/sante\/\" rel=\"tag\">sant\u00e9<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/sras\/\" rel=\"tag\">SRAS<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F02%2F08%2Fcoronavirus-chine-france-loi-rumeur-contestation-racisme%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=Coronavirus+%3A+la+loi+de+la+rumeur%2C+de+la+contestation+au+racisme&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F02%2F08%2Fcoronavirus-chine-france-loi-rumeur-contestation-racisme%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F02%2F08%2Fcoronavirus-chine-france-loi-rumeur-contestation-racisme%2F&title=Coronavirus+%3A+la+loi+de+la+rumeur%2C+de+la+contestation+au+racisme\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2020%2F02%2F08%2Fcoronavirus-chine-france-loi-rumeur-contestation-racisme%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2020%2F02%2Fcoronavirus-racisme-anti-chinois-scaled-e1580896952845-250x95.jpg&description=Coronavirus+%3A+la+loi+de+la+rumeur%2C+de+la+contestation+au+racisme\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/tamara.jpg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/tamaralui\/\">\n\t\t\t\t\t\t\tTamara Lui\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tOriginaire de Hongkong, ancienne journaliste pour deux grands m\u00e9dias hongkongais, Tamara s'est reconvertie dans le documentaire. Sp\u00e9cialis\u00e9e dans les \u00e9tudes sur l'immigration chinoise en France, elle m\u00e8ne actuellement  des projets d'\u00e9conomie sociale et solidaire.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2020\/01\/31\/coronavirus-chine-enchainement-erreurs-gestion-crise-wuhan-epidemie\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"400\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-576x400.jpg\" class=\"img-responsive wp-post-image\" alt=\"Personnel m\u00e9dical r\u00e9uni \u00e0 Xi&#039;an, capitale de la province du Shaanxi dans le centre de la Chine, avant son d\u00e9part pour Wuhan le 26 janvier 2020. (Source : Courrier international)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-576x400.jpg 576w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-150x104.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-250x174.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-768x533.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-1024x711.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-200x139.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-288x200.jpg 288w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-864x600.jpg 864w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-1228x853.jpg 1228w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus-680x472.jpg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/chine-masques-coronavirus.jpg 1280w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Politique<\/span><h4>Coronavirus en Chine : l'encha\u00eenement d'erreurs dans la gestion de la crise \u00e0 Wuhan<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2020\/01\/30\/economie-coronavirus-plus-menacant-que-sras-pour-chine-monde\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"279\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-600x279.jpg\" class=\"img-responsive wp-post-image\" alt=\"Usine de production de masques \u00e0 Handan, dans la province du Hebei au nord de la Chine, le 22 janvier 2020. (Source : Lowy Institute)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-600x279.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-150x70.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-250x116.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-768x357.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-1024x476.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-200x93.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-300x140.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-900x419.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-1280x595.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274-680x316.jpg 680w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/01\/coronavirus-masque-usine-e1580395585274.jpg 1600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Economie<\/span><h4>\u00c9conomie : le coronavirus plus mena\u00e7ant que le SRAS pour la Chine et le monde<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le coronavirus est-il une nouvelle \u00ab\u00a0pand\u00e9mie de la peur\u00a0\u00bb ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l&rsquo;information officielle dans les villes en quarantaine. \u00c0 l&rsquo;\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.<\/p>\n","protected":false},"author":674,"featured_media":46457,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[23,22,1684,1848,1850,1301,294,1192,486,222,1849],"class_list":["post-46450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-asie-du-nord-est","tag-chine","tag-chinois-de-france","tag-coronavirus","tag-crise-sanitaire","tag-epidemie","tag-france","tag-organisation-mondiale-de-la-sante","tag-racisme","tag-sante","tag-sras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coronavirus : la loi de la rumeur, de la contestation au racisme - Asialyst<\/title>\n<meta name=\"description\" content=\"Le coronavirus est-il une nouvelle &quot;pand\u00e9mie de la peur&quot; ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l&#039;information officielle dans les villes en quarantaine. \u00c0 l&#039;\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus : la loi de la rumeur, de la contestation au racisme\" \/>\n<meta property=\"og:description\" content=\"Le coronavirus est-il une nouvelle &quot;pand\u00e9mie de la peur&quot; ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l&#039;information officielle dans les villes en quarantaine. \u00c0 l&#039;\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-08T00:15:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-09T01:27:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2547\" \/>\n\t<meta property=\"og:image:height\" content=\"966\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tamara Lui\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coronavirus : la loi de la rumeur, de la contestation au racisme\" \/>\n<meta name=\"twitter:description\" content=\"Le coronavirus est-il une nouvelle &quot;pand\u00e9mie de la peur&quot; ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l&#039;information officielle dans les villes en quarantaine. \u00c0 l&#039;\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tamara Lui\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/\"},\"author\":{\"name\":\"Tamara Lui\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/3df1ceedcba280d318df70345225ccd7\"},\"headline\":\"Coronavirus : la loi de la rumeur, de la contestation au racisme\",\"datePublished\":\"2020-02-08T00:15:31+00:00\",\"dateModified\":\"2020-02-09T01:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/\"},\"wordCount\":2584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\",\"keywords\":[\"Asie du Nord-Est\",\"Chine\",\"Chinois de France\",\"coronavirus\",\"crise sanitaire\",\"\u00e9pid\u00e9mie\",\"France\",\"Organisation mondiale de la Sant\u00e9\",\"racisme\",\"sant\u00e9\",\"SRAS\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/\",\"name\":\"Coronavirus : la loi de la rumeur, de la contestation au racisme - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\",\"datePublished\":\"2020-02-08T00:15:31+00:00\",\"dateModified\":\"2020-02-09T01:27:20+00:00\",\"description\":\"Le coronavirus est-il une nouvelle \\\"pand\u00e9mie de la peur\\\" ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l'information officielle dans les villes en quarantaine. \u00c0 l'\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg\",\"width\":2547,\"height\":966,\"caption\":\"Des passagers portent un masque pour se prot\u00e9ger du coronavirus \u00e0 l'arriv\u00e9e d'un vol en provenance d'Asie \u00e0 l'a\u00e9roport international de Los Angeles, le 29 janvier 2020. (Source : USA Today)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2020\\\/02\\\/08\\\/coronavirus-chine-france-loi-rumeur-contestation-racisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus : la loi de la rumeur, de la contestation au racisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/3df1ceedcba280d318df70345225ccd7\",\"name\":\"Tamara Lui\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tamara-121x150.jpg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tamara-121x150.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tamara-121x150.jpg\",\"caption\":\"Tamara Lui\"},\"description\":\"Originaire de Hongkong, ancienne journaliste pour deux grands m\u00e9dias hongkongais, Tamara s'est reconvertie dans le documentaire. Sp\u00e9cialis\u00e9e dans les \u00e9tudes sur l'immigration chinoise en France, elle m\u00e8ne actuellement des projets d'\u00e9conomie sociale et solidaire.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/tamaralui\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus : la loi de la rumeur, de la contestation au racisme - Asialyst","description":"Le coronavirus est-il une nouvelle \"pand\u00e9mie de la peur\" ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l'information officielle dans les villes en quarantaine. \u00c0 l'\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Coronavirus : la loi de la rumeur, de la contestation au racisme","og_description":"Le coronavirus est-il une nouvelle \"pand\u00e9mie de la peur\" ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l'information officielle dans les villes en quarantaine. \u00c0 l'\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.","og_url":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2020-02-08T00:15:31+00:00","article_modified_time":"2020-02-09T01:27:20+00:00","og_image":[{"width":2547,"height":966,"url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg","type":"image\/jpeg"}],"author":"Tamara Lui","twitter_card":"summary_large_image","twitter_title":"Coronavirus : la loi de la rumeur, de la contestation au racisme","twitter_description":"Le coronavirus est-il une nouvelle \"pand\u00e9mie de la peur\" ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l'information officielle dans les villes en quarantaine. \u00c0 l'\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.","twitter_image":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg","twitter_misc":{"\u00c9crit par":"Tamara Lui","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/"},"author":{"name":"Tamara Lui","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/3df1ceedcba280d318df70345225ccd7"},"headline":"Coronavirus : la loi de la rumeur, de la contestation au racisme","datePublished":"2020-02-08T00:15:31+00:00","dateModified":"2020-02-09T01:27:20+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/"},"wordCount":2584,"commentCount":0,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg","keywords":["Asie du Nord-Est","Chine","Chinois de France","coronavirus","crise sanitaire","\u00e9pid\u00e9mie","France","Organisation mondiale de la Sant\u00e9","racisme","sant\u00e9","SRAS"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/","url":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/","name":"Coronavirus : la loi de la rumeur, de la contestation au racisme - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg","datePublished":"2020-02-08T00:15:31+00:00","dateModified":"2020-02-09T01:27:20+00:00","description":"Le coronavirus est-il une nouvelle \"pand\u00e9mie de la peur\" ? Pour comprendre ce qui nous arrive, de Wuhan \u00e0 Paris, il faut consid\u00e9rer un acteur central de cette crise sanitaire internationale : la rumeur. En Chine, elle peut servir de vecteur de la col\u00e8re contre le verrouillage de l'information officielle dans les villes en quarantaine. \u00c0 l'\u00e9tranger et en France en particulier, elle nourrit aussi un racisme anti-asiatique d\u00e9j\u00e0 sous-jacent au quotidien.","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/coronavirus-racisme-anti-chinois-scaled-e1580896952845.jpg","width":2547,"height":966,"caption":"Des passagers portent un masque pour se prot\u00e9ger du coronavirus \u00e0 l'arriv\u00e9e d'un vol en provenance d'Asie \u00e0 l'a\u00e9roport international de Los Angeles, le 29 janvier 2020. (Source : USA Today)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2020\/02\/08\/coronavirus-chine-france-loi-rumeur-contestation-racisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Coronavirus : la loi de la rumeur, de la contestation au racisme"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/3df1ceedcba280d318df70345225ccd7","name":"Tamara Lui","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/tamara-121x150.jpg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/tamara-121x150.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2020\/02\/tamara-121x150.jpg","caption":"Tamara Lui"},"description":"Originaire de Hongkong, ancienne journaliste pour deux grands m\u00e9dias hongkongais, Tamara s'est reconvertie dans le documentaire. Sp\u00e9cialis\u00e9e dans les \u00e9tudes sur l'immigration chinoise en France, elle m\u00e8ne actuellement des projets d'\u00e9conomie sociale et solidaire.","url":"https:\/\/asialyst.com\/fr\/auteur\/tamaralui\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/46450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/674"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=46450"}],"version-history":[{"count":15,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/46450\/revisions"}],"predecessor-version":[{"id":46565,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/46450\/revisions\/46565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/46457"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=46450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=46450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=46450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}