﻿<br />
<b>Warning</b>:  Undefined array key "p" in <b>/home/asialyst/www/releases/20250606081313/fr/wp-content/themes/asialyst_v2.3/shortcodes/article-category.php</b> on line <b>9</b><br />
{"id":34445,"date":"2017-10-13T02:52:18","date_gmt":"2017-10-13T00:52:18","guid":{"rendered":"https:\/\/asialyst.com\/fr\/2017\/10\/11\/brouillon-regards-copy-3-copy-copy-copy-copy-2-copy-copy-copy-2\/"},"modified":"2017-10-14T18:51:04","modified_gmt":"2017-10-14T16:51:04","slug":"presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote","status":"publish","type":"post","link":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/","title":{"rendered":"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote"},"content":{"rendered":"<div class=\"container\">\n\t<meta itemprop=\"keywords\" content=\"Politique\" \/>\n\t<a href=\"https:\/\/asialyst.com\/fr\/politique\/\" class=\"category category-20\">Politique<\/a><br \/>\n\t<time datetime=\"2017-10-13T02:52:18Z\" itemprop=\"datePublished\">\n\t\tPubli\u00e9 13 Octobre 2017<br \/>\n\t\tMis \u00e0 jour 14 Octobre 2017\t<\/time>\n\t<meta itemprop=\"dateModified\" content=\"2017-10-14T18:51:04Z\" \/>\n<\/div>\n<div class=\"container\">\n<div class=\"surtitre\" itemprop=\"headline\">Analyse<\/div><\/div>\n<div class=\"container\">\n\t<h1 itemprop=\"name\">Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote<\/h1>\n<\/div>\n<div class=\"container\">\n  <div class=\"authors\">\n    <ul>\n    \t        <li class=\"author\" itemprop=\"author\" itemscope itemtype=\"http:\/\/schema.org\/Person\">\n          <a href=\"https:\/\/asialyst.com\/fr\/auteur\/asselkipchakova\/\" class=\"category-color\" itemprop=\"url\">\n            <span itemprop=\"name\" class=\"name\">\n              Assel Kipchakova            <\/span>\n            <img data-del=\"avatar\" alt=\"Assel Kipchakova\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/portrait-assel-180x180.jpg' class='avatar pp-user-avatar avatar-150 photo ' height='150' width='150'\/>          <\/a>\n        <\/li>\n    \t    <\/ul>\n  <\/div>\n<\/div>\n<div class=\"container\">\n  <div class=\"photo-une\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n    <figure>\n      <a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg\" class=\"article-image\" title=\"Affiche de campagne du candidat soutenu par le pouvoir Sooronbai Jeenbekov pour l'ection presidentielle du dimanche 15 octobre, dans le village de Kok-Zhar, le12 Octobre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"756\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg\" class=\"img-responsive\" alt=\"Affiche de campagne du candidat soutenu par le pouvoir Sooronbai Jeenbekov pour l&#039;ection presidentielle du dimanche 15 octobre, dans le village de Kok-Zhar, le12 Octobre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)\" \/><\/a>\n      <meta itemprop=\"height\" content=\"1024\"\/>\n      <meta itemprop=\"width\" content=\"756\"\/>\n      <meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/\"\/>\n      <figcaption class=\"legend\" itemprop=\"description\">\n      \t<div class=\"container\">\n        \tAffiche de campagne du candidat soutenu par le pouvoir Sooronbai Jeenbekov pour l'ection presidentielle du dimanche 15 octobre, dans le village de Kok-Zhar, le12 Octobre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)        <\/div>\n      <\/figcaption>\n    <\/figure>\n  <\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"chapo\" itemprop=\"description\">\n\t\tEn Asie centrale, les citoyens du Kirghizistan sont appel\u00e9s aux urnes ce dimanche 15 octobre pour \u00e9lire leur cinqui\u00e8me pr\u00e9sident. Dans un contexte d\u2019instabilit\u00e9 \u00e9conomique, de d\u00e9pendance \u00e9nerg\u00e9tique envers ses voisins et de menaces terroristes \u00e0 ses fronti\u00e8res, la seule d\u00e9mocratie d\u2019Asie centrale doit faire face \u00e0 de nouveaux d\u00e9fis. Tour d\u2019horizon des enjeux de cette pr\u00e9sidentielle.\t<\/div>\n<\/div>\n<div class=\"large large\" style=\"background-color:#961157;\">\n\t<div class=\"container\">\n\t\t<div class=\"sub-article\">\n\t\t\t<h2>Contexte<\/h2>\n\t\t\t<p>Situ\u00e9 au c\u0153ur du jeu g\u00e9opolitique entre la Chine, la Russie et la Turquie, le Kirghizistan occupe une place singuli\u00e8re en Asie centrale. Tout en \u00e9tant l\u2019un des pays les plus pauvres de la r\u00e9gion avec un salaire moyen de 180 euros par mois, cette petite r\u00e9publique montagneuse peupl\u00e9e de pr\u00e8s de 6 millions d\u2019habitants se distingue de ses voisins par une relative bonne sant\u00e9 d\u00e9mocratique. Un esprit guerrier \u00e9pris de libert\u00e9 r\u00e8gne chez ce peuple d\u2019anciens nomades qui, en 2005 et 2010, a renvers\u00e9 sans m\u00e9nagement ses deux anciens pr\u00e9sidents, Askar Akaev et Kourmanbek Bakiev. Pour Adrien Fauve, chercheur \u00e0 l\u2019Universit\u00e9 Paris-Sud, <em>\u00ab\u00a0c\u2019est peut-\u00eatre la premi\u00e8re fois dans l\u2019histoire du pays que le changement d\u2019\u00e9lite gouvernementale se fera de mani\u00e8re apais\u00e9e, sans avoir besoin de recourir aux m\u00e9contentements de la rue\u00a0\u00bb.<\/em> Cette d\u00e9mocratie est pourtant tr\u00e8s fragile, car le pays est gangr\u00e9n\u00e9 par la corruption. Il se classe au 136e rang mondial de l\u2019indice de perception de la corruption sur 176 pays, selon Transparency International. L\u2019enjeu de cette pr\u00e9sidentielle est d\u2019\u00e9viter que le pays ne glisse vers l\u2019autoritarisme comme l\u2019a r\u00e9cemment fait le Tadjikistan.<\/p>\n<p>Depuis 2011, le Chef de l\u2019\u00c9tat est \u00e9lu pour un mandat de six ans et n\u2019a pas le droit de se repr\u00e9senter. La campagne pr\u00e9sidentielle de 2017 a \u00e9t\u00e9 lanc\u00e9e d\u00e9but septembre : parmi les 10 candidats en lice restants, une seule femme. Lors de la pr\u00e9c\u00e9dente \u00e9lection de 2011, la participation avait \u00e9t\u00e9 relativement faible, pr\u00e8s de 57%. Cette ann\u00e9e, elle risque de l\u2019\u00eatre encore plus, car les \u00e9lecteurs doivent se munir d\u2019un passeport biom\u00e9trique. Or, seuls 2,9 millions sur pr\u00e8s de 3,8 millions d\u2019\u00e9lecteurs potentiels poss\u00e8dent ce s\u00e9same.<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<h2>L\u2019h\u00e9ritage du pr\u00e9sident Atambaev<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe pr\u00e9sident sortant Almazbek Atambaev termine son mandat avec un bilan mitig\u00e9. Ce social- d\u00e9mocrate repr\u00e9sentant le parti SDPK (le Parti social-d\u00e9mocrate du Kirghizistan) a r\u00e9ussi \u00e0 pr\u00e9server la souverainet\u00e9 nationale. Il a su instaurer jusque-l\u00e0 un dialogue relativement \u00e9galitaire avec ses voisins, le Kazakhstan, la Russie et la Chine &#8211; m\u00eame si ses r\u00e9centes critiques envers l\u2019oligarchie dirigeante du Kazakhstan ont compromis cet \u00e9quilibre. En obtenant des injections financi\u00e8res de ces pays dans l\u2019\u00e9conomie kirghize, jusqu\u2019\u00e0 supprimer la dette du pays, il a \u00e9vit\u00e9 ainsi la faillite et a renforc\u00e9 son pouvoir pouvoir. Depuis 2015, l\u2019ann\u00e9e de l\u2019int\u00e9gration du Kirghizistan \u00e0 l\u2019Union \u00e9conomique eurasiatique (UEE) dont les b\u00e9n\u00e9fices sont encore tr\u00e8s faibles, le pr\u00e9sident a obtenu des am\u00e9liorations du statut des migrants kirghizes en Russie. Aujourd\u2019hui, quelque 10% de la population kirghize y travaillent et envoient chaque ann\u00e9e pr\u00e8s de 1,7 milliard de dollars au pays.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tCependant, Atambaev est aussi critiqu\u00e9 pour son acharnement contre l\u2019opposition, les activistes et les m\u00e9dias ind\u00e9pendants, notamment dans les derniers mois de son mandat. Le socialiste Omurbek Tekebaev, son principal rival et leader du parti Ata-Meken, candidat lui aussi \u00e0 la pr\u00e9sidentielle, a \u00e9t\u00e9 arr\u00eat\u00e9 en pleine campagne pour corruption et condamn\u00e9 \u00e0 8 ans de prison, apr\u00e8s un proc\u00e8s compl\u00e8tement fabriqu\u00e9, selon l\u2019opposition. De m\u00eame pour la condamnation \u00e0 vie du d\u00e9fenseur des droits de l\u2019homme, Azimjan Askarov, accus\u00e9 d&rsquo;incitations \u00e0 la haine au cours d\u2019\u00e9v\u00e9nements sanglants dans le sud du pays en 2010 &#8211; all\u00e9gations que l\u2019opposition impute au chef de l\u2019\u00c9tat. Rien d\u2019\u00e9tonnant \u00e0 ce que les rapports de ce dernier avec les journalistes kirghizes manquent de s\u00e9r\u00e9nit\u00e9. Pour preuve, cette amende pour diffamation de 3 millions de soms (37 mille euros) inflig\u00e9e brutalement au site d\u2019information ind\u00e9pendant Zanoza.kg.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tSi le pr\u00e9sident sortant nie toute possibilit\u00e9 de briguer le poste de Premier ministre \u00e0 la mani\u00e8re du sc\u00e9nario Poutine-Medvedev, il compte bien rester dans la vie politique du pays. David Ga\u00fcz\u00e8re, chercheur associ\u00e9 \u00e0 l\u2019Universit\u00e9 de Bordeaux, doute qu\u2019Almazbek Atambaev puisse revenir aux manettes du pays : <em>\u00ab\u00a0Les Kirghizes ne sont pas les Russes et ils ne permettront pas \u00e7a.\u00a0\u00bb<\/em> Cependant aux yeux du chercheur, <em>\u00ab\u00a0il gardera un r\u00f4le de second plan, de conseiller, aupr\u00e8s du futur pr\u00e9sident, mais officieusement, il aura toujours la main dessus\u00a0\u00bb.<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Le choix du pr\u00e9sident<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe pr\u00e9sident Atambaev a d\u00e9j\u00e0 choisi \u00ab\u00a0son\u00a0\u00bb candidat depuis longtemps. Il s\u2019agit de Sooronbay Jeenbekov, le Premier ministre sortant, 59 ans. Solidement install\u00e9 au pouvoir malgr\u00e9 un manque de charisme notoire, Sooronbay Jeenbekov, ancien ing\u00e9nieur zootechnicien, se situe dans une parfaite continuit\u00e9 du pr\u00e9sident actuel. Selon l&rsquo;agence de presse locale AkiPress, il a connu une progression spectaculaire dans les sondages. Si en mai dernier il n\u2019affichait que 0,87% d\u2019intentions de vote, ce score est mont\u00e9 en fl\u00e8che en ao\u00fbt pour atteindre les 42%. Fortement critiqu\u00e9 pour l\u2019utilisation abusive des <em>\u00ab\u00a0ressources administratives\u00a0\u00bb,<\/em> c\u2019est-\u00e0-dire pour avoir eu recours aux fonctionnaires qu\u2019il incite \u00e0 faire voter en sa faveur, cet originaire du sud du pays, est ouvertement soutenu par le pouvoir en place. David Ga\u00fcz\u00e8re est assez cat\u00e9gorique: <em>\u00ab\u00a0Sooronbay Jeenbekov sera au deuxi\u00e8me tour et gagnera les \u00e9lections. Il peut b\u00e9n\u00e9ficier de ce qu\u2019on appelle depuis le r\u00e9f\u00e9rendum dernier en 2016, de \u00ab\u00a0l\u2019Etat SDPK\u00a0\u00bb la mise \u00e0 disposition des moyens de l\u2019\u00c9tat au service du parti.\u00a0\u00bb<\/em> Par ailleurs, la rencontre expresse du pr\u00e9sident kirghize avec son homologue russe Vladimir Poutine fin septembre aurait eu pour but de s\u2019assurer du soutien de Moscou \u00e0 la candidature de Jeenbekov. Selon l\u2019expert russe Arkadiy Dubnov, il s\u2019agissait de garanties apport\u00e9es au Kremlin qu\u2019en cas de victoire de son prot\u00e9g\u00e9, le Kirghizistan maintiendrait sa loyaut\u00e9 envers la Russie. Malgr\u00e9 toutes ces agitations de derni\u00e8re minute, Moscou reste distant et n\u2019affiche pas ouvertement ses pr\u00e9f\u00e9rences.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tQuant au candidat du parti adverse, Omurbek Babanov, s&rsquo;il a r\u00e9ussi \u00e0 maintenir sa popularit\u00e9 \u00e0 pr\u00e8s de 40% selon AkiPress, il doit redoubler d\u2019efforts pour affronter la grosse machine du pouvoir actuel. Candidat sans \u00e9tiquette, jusque-l\u00e0 leader du parti R\u00e9publika Ata-Jourt, Babanov est un ambitieux lib\u00e9ral de 47 ans, ancien Premier ministre lui aussi. Dipl\u00f4m\u00e9 de l\u2019Acad\u00e9mie de l\u2019agriculture de Moscou, ancien entrepreneur dans le p\u00e9trole, il a fait ses armes au gouvernement sous la pr\u00e9sidence controvers\u00e9e de Bakiev puis celle d\u2019Atambaev. En vrai diplomate, il a toujours su se maintenir \u00e0 flot. Aujourd&rsquo;hui, il promet un nouveau style de gouvernance : \u00ab\u00a0Oui \u00e0 la lib\u00e9ralisation de l\u2019\u00e9conomie\u00a0\u00bb, \u00ab\u00a0Non \u00e0 la corruption\u00a0\u00bb, \u00ab\u00a0Pour une justice ind\u00e9pendante\u00a0\u00bb, \u00ab\u00a0S\u00e9curit\u00e9 pour tous\u00a0\u00bb, \u00ab\u00a0Doublement du revenu minimum\u00a0\u00bb&#8230; Mais aussi s\u00e9duisants soient-ils, ses slogans ne garantissent pas que son programme sera r\u00e9alis\u00e9 en peu de temps.\t<\/div>\n<\/div>\n\n<div class=\"photo-text paragraph\" itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\">\n\t<figure>\n\t\t<a href=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-1280x703.jpg\" class=\"article-image\" title=\"Le candidat de l'opposition \u00e0 l'election pr\u00e9sidentielle khirgize du 15 octobre 2017, Omurbek Babanov, en campagne dans la ville de Tokmok, \u00e0 60 km de la capitale Bishkek, le 22 septembre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"703\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-1280x703.jpg\" class=\"img-responsive\" alt=\"Le candidat de l&#039;opposition \u00e0 l&#039;election pr\u00e9sidentielle khirgize du 15 octobre 2017, Omurbek Babanov, en campagne dans la ville de Tokmok, \u00e0 60 km de la capitale Bishkek, le 22 septembre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-1280x703.jpg 1280w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-150x82.jpg 150w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-250x137.jpg 250w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-768x422.jpg 768w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-e1507858962299.jpg 1024w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-200x110.jpg 200w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-300x165.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-600x329.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-900x494.jpg 900w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-1600x878.jpg 1600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-babnov-680x373.jpg 680w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t<meta itemprop=\"height\" content=\"1280\"\/>\n\t\t<meta itemprop=\"width\" content=\"703\"\/>\n\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/\"\/>\n\t\t<figcaption class=\"legend\" itemprop=\"description\">\n\t\t  \tLe candidat de l'opposition \u00e0 l'election pr\u00e9sidentielle khirgize du 15 octobre 2017, Omurbek Babanov, en campagne dans la ville de Tokmok, \u00e0 60 km de la capitale Bishkek, le 22 septembre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)\t\t<\/figcaption>\n\t<\/figure>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tRalli\u00e9 r\u00e9cemment par un autre candidat \u00e0 la pr\u00e9sidentielle, Bakyt Torobaev, 44 ans, du parti<br \/>\n\u00ab\u00a0Onougou Progress\u00a0\u00bb, Omurbek Babanov est plus que jamais d\u00e9cid\u00e9 \u00e0 remporter l&rsquo;\u00e9lection. D\u2019\u00e9normes affiches de la taille d\u2019un immeuble de 5 \u00e9tages, avec le candidat tout sourire, la main sur le c\u0153ur, drapeau kirghize au vent, foisonnent dans toute la capitale Bichkek. Le candidat a d\u00e9j\u00e0 d\u00e9pens\u00e9 pr\u00e8s de 2,5 millions de dollars pour sa campagne pr\u00e9sidentielle, soit trois fois plus que les autres candidats.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tSi on accuse le chalenger d\u2019acheter des votes, Mars Sariev, politologue kirghize, reste persuad\u00e9 qu\u2019il s\u2019agit d\u2019une pure campagne de d\u00e9nigrement : <em>\u00ab\u00a0Cela fait longtemps que le Kirghizistan attend de jeunes r\u00e9formateurs comme eux. Ils ont de l\u2019exp\u00e9rience, aussi bien en politique qu\u2018en business.\u00a0\u00bb<\/em> Pour le politologue, les deux candidats sont <em>\u00ab\u00a0soutenus par une tr\u00e8s large partie de la soci\u00e9t\u00e9, les jeunes, les entrepreneurs, l\u2019<\/em><em>intelligentsia,<\/em> mais aussi par la soci\u00e9t\u00e9 traditionnelle du sud et du nord\u00a0\u00bb.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tAlors que la confrontation s&rsquo;intensifie entre les camps, on vient d\u2019apprendre l\u2019arrestation d\u2019un proche d\u2019Omourbek Babanov, le d\u00e9put\u00e9 Kanatbek Issaev du parti \u00ab\u00a0Kirghizstan\u00a0\u00bb. Le 30 septembre, le Procureur g\u00e9n\u00e9ral a ouvert une enqu\u00eate p\u00e9nale pour incitation \u00e0 l\u2019\u00e9meute et intention de prendre le pouvoir au cours de la campagne ou dans l\u2019apr\u00e8s-pr\u00e9sidentielle, le tout assorti d\u2019une suspicion de collusion avec des groupes criminels. Omurbel Babanov a appel\u00e9 les autorit\u00e9s \u00e0 examiner la situation avec la plus grande impartialit\u00e9. <em>\u00ab\u00a0Si Kanatbek Issaev ne m\u2019avait pas apport\u00e9 son soutien, il n\u2019aurait pas eu de probl\u00e8me\u00a0\u00bb,<\/em> a-t-il d\u00e9fendu.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>L\u2019avenir incertain de la Constitution<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tLe Kirghizistan est le seul pays d\u2019Asie centrale \u00e0 avoir instaur\u00e9 un r\u00e9gime semi-parlementaire. Les deux r\u00e9volutions de 2005 et de 2010 ont mis fin \u00e0 la supr\u00e9matie du pr\u00e9sident. En d\u00e9cembre dernier, la Constitution a subi 26 amendements. D\u00e9sormais, la nouvelle version, approuv\u00e9e \u00e0 80% des votes lors du r\u00e9f\u00e9rendum du 11 d\u00e9cembre 2016, augmente le pouvoir du Premier ministre. Mais elle rend aussi les juges moins autonomes, tandis que les lois kirghizes priment d\u00e9sormais sur le droit international. Celui qui a \u0153uvr\u00e9 \u00e0 cette Constitution \u00e0 la t\u00eate du gouvernement n\u2019est autre que Sooronbay Jeenbekov. S\u2019il remporte l\u2019\u00e9lection, la Constitution sera renforc\u00e9e. Mais en cas de victoire d\u2019Omourbek Babanov, la position du chef de l\u2019\u00c9tat pourrait se trouver renforc\u00e9e. Selon Babanov, le syst\u00e8me semi-parlementaire est inefficace : <em>\u00ab\u00a0La personne qui prend les d\u00e9cisions doit les assumer. Et chez nous, durant les 20 derni\u00e8res ann\u00e9es, les d\u00e9cisions ont \u00e9t\u00e9 prises par les chefs d\u2019\u00c9tat qui ont fait porter la responsabilit\u00e9 par les Premiers ministres. On s\u2019est retrouv\u00e9 ainsi avec 24 chefs de gouvernement !\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>L\u2019\u00e9quilibre Nord-Sud<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL\u2019un des enjeux de cette pr\u00e9sidentielle est l\u2019\u00e9quilibre entre les forces politiques du Sud et du Nord. Face \u00e0 la capitale Bichkek dans le nord du pays, plus d\u00e9velopp\u00e9e \u00e9conomiquement, plus ouverte et moins religieuse, les r\u00e9gions d\u2019Och et de Djalal-Abad dans le Sud, frontali\u00e8res avec l\u2019Ouzb\u00e9kistan, sont plus traditionnelles et connaissent une plus grande pr\u00e9carit\u00e9. Les tensions ethniques entre les Kirghizes et la minorit\u00e9 ouzb\u00e8ke s&rsquo;enflamment r\u00e9guli\u00e8rement. Les Ouzbeks repr\u00e9sentent la plus grande minorit\u00e9 ethnique dans le pays avec quelque 850 000 personnes vivant dans le Sud, principalement dans la vall\u00e9e de Fergana. Ce conflit ethnique s&rsquo;est traduit en 2010 par de sanglants affrontements qui ont fait pr\u00e8s de 450 morts \u00e0 Och et \u00e0 Djalal-Abad en \u00e0 peine cinq jours .\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>\u00ab\u00a0Cet axe Nord-Sud est n\u00e9cessaire pour maintenir la coh\u00e9sion nationale,<\/em> explique David Ga\u00fcz\u00e8re. <em>Afin qu\u2019elle soit davantage garantie et que d\u2019\u00e9ventuelles tensions puissent \u00eatre d\u00e9samorc\u00e9es, il faudrait que la minorit\u00e9 ouzb\u00e8ke soit plus pr\u00e9sente dans le d\u00e9bat. Cela se pratique dans le nord du pays avec la minorit\u00e9 russe, dont certains d\u00e9put\u00e9s repr\u00e9sentent le SDPK ou l&rsquo;Ata-Meken au Parlement. Une partie du pays se sentirait flou\u00e9 si une seule formation politique accaparait tous les pouvoirs.\u00a0\u00bb<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tPour pallier cette divergence, le tandem pr\u00e9sident-Premier ministre repr\u00e9sentant les deux parties du pays serait un duo gagnant. Dans ce sens, une fine strat\u00e9gie politique est en train de se mettre en place. Le nouveau chef du gouvernement Sapar Isakov, le poulain du pr\u00e9sident actuel, est originaire du Nord, alors que le candidat du parti au pouvoir vient du sud. Il n\u2019est pas \u00e9tonnant que cet argument soit largement exploit\u00e9 par le SDPK depuis le d\u00e9but de la campagne.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<h2>Le terrain glissant de l\u2019islamisme fondamentaliste<\/h2>\n<\/div>\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tAutre enjeu de la pr\u00e9sidentielle : l\u2019islamisme fondamentaliste. M\u00eame s\u2019il existe un important courant la\u00efc de r\u00e9habilitation de la pens\u00e9e tengriste et de l\u2019islam national kirghize avec des \u00e9l\u00e9ments de chamanisme, on compte aujourd\u2019hui plus d\u2019une centaine d\u2019institutions islamiques. Plus de 6 000 enfants \u00e9tudient dans des \u00e9coles coraniques, d\u2019apr\u00e8s la Direction spirituelle des musulmans du Kirghizstan. En 1991, l\u2019ann\u00e9e de l&rsquo;ind\u00e9pendance du pays, le Kirghizistan comptait 39 mosqu\u00e9es sur le territoire kirghize. Aujourd\u2019hui, elles sont plus de 2 700.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tAlors que les partis politiques fond\u00e9s sur une religion ou une ethnie sont interdits, il existe n\u00e9anmoins des associations religieuses puissantes. <em>\u00ab\u00a0Ces associations peuvent infiltrer la classe politique locale, notamment en s\u2019appuyant sur la jeunesse la plus religieuse,<\/em> pr\u00e9vient David Ga\u00fcz\u00e8re, <em>le risque \u00e9tant la pression qu\u2018elles exerceraient sur des politiques, pour ne pas \u00e9voquer les questions li\u00e9es au terrorisme.\u00a0\u00bb<\/em> C\u2019est le cas notamment des religieux qui ne pr\u00f4nent pas la violence, mais qui tiennent un discours radical. Selon le chercheur, ils pr\u00eachent un chemin religieux plus rigoriste, surtout dans les villages recul\u00e9s et sont financ\u00e9s par les fonds d\u2019aide \u00e9gyptiens et saoudiens. Des imams d\u2019Och ont appel\u00e9 r\u00e9cemment les jeunes femmes kirghizes \u00e0 bien r\u00e9fl\u00e9chir avant de se marier avec des \u00e9trangers, car ce type d&rsquo;union est \u00ab\u00a0contraire \u00e0 la religion\u00a0\u00bb et elles pourraient souffrir de violences conjugales.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tSi le pr\u00e9sident Atambaev a bien conscience des risques de radicalisation, il estime n\u00e9anmoins que les interdictions seront contreproductives : <em>\u00ab\u00a0Nous avons une autre voie. Certains interdisent la religion. A mon avis, la religion doit \u00eatre canalis\u00e9e par l\u2019\u00e9ducation, l\u2019explication. Il n\u2019y a pas d\u2019autre moyen. Si on l\u2019interdit, elle deviendra source de radicalisation.\u00a0\u00bb<\/em> D\u2019apr\u00e8s Tchinara Esengoul, experte kirghize de l\u2019islamisme radical, environ 850 personnes ont rejoint Daech en Syrie et en Irak depuis le Kirghizistan.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\tL\u2019enjeu majeur de cette pr\u00e9sidentielle, mais aussi celui de la jeune g\u00e9n\u00e9ration kirghize, c\u2019est donc de r\u00e9ussir \u00e0 entretenir l\u2019esprit de concorde nationale sous le prisme des traditions ancestrales, de l\u2019esprit de <em>\u00ab\u00a0kirghizchylyk\u00a0\u00bb,<\/em> le mode de vie des anc\u00eatres kirghizes, sans pour autant tomber dans l\u2019ethnonationalisme.\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<strong>Par Assel Kipchakova<\/strong>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" itemprop=\"articleBody\">\n\t\t<em>(Cette article a \u00e9t\u00e9 publi\u00e9 dans <a href=\"http:\/\/www.rfi.fr\/asie-pacifique\/20171013-presidentielle-kirghize-enjeux-democratie-marbre\" rel=\"noopener\" target=\"_blank\">une version plus courte sur le site de notre partenaire RFI<\/a>)<\/em>\t<\/div>\n<\/div>\n\n<div class=\"container\">\n\t<div class=\"text\" style=\"background:#d9463d; padding:20px 20px 30px 20px; text-align:center; border-radius:8px;\">\n\t\t<h3 style=\"color:#fff; font-weight:700;\">Soutenez-nous !<\/h3>\n\t\t<p style=\"color:#fff; font-size:0.8em; line-height:1.5em; margin-bottom:30px;\">Asialyst est con\u00e7u par une \u00e9quipe compos\u00e9e \u00e0 100 % de b\u00e9n\u00e9voles et gr\u00e2ce \u00e0 un r\u00e9seau de contributeurs en Asie ou ailleurs, journalistes, experts, universitaires, consultants ou anciens diplomates... Notre seul but : partager la connaissance de l'Asie au plus large public.<\/p>\n\t\t<a href=\"https:\/\/www.helloasso.com\/associations\/les-amis-d-asialyst\/formulaires\/1\" target=\"_blank\" style=\"display:inline; background:#fff; padding:10px 25px; font-weight:700; border-radius:4px; color:#000; font-size:0.9em;\">Faire un don<\/a>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"tags\">\n\t\t<h5>Tags de l'article<\/h5>\n\t\t<ul><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/abonnes\/\" rel=\"tag\">Abonn\u00e9s<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/asie-centrale\/\" rel=\"tag\">Asie Centrale<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/kirghizistan\/\" rel=\"tag\">Kirghizistan<\/a><\/li><li><a href=\"https:\/\/asialyst.com\/fr\/tag\/temps-forts\/\" rel=\"tag\">temps forts<\/a><\/li><\/ul><ul>\t<\/ul><\/div>\n<\/div>\n\n\t\t<div class=\"social-sharing ss-social-sharing\">\r\n\t\t\t\t        <a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-facebook\" href=\"http:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fasialyst.com%2Ffr%2F2017%2F10%2F13%2Fpresidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote%2F\" target=\"_blank\">Share on Facebook<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-twitter\" href=\"http:\/\/twitter.com\/intent\/tweet\/?text=Pr%C3%A9sidentielle+au+Kirghizistan+%3A+la+seule+d%C3%A9mocratie+d%E2%80%99Asie+centrale+%C3%A0+l%E2%80%99%C3%A9preuve+du+vote&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2017%2F10%2F13%2Fpresidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote%2F&via=asialyst\" target=\"_blank\">Share on Twitter<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https%3A%2F%2Fasialyst.com%2Ffr%2F2017%2F10%2F13%2Fpresidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote%2F&title=Pr%C3%A9sidentielle+au+Kirghizistan+%3A+la+seule+d%C3%A9mocratie+d%E2%80%99Asie+centrale+%C3%A0+l%E2%80%99%C3%A9preuve+du+vote\" target=\"_blank\">Share on Linkedin<\/a><a onclick=\"return ss_plugin_loadpopup_js(this);\" rel=\"external nofollow\" class=\"ss-button-pinterest\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fasialyst.com%2Ffr%2F2017%2F10%2F13%2Fpresidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote%2F&media=https%3A%2F%2Fasialyst.com%2Ffr%2Fwp-content%2Fuploads%2F2017%2F10%2Fkirghizistan-election-presidentielle-250x185.jpg&description=Pr%C3%A9sidentielle+au+Kirghizistan+%3A+la+seule+d%C3%A9mocratie+d%E2%80%99Asie+centrale+%C3%A0+l%E2%80%99%C3%A9preuve+du+vote\" target=\"_blank\">Share on Pinterest<\/a>\t        \t    <\/div>\r\n\t    \n<div class=\"container\">\n\t<div class=\"auteurs-a-propos\">\n\t\t<h5>A propos de l'auteur<\/h5>\n\t\t\t\t\t<div class=\"author\">\n\t\t\t\t<img data-del=\"avatar\" src='https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/portrait-assel-180x180.jpg' class='avatar pp-user-avatar avatar-150wp-user-avatar wp-user-avatar-150 photo ' height='150' width='150'\/>\t\t\t\t<div class=\"infos\">\n\t\t\t\t\t<div class=\"name\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/asialyst.com\/fr\/auteur\/asselkipchakova\/\">\n\t\t\t\t\t\t\tAssel Kipchakova\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\tAssel Kipchakova est une journaliste d\u2019origine kirghize sp\u00e9cialis\u00e9e sur l\u2019Asie centrale et la Russie. Pass\u00e9e par les Universit\u00e9s de Saint-P\u00e9tersbourg, Moscou et Sciences Po Paris, elle souhaite apporter un regard ind\u00e9pendant et nuanc\u00e9 sur les \u00e9volutions soci\u00e9tales et politiques dans ces r\u00e9gions. Elle collabore avec RFI, Asialyst et Novastan.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"block3news\">\n\t<div class=\"container\">\n\t\t<div class=\"recommand\">\n\t\t\t<h5>On vous recommande<\/h5>\t\t\t<ul class=\"row\">\n\t\t\t\t<li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2016\/10\/26\/kirghizstan-etonnant-carnet-du-resistant-djekichev\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/10\/Carnet-de-resistance-kirghize-Novastan-5-piece-didentite-Copier-600x400.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/10\/Carnet-de-resistance-kirghize-Novastan-5-piece-didentite-Copier-600x400.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/10\/Carnet-de-resistance-kirghize-Novastan-5-piece-didentite-Copier-300x200.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2016\/10\/Carnet-de-resistance-kirghize-Novastan-5-piece-didentite-Copier-900x600.jpg 900w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Histoire<\/span><h4>Kirghizistan : l\u2019\u00e9tonnant carnet du r\u00e9sistant Djekichev<\/h4><\/span><\/a><\/li><li class=\"col-md-6 col-sm-12 col-xs-12 news\"><a href=\"https:\/\/asialyst.com\/fr\/2015\/05\/04\/le-kirghizistan-havre-de-lislamisme-fondamental-en-asie-centrale\/\"><span class=\"photo\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/05\/KIRGHIZISTAN-ISLAM-PRIERE-600x400.jpg\" class=\"img-responsive wp-post-image\" alt=\"Photo de musulmans rassembl\u00e9s pour la pri\u00e8re\" srcset=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/05\/KIRGHIZISTAN-ISLAM-PRIERE-600x400.jpg 600w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/05\/KIRGHIZISTAN-ISLAM-PRIERE-300x200.jpg 300w, https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/05\/KIRGHIZISTAN-ISLAM-PRIERE-900x600.jpg 900w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><span class=\"info\"><span class=\"metadata category category-\">Soci\u00e9t\u00e9<\/span><h4>Le Kirghizistan, havre de l\u2019islamisme fondamental en Asie centrale<\/h4><\/span><\/a><\/li>\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"container\">\n\t<div class=\"comments\">\n\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d&rsquo;horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre. <\/p>\n","protected":false},"author":969,"featured_media":34508,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[613,72,71,193],"class_list":["post-34445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-abonnes","tag-asie-centrale","tag-kirghizistan","tag-temps-forts"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote - Asialyst<\/title>\n<meta name=\"description\" content=\"Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d&#039;horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote\" \/>\n<meta property=\"og:description\" content=\"Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d&#039;horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/\" \/>\n<meta property=\"og:site_name\" content=\"Asialyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Asialyst.fr\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-13T00:52:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-14T16:51:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Assel Kipchakova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assel Kipchakova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/\"},\"author\":{\"name\":\"Assel Kipchakova\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/43b8e38392bb60e3cad84eeb219b3c8d\"},\"headline\":\"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote\",\"datePublished\":\"2017-10-13T00:52:18+00:00\",\"dateModified\":\"2017-10-14T16:51:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/\"},\"wordCount\":2569,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/kirghizistan-election-presidentielle-e1507858794831.jpg\",\"keywords\":[\"Abonn\u00e9s\",\"Asie Centrale\",\"Kirghizistan\",\"temps forts\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/\",\"name\":\"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote - Asialyst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/kirghizistan-election-presidentielle-e1507858794831.jpg\",\"datePublished\":\"2017-10-13T00:52:18+00:00\",\"dateModified\":\"2017-10-14T16:51:04+00:00\",\"description\":\"Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d'horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/kirghizistan-election-presidentielle-e1507858794831.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/kirghizistan-election-presidentielle-e1507858794831.jpg\",\"width\":1024,\"height\":756,\"caption\":\"Affiche de campagne du candidat soutenu par le pouvoir Sooronbai Jeenbekov pour l'ection presidentielle du dimanche 15 octobre, dans le village de Kok-Zhar, le12 Octobre 2017. (Credits : AFP PHOTO \\\/ Vyacheslav OSELEDKO)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/2017\\\/10\\\/13\\\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"name\":\"Asialyst\",\"description\":\"Votre m\u00e9dia sur l Asie\",\"publisher\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#organization\",\"name\":\"Asialyst\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/logo_blanc.png\",\"width\":657,\"height\":165,\"caption\":\"Asialyst\"},\"image\":{\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Asialyst.fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/#\\\/schema\\\/person\\\/43b8e38392bb60e3cad84eeb219b3c8d\",\"name\":\"Assel Kipchakova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/portrait-assel-180x180.jpg\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/portrait-assel-180x180.jpg\",\"contentUrl\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/portrait-assel-180x180.jpg\",\"caption\":\"Assel Kipchakova\"},\"description\":\"Assel Kipchakova est une journaliste d\u2019origine kirghize sp\u00e9cialis\u00e9e sur l\u2019Asie centrale et la Russie. Pass\u00e9e par les Universit\u00e9s de Saint-P\u00e9tersbourg, Moscou et Sciences Po Paris, elle souhaite apporter un regard ind\u00e9pendant et nuanc\u00e9 sur les \u00e9volutions soci\u00e9tales et politiques dans ces r\u00e9gions. Elle collabore avec RFI, Asialyst et Novastan.\",\"url\":\"https:\\\/\\\/asialyst.com\\\/fr\\\/auteur\\\/asselkipchakova\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote - Asialyst","description":"Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d'horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote","og_description":"Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d'horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre.","og_url":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/","og_site_name":"Asialyst","article_publisher":"https:\/\/www.facebook.com\/Asialyst.fr","article_published_time":"2017-10-13T00:52:18+00:00","article_modified_time":"2017-10-14T16:51:04+00:00","og_image":[{"width":1024,"height":756,"url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg","type":"image\/jpeg"}],"author":"Assel Kipchakova","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Assel Kipchakova","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#article","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/"},"author":{"name":"Assel Kipchakova","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/43b8e38392bb60e3cad84eeb219b3c8d"},"headline":"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote","datePublished":"2017-10-13T00:52:18+00:00","dateModified":"2017-10-14T16:51:04+00:00","mainEntityOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/"},"wordCount":2569,"commentCount":1,"publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg","keywords":["Abonn\u00e9s","Asie Centrale","Kirghizistan","temps forts"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/","url":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/","name":"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote - Asialyst","isPartOf":{"@id":"https:\/\/asialyst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#primaryimage"},"image":{"@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#primaryimage"},"thumbnailUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg","datePublished":"2017-10-13T00:52:18+00:00","dateModified":"2017-10-14T16:51:04+00:00","description":"Economie instable, d\u00e9pendance \u00e9nerg\u00e9tique et menace terroriste, tour d'horizon des enjeux de la pr\u00e9sidentielle au Kirghizistan ce dimance 15 octobre.","breadcrumb":{"@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#primaryimage","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/kirghizistan-election-presidentielle-e1507858794831.jpg","width":1024,"height":756,"caption":"Affiche de campagne du candidat soutenu par le pouvoir Sooronbai Jeenbekov pour l'ection presidentielle du dimanche 15 octobre, dans le village de Kok-Zhar, le12 Octobre 2017. (Credits : AFP PHOTO \/ Vyacheslav OSELEDKO)"},{"@type":"BreadcrumbList","@id":"https:\/\/asialyst.com\/fr\/2017\/10\/13\/presidentielle-kirghizistan-unique-democratie-asie-centrale-epreuve-vote\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asialyst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9sidentielle au Kirghizistan : la seule d\u00e9mocratie d\u2019Asie centrale \u00e0 l\u2019\u00e9preuve du vote"}]},{"@type":"WebSite","@id":"https:\/\/asialyst.com\/fr\/#website","url":"https:\/\/asialyst.com\/fr\/","name":"Asialyst","description":"Votre m\u00e9dia sur l Asie","publisher":{"@id":"https:\/\/asialyst.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asialyst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asialyst.com\/fr\/#organization","name":"Asialyst","url":"https:\/\/asialyst.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2015\/04\/logo_blanc.png","width":657,"height":165,"caption":"Asialyst"},"image":{"@id":"https:\/\/asialyst.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Asialyst.fr"]},{"@type":"Person","@id":"https:\/\/asialyst.com\/fr\/#\/schema\/person\/43b8e38392bb60e3cad84eeb219b3c8d","name":"Assel Kipchakova","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/portrait-assel-180x180.jpg","url":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/portrait-assel-180x180.jpg","contentUrl":"https:\/\/asialyst.com\/fr\/wp-content\/uploads\/2017\/10\/portrait-assel-180x180.jpg","caption":"Assel Kipchakova"},"description":"Assel Kipchakova est une journaliste d\u2019origine kirghize sp\u00e9cialis\u00e9e sur l\u2019Asie centrale et la Russie. Pass\u00e9e par les Universit\u00e9s de Saint-P\u00e9tersbourg, Moscou et Sciences Po Paris, elle souhaite apporter un regard ind\u00e9pendant et nuanc\u00e9 sur les \u00e9volutions soci\u00e9tales et politiques dans ces r\u00e9gions. Elle collabore avec RFI, Asialyst et Novastan.","url":"https:\/\/asialyst.com\/fr\/auteur\/asselkipchakova\/"}]}},"_links":{"self":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/34445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/users\/969"}],"replies":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/comments?post=34445"}],"version-history":[{"count":12,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/34445\/revisions"}],"predecessor-version":[{"id":34579,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/posts\/34445\/revisions\/34579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media\/34508"}],"wp:attachment":[{"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/media?parent=34445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/categories?post=34445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asialyst.com\/fr\/wp-json\/wp\/v2\/tags?post=34445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}